{"id":8329,"date":"2023-12-09T02:42:21","date_gmt":"2023-12-09T01:42:21","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=8329"},"modified":"2023-12-09T02:44:30","modified_gmt":"2023-12-09T01:44:30","slug":"zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/","title":{"rendered":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil"},"content":{"rendered":"<p>(<a title=\"dpa\" href=\"https:\/\/www.dpa-news.de\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>dpa<\/strong><\/span><\/a>) &#8211; La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. <strong>Despu\u00e9s de que Nio &amp; Co hayan atacado hasta ahora sobre todo la clase de lujo, el grupo Geely vuelve a mostrar c\u00f3mo pueden ser los coches el\u00e9ctricos de entrada de gama con clase.<\/strong><\/p>\n<figure id=\"attachment_8330\" aria-describedby=\"caption-attachment-8330\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-8330 size-large\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X-650x432.jpg\" alt=\"Zeekr X\" width=\"650\" height=\"432\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X-768x510.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg 998w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-8330\" class=\"wp-caption-text\">El Zeekr X est\u00e1 disponible con tracci\u00f3n a las cuatro ruedas. Foto: Zeekr\/dpa<\/figcaption><\/figure>\n<p>Poco m\u00e1s de un a\u00f1o despu\u00e9s del compacto Smart #1 (como empresa conjunta con Mercedes), la compa\u00f1\u00eda china lanza el Zeekr X y el Volvo EX30 sobre la misma base.<\/p>\n<p>Bastante m\u00e1s cortos de 4,30 metros y, en el mejor de los casos, sin llegar a los 40.000 euros (43.600 d\u00f3lares) de precio, pero con clase y bien equipados, as\u00ed como con una tecnolog\u00eda apta para el uso diario: as\u00ed es como est\u00e1n llenando un hueco entre el Mercedes EQA, el BMW iX1 y el Audi Q4 e-tron.<\/p>\n<h2>Una plataforma para tres coches diferentes<\/h2>\n<p>Ambos reci\u00e9n llegados utilizan la misma plataforma que el Smart. Sin embargo, los modelos est\u00e1n configurados de forma diferente. Como el Volvo es el m\u00e1s barato de la familia, el modelo b\u00e1sico solo tiene una bater\u00eda de 51 kWh para 344 kil\u00f3metros y un motor trasero con 200 kW\/272 CV.<\/p>\n<p>Zeekr, por su parte, se sit\u00faa en la cima y ofrece el X con una bater\u00eda de 69 kWh. Esto es suficiente para 445 kil\u00f3metros en la versi\u00f3n de tracci\u00f3n trasera.<\/p>\n<blockquote><p>Ambos modelos tambi\u00e9n est\u00e1n disponibles con la bater\u00eda grande y tracci\u00f3n total de 315 kW\/428 CV.<\/p><\/blockquote>\n<h2>Acogedor o autoritario: as\u00ed de diferentes conducen los dos<\/h2>\n<p>Ambos <a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/\"><span style=\"color: #ff6600;\"><strong>coches el\u00e9ctricos<\/strong><\/span><\/a> son potentes y r\u00e1pidos. Despu\u00e9s de todo, con una aceleraci\u00f3n de 0 a 100 km\/h de 3,8 segundos en el mejor de los casos, dejan atr\u00e1s a muchos deportivos cl\u00e1sicos. Y una velocidad m\u00e1xima de 180 km\/h tampoco est\u00e1 nada mal para un coche el\u00e9ctrico.<\/p>\n<p>Pero el dise\u00f1o de los dos coches es muy diferente. Donde el Zeekr conduce de forma digna y c\u00f3moda -m\u00e1s como un Mercedes de los de antes-, el Volvo quiere ser preciso, predecible y un poco m\u00e1s ajustado y deportivo. Como un Audi, en otras palabras, para salir en la foto. Qu\u00e9 oportuno que el Smart, como tercer y m\u00e1s salvaje miembro de la familia, apunte a BMW.<\/p>\n<p>Los reci\u00e9n llegados solo son d\u00e9biles cuando se trata de cargar: aunque todos ofrecen hasta 22 kW de potencia en corriente alterna, est\u00e1n limitados a 153 kW en el mejor de los casos en corriente continua.<\/p>\n<p>Incluso algunos <a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/negocios\/\"><span style=\"color: #ff6600;\"><strong>fabricantes<\/strong><\/span><\/a> de gran volumen en los segmentos de precios m\u00e1s bajos son ahora mejores en este aspecto. Pero sin competencia real en su clase, Geely naturalmente no tiene presi\u00f3n.<\/p>\n<h2>Sobriedad n\u00f3rdica o elegancia deslumbrante<\/h2>\n<p>El Zeekr y el Volvo tambi\u00e9n difieren en sus carrocer\u00edas, no solo porque el X es 20 cent\u00edmetros m\u00e1s largo que el EX30, con 4,43 metros, y ofrece en consecuencia m\u00e1s espacio en los asientos traseros.<\/p>\n<p>Pero donde uno es divertido, deslumbrante y llama la atenci\u00f3n con detalles como la banda luminosa o las luces de corte dentado, el otro es n\u00f3rdico, sobrio y un poco fr\u00edo. Y por dentro es exactamente igual.<\/p>\n<blockquote><p>El Zeekr quiere ser un joyero, apostando por materiales con clase y una acogedora iluminaci\u00f3n ambiental, mientras que el Volvo quiere ser funcional y, sobre todo, sostenible.<\/p><\/blockquote>\n<p>Hay enormes huecos en las puertas porque todos los altavoces est\u00e1n combinados en la barra de sonido bajo el parabrisas. Hay un reposabrazos multifuncional con un caj\u00f3n para tazas y una solapa en el suelo a modo de garaje para el m\u00f3vil.<\/p>\n<p>A esto se a\u00f1ade una selecci\u00f3n de materiales que pone deliberadamente el acento en el reciclaje. <strong>Desde las fibras de lino del salpicadero hasta el granulado de pl\u00e1stico grueso de las puertas. Y aunque el Volvo es el coche m\u00e1s peque\u00f1o, da la sensaci\u00f3n de ser m\u00e1s espacioso, al menos en la primera fila, y los asientos son algo m\u00e1s amplios.<\/strong><\/p>\n<h2>Muchos detalles pr\u00e1cticos<\/h2>\n<p>Ambos tienen detalles pr\u00e1cticos que ofrecer -a veces de formas muy diferentes-, electr\u00f3nicamente l\u00fadicos en el Zeekr e ingeniosos en el Volvo: el X seduce con juegos de ordenador mientras se carga, con karaoke y videoconferencia e incluso tiene una peque\u00f1a pantalla en el exterior en la que se puede leer el nivel de carga, por ejemplo.<\/p>\n<p>Y en el Volvo, en alg\u00fan momento se descubren los gr\u00e1ficos en el espacio entre los asientos delanteros, por ejemplo, donde los pasajeros de los asientos traseros pueden guardar sus cachivaches.<\/p>\n<p>De nuevo, ambos tienen maletero. Es decir, la caracter\u00edstica el\u00e9ctrica en forma de compartimento portaobjetos bajo el cap\u00f3, que todav\u00eda no se ha puesto realmente de moda entre los fabricantes alemanes. <strong>Aunque oficialmente solo tiene capacidad para siete litros, puede albergar el cable de carga y los peque\u00f1os objetos habituales.<\/strong><\/p>\n<p>Pero tambi\u00e9n hay algunas caracter\u00edsticas especiales a las que cuesta acostumbrarse. Por ejemplo, el hecho de que el volante y los retrovisores del Zeekr solo se puedan ajustar a trav\u00e9s de la pantalla t\u00e1ctil, al igual que la guantera del Volvo solo se puede abrir a trav\u00e9s de la pantalla.<\/p>\n<p>Y quien antes miraba el veloc\u00edmetro detr\u00e1s del volante, ahora mira irritado al vac\u00edo. Para mantener el precio bajo, Volvo ha prescindido del display y ha relegado todos los datos de conducci\u00f3n a la pantalla t\u00e1ctil.<\/p>\n<h2>Conclusi\u00f3n: dos coches peque\u00f1os con un gran potencial<\/h2>\n<p>Despu\u00e9s de todo, funciona. Con el Zeekr X y el Volvo EX30, Geely demuestra que es posible crear modelos atractivos para la generaci\u00f3n joven o entrar en la gama premium. Y con finura, encanto y tecnolog\u00eda adecuada para el uso diario.<\/p>\n<p>Y lo que Volvo ofrece con tradici\u00f3n y estructuras de concesionarios establecidas en t\u00e9rminos de confianza, Zeekr lo contrarresta con el atractivo de lo nuevo. Y al menos, Volvo no solo fabrica el EX30 en Extremo Oriente, sino que tambi\u00e9n lo ha llevado a una planta europea en Gante.<\/p>\n<p><strong>Datos: Volvo\u00a0<\/strong><strong>EX30<\/strong>\u00a0<strong>|Zeekr<\/strong><strong>\u00a0X<\/strong><\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td>Motorizaci\u00f3n:<\/td>\n<td>El\u00e9ctrica | El\u00e9ctrica con dos motores<\/td>\n<\/tr>\n<tr>\n<td>Potencia m\u00e1xima:<\/td>\n<td>200 kW\/272 PS | 315 kW\/428 PS<\/td>\n<\/tr>\n<tr>\n<td>Par m\u00e1ximo:<\/td>\n<td>343 Nm | 543 Nm<\/td>\n<\/tr>\n<tr>\n<td>Tracci\u00f3n:<\/td>\n<td>Trasera | A las cuatro ruedas<\/td>\n<\/tr>\n<tr>\n<td>Caja de cambios:<\/td>\n<td>Una marcha<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td>Medidas y peso<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Longitud:<\/td>\n<td>4233 mm | 4432 mm<\/td>\n<\/tr>\n<tr>\n<td>Ancho:<\/td>\n<td>1837 mm | 1836 mm<\/td>\n<\/tr>\n<tr>\n<td>Altura:<\/td>\n<td>1549 mm | 1566 mm<\/td>\n<\/tr>\n<tr>\n<td>Radio de giro:<\/td>\n<td>2665 mm | 2750 mm<\/td>\n<\/tr>\n<tr>\n<td>Peso<\/td>\n<td>1765 kg | 1960 kg<\/td>\n<\/tr>\n<tr>\n<td>Carga:<\/td>\n<td>sin datos<\/td>\n<\/tr>\n<tr>\n<td>Volumen del maletero:<\/td>\n<td>318-904 litros | 362 litros<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td>Caracter\u00edsticas de circulaci\u00f3n:<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Velocidad m\u00e1xima:<\/td>\n<td>180 km\/h<\/td>\n<\/tr>\n<tr>\n<td>Aceleraci\u00f3n 0-100 km\/h:<\/td>\n<td>5,3 s | 3,8 s<\/td>\n<\/tr>\n<tr>\n<td>Consumo medio:<\/td>\n<td>17 kWh\/100 km | 18,3 kWh\/100 km<\/td>\n<\/tr>\n<tr>\n<td>Autonom\u00eda:<\/td>\n<td>476 km | 400 km<\/td>\n<\/tr>\n<tr>\n<td>Bater\u00edas (capacidad neta):<\/td>\n<td>64 kWh<\/td>\n<\/tr>\n<tr>\n<td>Rendimiento de carga m\u00e1ximo AC\/DC:<\/td>\n<td>22 kW\/153 kW<\/td>\n<\/tr>\n<tr>\n<td>Emisiones de CO2:<\/td>\n<td>0 g\/km<\/td>\n<\/tr>\n<tr>\n<td>Combustible:<\/td>\n<td>Corriente<\/td>\n<\/tr>\n<tr>\n<td>Nivel de emisiones contaminantes:<\/td>\n<td>sin datos<\/td>\n<\/tr>\n<tr>\n<td>Eficiencia energ\u00e9tica:<\/td>\n<td>A+++<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td>Otros datos importantes:<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Seguridad:<\/td>\n<td>Siete airbags, control de distancia y carril, asistente de salida | Siete airbags, asistente en carretera, alerta de cruce<\/td>\n<\/tr>\n<tr>\n<td>Confort:<\/td>\n<td>Climatizador autom\u00e1tico, barra de sonido, infoentretenimiento con navegaci\u00f3n | Climatizador autom\u00e1tico, head-up display, techo panor\u00e1mico<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Por Thomas Geiger (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta ahora sobre todo la clase de lujo, el grupo Geely vuelve a mostrar c\u00f3mo pueden ser los coches el\u00e9ctricos de entrada de gama con clase. Poco m\u00e1s de un<\/p>\n","protected":false},"author":1,"featured_media":8330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[99,44],"class_list":["post-8329","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportajes","tag-motor","tag-reportajes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"reportajes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"998\" \/>\n\t\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-09T01:42:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-09T01:44:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/reportajes\\\/#listItem\",\"name\":\"Reportajes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/reportajes\\\/#listItem\",\"position\":2,\"name\":\"Reportajes\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/reportajes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#listItem\",\"name\":\"Zeekr X y Volvo EX30 desaf\\u00edan a la \\u00e9lite del autom\\u00f3vil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#listItem\",\"position\":3,\"name\":\"Zeekr X y Volvo EX30 desaf\\u00edan a la \\u00e9lite del autom\\u00f3vil\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/reportajes\\\/#listItem\",\"name\":\"Reportajes\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#newsarticle\",\"name\":\"Zeekr X y Volvo EX30 desaf\\u00edan a la \\u00e9lite del autom\\u00f3vil | El Digital de Asturias\",\"headline\":\"Zeekr X y Volvo EX30 desaf\\u00edan a la \\u00e9lite del autom\\u00f3vil\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Zeekr-X.jpg\",\"width\":998,\"height\":663,\"caption\":\"El Zeekr X est\\u00e1 disponible con tracci\\u00f3n a las cuatro ruedas. Foto: Zeekr\\\/dpa\"},\"datePublished\":\"2023-12-09T02:42:21+01:00\",\"dateModified\":\"2023-12-09T02:44:30+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#webpage\"},\"articleSection\":\"Reportajes, motor, Reportajes\",\"dateline\":\"Publicado el diciembre 9, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/\",\"name\":\"Zeekr X y Volvo EX30 desaf\\u00edan a la \\u00e9lite del autom\\u00f3vil | El Digital de Asturias\",\"description\":\"(dpa) - La \\u00e9lite automovil\\u00edstica alemana se enfrenta tambi\\u00e9n a la competencia china en la gama baja. Despu\\u00e9s de que Nio & Co hayan atacado hasta\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Zeekr-X.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#mainImage\",\"width\":998,\"height\":663,\"caption\":\"El Zeekr X est\\u00e1 disponible con tracci\\u00f3n a las cuatro ruedas. Foto: Zeekr\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\\\/#mainImage\"},\"datePublished\":\"2023-12-09T02:42:21+01:00\",\"dateModified\":\"2023-12-09T02:44:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias","description":"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio & Co hayan atacado hasta","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/","robots":"max-image-preview:large","keywords":"reportajes","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/reportajes\/#listItem","name":"Reportajes"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/reportajes\/#listItem","position":2,"name":"Reportajes","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/reportajes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#listItem","name":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#listItem","position":3,"name":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/reportajes\/#listItem","name":"Reportajes"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#newsarticle","name":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias","headline":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg","width":998,"height":663,"caption":"El Zeekr X est\u00e1 disponible con tracci\u00f3n a las cuatro ruedas. Foto: Zeekr\/dpa"},"datePublished":"2023-12-09T02:42:21+01:00","dateModified":"2023-12-09T02:44:30+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#webpage"},"articleSection":"Reportajes, motor, Reportajes","dateline":"Publicado el diciembre 9, 2023."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/","name":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias","description":"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio & Co hayan atacado hasta","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#mainImage","width":998,"height":663,"caption":"El Zeekr X est\u00e1 disponible con tracci\u00f3n a las cuatro ruedas. Foto: Zeekr\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/#mainImage"},"datePublished":"2023-12-09T02:42:21+01:00","dateModified":"2023-12-09T02:44:30+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias","og:description":"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg","og:image:width":998,"og:image:height":663,"article:published_time":"2023-12-09T01:42:21+00:00","article:modified_time":"2023-12-09T01:44:30+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil | El Digital de Asturias","twitter:description":"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/12\/Zeekr-X.jpg"},"aioseo_meta_data":{"post_id":"8329","title":null,"description":"(dpa) - La \u00e9lite automovil\u00edstica alemana se enfrenta tambi\u00e9n a la competencia china en la gama baja. Despu\u00e9s de que Nio &amp; Co hayan atacado hasta","keywords":[],"keyphrases":{"focus":{"keyphrase":"\u00e9lite","score":60,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"\u00e9lite","score":53,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},{"keyphrase":"Zeekr X","score":67,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 07:01:41","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-12-09 01:35:08","updated":"2026-05-15 07:01:41","focus_keyword":"\u00e9lite","additional_keywords":[{"word":"\u00e9lite","score":53},{"word":"Zeekr X","score":67}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/reportajes\/\" title=\"Reportajes\">Reportajes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tZeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Reportajes","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/reportajes\/"},{"label":"Zeekr X y Volvo EX30 desaf\u00edan a la \u00e9lite del autom\u00f3vil","link":"https:\/\/eldigitaldeasturias.com\/radio\/zeekr-x-y-volvo-ex30-desafian-a-la-elite-del-automovil\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/8329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=8329"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/8329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/8330"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=8329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=8329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=8329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}