{"id":8002,"date":"2023-10-05T06:45:25","date_gmt":"2023-10-05T04:45:25","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=8002"},"modified":"2023-10-05T06:46:02","modified_gmt":"2023-10-05T04:46:02","slug":"guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/","title":{"rendered":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb"},"content":{"rendered":"<p>Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en <a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>Asturias<\/strong><\/span><\/a>, como en el resto del mundo son muchas las personas que han elegido est\u00e9 medio de vida.<\/p>\n<figure id=\"attachment_8003\" aria-describedby=\"caption-attachment-8003\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-8003\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez-360x271.jpg\" alt=\"Guillermo Pel\u00e1ez\" width=\"650\" height=\"489\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez-360x271.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez-150x113.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez-450x339.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg 719w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-8003\" class=\"wp-caption-text\">Foto: Prensa Gobierno de Asturias<\/figcaption><\/figure>\n<p>En la tarde ayer. el consejero de Hacienda y Fondos Europeos, <strong>Guillermo Pel\u00e1ez, ha destacado el atractivo de Asturias como refugio para n\u00f3madas digitales y profesionales que quieran un buen nivel de vida.<\/strong> El consejero realiz\u00f3 estas declaraciones en el acto de entrega del XXII Premio Fundaci\u00f3n Banco Sabadell a la Investigaci\u00f3n Econ\u00f3mica.<\/p>\n<h2>Ventajas de ser un n\u00f3mada digital<\/h2>\n<p>Ser un n\u00f3mada digital tiene sus ventajas y tambi\u00e9n su muchos desaf\u00edos. Uno de los principales beneficios del trabajo independiente de la ubicaci\u00f3n es la flexibilidad que proporciona a las personas, siendo ellas las que se fijan sus metas y horarios.<\/p>\n<p>Los n\u00f3madas digitales pueden trabajar desde cualquier lugar y en cualquier momento, lo que les permite conciliar el <a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/negocios\/\"><span style=\"color: #ff6600;\"><strong>trabajo<\/strong><\/span><\/a> y la vida personal de forma m\u00e1s eficaz. Tambi\u00e9n tienen la libertad de elegir sus propios proyectos, clientes y condiciones laborales, lo que puede conducir a una mayor creatividad y satisfacci\u00f3n laboral.<\/p>\n<p>Durante los ultimos a\u00f1os en Asturias se han instalado muchos y lo seguir\u00e1n haciendo. Sin embargo, ser un n\u00f3mada digital tambi\u00e9n presenta algunos desaf\u00edos. Uno de los mayores desaf\u00edos es la falta de estabilidad y seguridad que conlleva un estilo de vida n\u00f3mada. Los n\u00f3madas digitales a menudo tienen dificultades para encontrar ingresos estables, construir redes profesionales e incluso en algunos casos su estilo de vida les impide mantener relaciones sociales.<\/p>\n<p>Es probable que la tendencia del nomadismo digital siga creciendo en el futuro, y cada vez m\u00e1s personas opten por un estilo de vida independiente de la ubicaci\u00f3n. Esta tendencia tiene importantes implicaciones para la econom\u00eda global y la sociedad en su conjunto. Por un lado, el nomadismo digital tiene el potencial de promover la innovaci\u00f3n, la creatividad y la diversidad, as\u00ed como de reducir el impacto ambiental del trabajo tradicional de oficina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias, como en el resto del mundo son muchas las personas que han elegido est\u00e9 medio de vida. En la tarde ayer. el consejero de Hacienda y Fondos Europeos, Guillermo Pel\u00e1ez, ha destacado<\/p>\n","protected":false},"author":1,"featured_media":8003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[42,103],"class_list":["post-8002","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-asturias","tag-tecnologia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-05T04:45:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-05T04:46:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#listItem\",\"name\":\"Guillermo Pel\\u00e1ez: \\u00abAsturias ser\\u00e1 un buen refugio para n\\u00f3madas digitales\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#listItem\",\"position\":3,\"name\":\"Guillermo Pel\\u00e1ez: \\u00abAsturias ser\\u00e1 un buen refugio para n\\u00f3madas digitales\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#newsarticle\",\"name\":\"Guillermo Pel\\u00e1ez: \\u00abAsturias ser\\u00e1 un buen refugio para n\\u00f3madas digitales\\u00bb | El Digital de Asturias\",\"headline\":\"Guillermo Pel\\u00e1ez: \\u00abAsturias ser\\u00e1 un buen refugio para n\\u00f3madas digitales\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Guillermo-Pelaez.jpg\",\"width\":719,\"height\":541,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"datePublished\":\"2023-10-05T06:45:25+02:00\",\"dateModified\":\"2023-10-05T06:46:02+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#webpage\"},\"articleSection\":\"Noticias, Asturias, Tecnolog\\u00eda\",\"dateline\":\"Publicado el octubre 5, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/\",\"name\":\"Guillermo Pel\\u00e1ez: \\u00abAsturias ser\\u00e1 un buen refugio para n\\u00f3madas digitales\\u00bb | El Digital de Asturias\",\"description\":\"Aunque para muchas personas sea un t\\u00e9rmino desconocido, los n\\u00f3madas digitales cada son m\\u00e1s populares y durante los \\u00faltimos a\\u00f1os tanto en Asturias,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Guillermo-Pelaez.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#mainImage\",\"width\":719,\"height\":541,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\\\/#mainImage\"},\"datePublished\":\"2023-10-05T06:45:25+02:00\",\"dateModified\":\"2023-10-05T06:46:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias","description":"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/","robots":"max-image-preview:large","keywords":"noticias","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#listItem","name":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#listItem","position":3,"name":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#newsarticle","name":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias","headline":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg","width":719,"height":541,"caption":"Foto: Prensa Gobierno de Asturias"},"datePublished":"2023-10-05T06:45:25+02:00","dateModified":"2023-10-05T06:46:02+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#webpage"},"articleSection":"Noticias, Asturias, Tecnolog\u00eda","dateline":"Publicado el octubre 5, 2023."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/","name":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias","description":"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#mainImage","width":719,"height":541,"caption":"Foto: Prensa Gobierno de Asturias"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/#mainImage"},"datePublished":"2023-10-05T06:45:25+02:00","dateModified":"2023-10-05T06:46:02+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias","og:description":"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg","og:image:width":719,"og:image:height":541,"article:published_time":"2023-10-05T04:45:25+00:00","article:modified_time":"2023-10-05T04:46:02+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb | El Digital de Asturias","twitter:description":"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/10\/Guillermo-Pelaez.jpg"},"aioseo_meta_data":{"post_id":"8002","title":null,"description":"Aunque para muchas personas sea un t\u00e9rmino desconocido, los n\u00f3madas digitales cada son m\u00e1s populares y durante los \u00faltimos a\u00f1os tanto en Asturias,","keywords":[],"keyphrases":{"focus":{"keyphrase":"Asturias","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Asturias","score":87,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 06:45:16","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-10-05 04:40:15","updated":"2026-05-15 06:45:16","focus_keyword":"Asturias","additional_keywords":[{"word":"Asturias","score":87}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tGuillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Noticias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/"},{"label":"Guillermo Pel\u00e1ez: \u00abAsturias ser\u00e1 un buen refugio para n\u00f3madas digitales\u00bb","link":"https:\/\/eldigitaldeasturias.com\/radio\/guillermo-pelaez-asturias-sera-un-buen-refugio-para-nomadas-digitales\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/8002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=8002"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/8002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/8003"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=8002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=8002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=8002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}