{"id":7722,"date":"2023-03-25T00:18:58","date_gmt":"2023-03-24T23:18:58","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=7722"},"modified":"2023-03-25T00:18:58","modified_gmt":"2023-03-24T23:18:58","slug":"el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/","title":{"rendered":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022"},"content":{"rendered":"<p>(EP) &#8211; El <strong>Defensor del Pueblo<\/strong> ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones Penitenciarias revise su protocolo porque \u00aben muchas c\u00e1rceles se sigue sin recoger correctamente la identidad de las personas transexuales\u00bb. <strong>Tambi\u00e9n se ha quejado de que en los cacheos policiales \u00abno es posible constatar que se ofrezca la posibilidad de escoger el sexo del personal que lo realiza\u00bb.<\/strong><\/p>\n<figure id=\"attachment_7723\" aria-describedby=\"caption-attachment-7723\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7723\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos-360x234.jpg\" alt=\"detenidos\" width=\"650\" height=\"422\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos-360x234.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos-768x498.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos-150x97.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos-450x292.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg 1016w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-7723\" class=\"wp-caption-text\">Foto: C\u00e9zaro De Luca &#8211; Europa Press<\/figcaption><\/figure>\n<p>La Oficina de \u00c1ngel Gabilondo asegura en su Informe Anual de 2022, consultado por Europa Press, que el Mecanismo Nacional de Prevenci\u00f3n de la Tortura de Espa\u00f1a (MNP) &#8211;cuya funci\u00f3n asume el propio Defensor del Pueblo&#8211; realiz\u00f3 una recomendaci\u00f3n a Instituciones Penitenciarias al constatar que \u00aben muchas c\u00e1rceles se sigue sin recoger correctamente la identidad de las personas transexuales\u00bb.<\/p>\n<p>Respecto de los cacheos a personas transexuales, a\u00f1ade que \u00abno es posible constatar que se ofrezca la posibilidad de escoger el sexo del personal que lo realiza\u00bb. \u00abCon respecto a las comisar\u00edas, debe se\u00f1alarse que el formulario de informaci\u00f3n no contempla el g\u00e9nero de los detenidos\u00bb, apunta.<\/p>\n<p>\u00abLa falta de datos desagregados por sexo implica la invisibilizaci\u00f3n de la mujer y las personas LGTBI, y la imposibilidad de realizar an\u00e1lisis comparativos, que resultan esenciales en materias como la aplicaci\u00f3n de medios coercitivos y la respuesta rehabilitadora\u00bb, ha argumentado el Defensor.<\/p>\n<p>En concreto, recuerda una visita a la prisi\u00f3n de Ja\u00e9n, donde el MNP inst\u00f3 a que se proceda a la revisi\u00f3n de la Instrucci\u00f3n 7\/2006, de la Secretar\u00eda General de Instituciones Penitenciarias, \u00aben consonancia con la realidad social actual\u00bb, o que al menos se especifique en el \u00e1mbito penitenciario c\u00f3mo se debe realizar el registro de datos de la condici\u00f3n de transexual.<\/p>\n<p>El Defensor se\u00f1ala que hace cuatro a\u00f1os ya recomend\u00f3 incorporar la variable de sexo en la recogida inform\u00e1tica de datos y elaborar estad\u00edsticas desagregadas por sexo que, \u00abpese a ser aceptada, resulta incumplida en una materia tan relevante como la de medios coercitivos\u00bb.<\/p>\n<h2>APROBACI\u00d3N DE NUEVA LEY TRANS<\/h2>\n<p>La reciente aprobaci\u00f3n de la Ley Trans ha llevado a varios Ministerios a estudiar si es necesario revisar sus protocolos en vigor en lo referente a la atenci\u00f3n que se da a estas personas: en el caso de Interior, en lo tocante a las prisiones, y en el de Justicia para el cambio registral de nombre y sexo en el Registro Civil.<\/p>\n<p>Desde 2007 las personas trans pod\u00edan hacer este cambio acompa\u00f1ando su solicitud con un diagn\u00f3stico de disforia de g\u00e9nero y un proceso de hormonaci\u00f3n de, al menos, dos a\u00f1os, pero estos dos requisitos son los que se eliminan ahora con la nueva ley.<\/p>\n<p>En la instrucci\u00f3n de Instituciones Penitenciarias que est\u00e1 en vigor desde 2006, este organismo regula cuestiones como la asignaci\u00f3n de m\u00f3dulos y cacheos de personas transexuales, as\u00ed como cambios de nombre o el acceso a las instalaciones de uso colectivo con vistas a facilitar un \u00abinternamiento adecuado\u00bb, teniendo en cuenta los \u00abpreceptivos informes de valoraci\u00f3n m\u00e9dica y psicol\u00f3gica\u00bb de cada caso.<\/p>\n<p>En lo referente al informe psicol\u00f3gico, se especifica que debe constar que la disonancia de g\u00e9nero tiene una trayectoria \u00aben un periodo suficiente de al menos doce meses\u00bb, as\u00ed como la \u00abausencia de trastornos de personalidad que pudieran influir de forma determinante en su elecci\u00f3n\u00bb y una \u00abevaluaci\u00f3n de la presencia de disforia de g\u00e9nero\u00bb.<\/p>\n<p>La instrucci\u00f3n sobre &#8216;Integraci\u00f3n penitenciaria de personas transexuales&#8217; derogaba una anterior de 2001 sobre los criterios para ordenar el ingreso en las c\u00e1rceles \u00aben el marco de la separaci\u00f3n interior que, por raz\u00f3n de sexo, establece el art\u00edculo 16 de la Ley Org\u00e1nica 1\/1979\u00bb.<\/p>\n<p>Adem\u00e1s, la Secretar\u00eda de Estado de Seguridad cuenta con una instrucci\u00f3n &#8211;la 12\/2007&#8211; de obligado cumplimiento para polic\u00edas y guardias civiles, que regula los comportamientos exigidos a los miembros de las Fuerzas y Cuerpos de Seguridad del Estado para garantizar los derechos de las personas detenidas o bajo custodia policial.<\/p>\n<p>Interior estableci\u00f3 que los cacheos polic\u00edas deb\u00edan realizarse, \u00absalvo urgencia\u00bb, por personal del mismo sexo que la persona cacheada, as\u00ed como que se deb\u00eda proceder con el \u00abm\u00e1ximo respeto a la identidad sexual, especialmente en el caso de las personas transexuales.<\/p>\n<p>La instrucci\u00f3n se difundi\u00f3 poco despu\u00e9s de la aprobaci\u00f3n de la ley 3\/2007 reguladora de la rectificaci\u00f3n registral de la menci\u00f3n relativa al sexo de las personas. Dicha orden interna se modific\u00f3 luego, con el PP en el Gobierno, para subrayar la necesidad del m\u00e1ximo respeto en el caso de personas transexuales, transg\u00e9nero o intersexuales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones Penitenciarias revise su protocolo porque \u00aben muchas c\u00e1rceles se sigue sin recoger correctamente la identidad de las personas transexuales\u00bb. Tambi\u00e9n se ha quejado de que en los cacheos policiales \u00abno es posible<\/p>\n","protected":false},"author":1,"featured_media":7723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[45],"class_list":["post-7722","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1016\" \/>\n\t\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-24T23:18:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-03-24T23:18:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#listItem\",\"name\":\"El Defensor del Pueblo ha apremiado a mejorar la informaci\\u00f3n sobre el n\\u00famero de transexuales detenidos entre 2019-2022\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#listItem\",\"position\":3,\"name\":\"El Defensor del Pueblo ha apremiado a mejorar la informaci\\u00f3n sobre el n\\u00famero de transexuales detenidos entre 2019-2022\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#newsarticle\",\"name\":\"El Defensor del Pueblo ha apremiado a mejorar la informaci\\u00f3n sobre el n\\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias\",\"headline\":\"El Defensor del Pueblo ha apremiado a mejorar la informaci\\u00f3n sobre el n\\u00famero de transexuales detenidos entre 2019-2022\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/detenidos.jpg\",\"width\":1016,\"height\":659,\"caption\":\"Foto: C\\u00e9zaro De Luca - Europa Press\"},\"datePublished\":\"2023-03-25T00:18:58+01:00\",\"dateModified\":\"2023-03-25T00:18:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#webpage\"},\"articleSection\":\"Noticias, Sociedad\",\"dateline\":\"Publicado el marzo 25, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/\",\"name\":\"El Defensor del Pueblo ha apremiado a mejorar la informaci\\u00f3n sobre el n\\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias\",\"description\":\"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\\u00f3n sobre el n\\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/detenidos.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#mainImage\",\"width\":1016,\"height\":659,\"caption\":\"Foto: C\\u00e9zaro De Luca - Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\\\/#mainImage\"},\"datePublished\":\"2023-03-25T00:18:58+01:00\",\"dateModified\":\"2023-03-25T00:18:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias","description":"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/","robots":"max-image-preview:large","keywords":"noticias","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#listItem","name":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#listItem","position":3,"name":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#newsarticle","name":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias","headline":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg","width":1016,"height":659,"caption":"Foto: C\u00e9zaro De Luca - Europa Press"},"datePublished":"2023-03-25T00:18:58+01:00","dateModified":"2023-03-25T00:18:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#webpage"},"articleSection":"Noticias, Sociedad","dateline":"Publicado el marzo 25, 2023."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/","name":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias","description":"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#mainImage","width":1016,"height":659,"caption":"Foto: C\u00e9zaro De Luca - Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/#mainImage"},"datePublished":"2023-03-25T00:18:58+01:00","dateModified":"2023-03-25T00:18:58+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias","og:description":"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg","og:image:width":1016,"og:image:height":659,"article:published_time":"2023-03-24T23:18:58+00:00","article:modified_time":"2023-03-24T23:18:58+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 | El Digital de Asturias","twitter:description":"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/detenidos.jpg"},"aioseo_meta_data":{"post_id":"7722","title":null,"description":"(EP) - El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022 y que Instituciones","keywords":[],"keyphrases":{"focus":{"keyphrase":"detenidos","score":83,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Defensor del Pueblo","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},{"keyphrase":"transexuales detenidos","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},{"keyphrase":"detenidos","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 06:29:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-03-24 23:13:36","updated":"2026-05-15 06:29:13","focus_keyword":"detenidos","additional_keywords":[{"word":"Defensor del Pueblo","score":83},{"word":"transexuales detenidos","score":83},{"word":"detenidos","score":100}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Noticias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/"},{"label":"El Defensor del Pueblo ha apremiado a mejorar la informaci\u00f3n sobre el n\u00famero de transexuales detenidos entre 2019-2022","link":"https:\/\/eldigitaldeasturias.com\/radio\/el-defensor-del-pueblo-ha-apremiado-a-mejorar-la-informacion-sobre-el-numero-de-transexuales-detenidos-entre-2019-2022\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=7722"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/7723"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=7722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=7722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=7722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}