{"id":7642,"date":"2023-03-07T12:07:23","date_gmt":"2023-03-07T11:07:23","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=7642"},"modified":"2023-03-07T12:07:23","modified_gmt":"2023-03-07T11:07:23","slug":"televisor-pc-y-el-movil-cuanto-consumen","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/","title":{"rendered":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen?"},"content":{"rendered":"<p>(dpa) &#8211; Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a <a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>ahorrar electricidad<\/strong> <\/span><\/a>por miedo al encarecimiento del costo de vida.<\/p>\n<figure id=\"attachment_7643\" aria-describedby=\"caption-attachment-7643\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7643\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar-360x240.jpg\" alt=\"ahorrar\" width=\"650\" height=\"434\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar-768x513.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg 995w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-7643\" class=\"wp-caption-text\">Por muy eficiente que sea, un televisor enorme siempre acaba consumiendo m\u00e1s electricidad que los aparatos m\u00e1s peque\u00f1os. Foto: Zacharie Scheurer\/dpa<\/figcaption><\/figure>\n<p>Para poder evaluar d\u00f3nde y c\u00f3mo se puede ahorrar energ\u00eda, es \u00fatil tener una visi\u00f3n general de la cantidad de electricidad que se consume de media.<\/p>\n<blockquote><p>Un hogar medio de dos personas consume unos 3.050 kilovatios hora al a\u00f1o, explica el servicio de asesoramiento energ\u00e9tico de los centros del consumidor alemanes.<\/p><\/blockquote>\n<p>Seg\u00fan una encuesta realizada por la Asociaci\u00f3n Federal de Industrias de la Energ\u00eda y el Agua (BDEW) para el a\u00f1o 2021, los aparatos electr\u00f3nicos de consumo, como los televisores y las consolas de juegos, representan el 28 por ciento, es decir, algo m\u00e1s de la cuarta parte del consumo total de electricidad.<\/p>\n<p>A modo de comparaci\u00f3n: seg\u00fan este estudio, el lavado y el secado de ropa consumen un 14 por ciento de la electricidad, la iluminaci\u00f3n el 13 por ciento y los frigor\u00edficos y congeladores el 11 por ciento. Le siguen la cocina y el lavavajillas, con un 9 y un 8 por ciento respectivamente. Estos valores suman un total del 55 por ciento.<\/p>\n<p>Por supuesto que estos son solo valores medios que no reflejan con exactitud todos los hogares. Al fin y al cabo, no todo el mundo tiene los mismos aparatos ni los utiliza en la misma medida.<\/p>\n<p>Sin embargo, en la categor\u00eda de electr\u00f3nica de consumo tambi\u00e9n hay diferencias significativas, se\u00f1ala Joshua Jahn, de un centro de asesoramiento alem\u00e1n: \u00abLos mayores devoradores de energ\u00eda son los televisores y las videoconsolas\u00bb.<\/p>\n<p>La cantidad de electricidad que consume un aparato no solo depende de su clase de eficiencia energ\u00e9tica, sino simplemente de su tama\u00f1o, explica Jahn: \u00abUn televisor muy grande con la mejor clase de eficiencia energ\u00e9tica sigue consumiendo mucha m\u00e1s electricidad que un televisor m\u00e1s peque\u00f1o de una clase peor\u00bb.<\/p>\n<p>De hecho, los televisores m\u00e1s antiguos y los que tienen una diagonal de pantalla de m\u00e1s de un metro pueden consumir una media de 200 kilovatios hora al a\u00f1o. <strong>Seg\u00fan la Agencia Alemana de Medio Ambiente, esta cantidad podr\u00eda servir para hacer funcionar, por ejemplo, dos frigor\u00edficos eficientes.<\/strong><\/p>\n<p>El hecho de que el tama\u00f1o sea relevante en t\u00e9rminos de consumo de energ\u00eda tambi\u00e9n es evidente en los ordenadores. Jahn explica que un ordenador de mesa consume mucha m\u00e1s electricidad que un port\u00e1til.<\/p>\n<p>Sebastian Kl\u00f6ss, de la asociaci\u00f3n alemana de la industria inform\u00e1tica Bitkom, a\u00f1ade que el consumo de un ordenador depende de su equipamiento: \u00abUn PC de juegos muy sofisticado, con un procesador de alto rendimiento y una enorme tarjeta gr\u00e1fica, necesitar\u00e1 m\u00e1s electricidad a pleno rendimiento que un PC est\u00e1ndar o un port\u00e1til dise\u00f1ado para ahorrar electricidad\u00bb.<\/p>\n<p>El uso que se hace del ordenador tambi\u00e9n desempe\u00f1a un papel importante. Seg\u00fan Kl\u00f6ss, los complejos juegos de ordenador y los elaborados programas de edici\u00f3n de v\u00eddeo son tan intensivos desde el punto de vista computacional que esto tambi\u00e9n se refleja en el consumo.<\/p>\n<p>El dispositivo que apenas tiene impacto en la factura de la luz es, de hecho, el m\u00f3vil. Kl\u00f6ss explica que quienes cargan su tel\u00e9fono a diario consumen unos 7,5 kilovatios hora al a\u00f1o. Los altavoces inteligentes, prosigue, tienen un impacto igualmente peque\u00f1o en la factura el\u00e9ctrica, lo que demuestra que cuanto m\u00e1s peque\u00f1o es el dispositivo, menor ser\u00e1 el potencial de ahorro.<\/p>\n<p>En otros \u00e1mbitos, sin embargo, no cabe duda de que existe un claro potencial de ahorro. Joshua Jahn explica que apagar completamente los aparatos en lugar de dejarlos en modo de espera cuando no se utilizan ahorra mucho dinero, y recomienda el uso de regletas con interruptor.<\/p>\n<blockquote><p>Adem\u00e1s, prosigue, vale la pena apagar el router por la noche cuando no se necesita, o al menos la WLAN. En muchos dispositivos, los tiempos de desconexi\u00f3n pueden automatizarse en la configuraci\u00f3n.<\/p><\/blockquote>\n<p>Sebastian Kl\u00f6ss indica que aquellos que quieran ahorrar electricidad cuando ven v\u00eddeos por streaming en casa pueden hacerlo reduciendo el brillo y utilizando dispositivos m\u00e1s peque\u00f1os, por ejemplo el ordenador port\u00e1til o el m\u00f3vil. En los televisores m\u00e1s nuevos, a\u00f1ade, se puede prescindir tambi\u00e9n de la funci\u00f3n de alto contraste (HDR) para reducir el consumo.<\/p>\n<p>Sin embargo, acota Kl\u00f6ss, el hecho de que se transmita en resoluci\u00f3n SD, HD o 4K solo tiene efecto en el consumo de los centros de datos, pero no en la propia factura de la luz. Los que reducen su consumo en este aspecto hacen algo bueno por el medio ambiente y reducen su huella de CO2.<\/p>\n<p>A la hora de comprar un nuevo electrodom\u00e9stico, Kl\u00f6ss aconseja: \u00abCuando se compra un nuevo electrodom\u00e9stico, merece la pena fijarse en la clase de eficiencia energ\u00e9tica, simplemente para saber lo que se va a pagar en el funcionamiento normal del aparato\u00bb. La etiqueta de eficiencia energ\u00e9tica indica el consumo anual aproximado de un aparato.<\/p>\n<p>En Europa se han reformado recientemente las diferentes clases. <strong>\u00abEl sistema A+ no existe m\u00e1s y, en su lugar, la mayor\u00eda de los aparatos se reclasificaron, a F o G, para liberar los puestos delanteros a favor de nuevos modelos\u00bb, explica Kl\u00f6ss.<\/strong><\/p>\n<p>Seg\u00fan el experto, sustituir un televisor por uno de mayor eficiencia energ\u00e9tica debido a los elevados costes de la electricidad solo merece la pena si se tiene un antiguo televisor de plasma.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Elisabeth Winkler (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad por miedo al encarecimiento del costo de vida. Para poder evaluar d\u00f3nde y c\u00f3mo se puede ahorrar energ\u00eda, es \u00fatil tener una visi\u00f3n general de la cantidad de electricidad que se<\/p>\n","protected":false},"author":1,"featured_media":7643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,36],"tags":[45,103],"class_list":["post-7642","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live","category-titulares","tag-sociedad","tag-tecnologia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live,titulares\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-07T11:07:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-03-07T11:07:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/#listItem\",\"name\":\"Titulares\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/#listItem\",\"position\":2,\"name\":\"Titulares\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#listItem\",\"name\":\"Televisor PC y el m\\u00f3vil: \\u00bfCu\\u00e1nto consumen?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#listItem\",\"position\":3,\"name\":\"Televisor PC y el m\\u00f3vil: \\u00bfCu\\u00e1nto consumen?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/#listItem\",\"name\":\"Titulares\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#newsarticle\",\"name\":\"Televisor PC y el m\\u00f3vil: \\u00bfCu\\u00e1nto consumen? | El Digital de Asturias\",\"headline\":\"Televisor PC y el m\\u00f3vil: \\u00bfCu\\u00e1nto consumen?\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ahorrar.jpg\",\"width\":995,\"height\":664,\"caption\":\"Por muy eficiente que sea, un televisor enorme siempre acaba consumiendo m\\u00e1s electricidad que los aparatos m\\u00e1s peque\\u00f1os. Foto: Zacharie Scheurer\\\/dpa\"},\"datePublished\":\"2023-03-07T12:07:23+01:00\",\"dateModified\":\"2023-03-07T12:07:23+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#webpage\"},\"articleSection\":\"Live, Titulares, Sociedad, Tecnolog\\u00eda\",\"dateline\":\"Publicado el marzo 7, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/\",\"name\":\"Televisor PC y el m\\u00f3vil: \\u00bfCu\\u00e1nto consumen? | El Digital de Asturias\",\"description\":\"(dpa) - Quienes a\\u00fan no hayan reaccionado a los llamamientos a la protecci\\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ahorrar.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#mainImage\",\"width\":995,\"height\":664,\"caption\":\"Por muy eficiente que sea, un televisor enorme siempre acaba consumiendo m\\u00e1s electricidad que los aparatos m\\u00e1s peque\\u00f1os. Foto: Zacharie Scheurer\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/televisor-pc-y-el-movil-cuanto-consumen\\\/#mainImage\"},\"datePublished\":\"2023-03-07T12:07:23+01:00\",\"dateModified\":\"2023-03-07T12:07:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias","description":"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/","robots":"max-image-preview:large","keywords":"live,titulares","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/#listItem","name":"Titulares"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/#listItem","position":2,"name":"Titulares","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#listItem","name":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#listItem","position":3,"name":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen?","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/#listItem","name":"Titulares"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#newsarticle","name":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias","headline":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen?","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg","width":995,"height":664,"caption":"Por muy eficiente que sea, un televisor enorme siempre acaba consumiendo m\u00e1s electricidad que los aparatos m\u00e1s peque\u00f1os. Foto: Zacharie Scheurer\/dpa"},"datePublished":"2023-03-07T12:07:23+01:00","dateModified":"2023-03-07T12:07:23+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#webpage"},"articleSection":"Live, Titulares, Sociedad, Tecnolog\u00eda","dateline":"Publicado el marzo 7, 2023."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/","name":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias","description":"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#mainImage","width":995,"height":664,"caption":"Por muy eficiente que sea, un televisor enorme siempre acaba consumiendo m\u00e1s electricidad que los aparatos m\u00e1s peque\u00f1os. Foto: Zacharie Scheurer\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/#mainImage"},"datePublished":"2023-03-07T12:07:23+01:00","dateModified":"2023-03-07T12:07:23+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias","og:description":"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg","og:image:width":995,"og:image:height":664,"article:published_time":"2023-03-07T11:07:23+00:00","article:modified_time":"2023-03-07T11:07:23+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen? | El Digital de Asturias","twitter:description":"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/03\/ahorrar.jpg"},"aioseo_meta_data":{"post_id":"7642","title":null,"description":"(dpa) - Quienes a\u00fan no hayan reaccionado a los llamamientos a la protecci\u00f3n del clima pueden ahora, al menos, verse motivados a ahorrar electricidad","keywords":[],"keyphrases":{"focus":{"keyphrase":"ahorrar","score":80,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"ahorrar electricidad","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 06:23:15","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-03-07 11:01:52","updated":"2026-05-15 06:23:15","focus_keyword":"ahorrar","additional_keywords":[{"word":"ahorrar electricidad","score":100}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/\" title=\"Titulares\">Titulares<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tTelevisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen?\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Titulares","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/"},{"label":"Televisor PC y el m\u00f3vil: \u00bfCu\u00e1nto consumen?","link":"https:\/\/eldigitaldeasturias.com\/radio\/televisor-pc-y-el-movil-cuanto-consumen\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=7642"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/7643"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=7642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=7642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=7642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}