{"id":7620,"date":"2023-02-14T20:33:42","date_gmt":"2023-02-14T19:33:42","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=7620"},"modified":"2023-02-14T20:33:42","modified_gmt":"2023-02-14T19:33:42","slug":"desciende-la-audiencia-de-los-premios-goya","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/","title":{"rendered":"Desciende la audiencia de los Premios Goya"},"content":{"rendered":"<p>(EP)\u00a0 &#8211; La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, <strong>93.000 menos que la de 2022, si bien la cuota de pantalla alcanz\u00f3 el 23,4%<\/strong>, cinco d\u00e9cimas m\u00e1s que en el a\u00f1o anterior.<\/p>\n<figure id=\"attachment_7621\" aria-describedby=\"caption-attachment-7621\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7621\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya-360x236.jpg\" alt=\"Premios Goya\" width=\"650\" height=\"427\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya-360x236.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya-768x505.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya-150x99.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya-450x296.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg 994w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-7621\" class=\"wp-caption-text\">Foto: Eduardo Parra &#8211; Europa Press<\/figcaption><\/figure>\n<p>La gala, que se celebr\u00f3 en el Auditorio Andaluc\u00eda de Sevilla y en la que &#8216;As bestas&#8217; se coron\u00f3 como la gran triunfadora, fue la emisi\u00f3n l\u00edder en su franja de emisi\u00f3n y reuni\u00f3 en alg\u00fan momento de la noche a 7.572.000 espectadores, seg\u00fan datos de RTVE.<\/p>\n<p>La ceremonia, que tambi\u00e9n supuso un homenaje al cineasta recientemente fallecido Carlos Saura, convirti\u00f3 as\u00ed a La 1 en l\u00edder del s\u00e1bado con un 13,8% y en las franjas de prime time (17,6 %) y late night (24,8 %).<\/p>\n<blockquote><p>El &#8216;minuto de oro&#8217; del d\u00eda tuvo lugar a las 23.15 horas, con 3.185.000 espectadores, lo que supone un 23,8% de cuota de pantalla, pendientes de la ceremonia.<\/p><\/blockquote>\n<p>Adem\u00e1s, la retransmisi\u00f3n previa de la alfombra roja, con la llegada de las estrellas del cine espa\u00f1ol a la gran fiesta de del cine espa\u00f1ol, reuni\u00f3 en La 1 a 1.317.000 espectadores (11,1%), lo que supone 67.000 personas m\u00e1s que la edici\u00f3n anterior.<\/p>\n<h2>RTVE DIGITAL<\/h2>\n<p>La audiencia tambi\u00e9n se interes\u00f3 por la retransmisi\u00f3n en directo en RTVE Digital. En total, m\u00e1s de 157.380 espectadores de RTVE Play conectaron con alguna de las se\u00f1ales de los Premios Goya 2023, un 19% m\u00e1s que el a\u00f1o pasado y un 41% m\u00e1s que en 2021.<\/p>\n<p>Asimismo, la 37 edici\u00f3n de la Gala de los Goya fue seguida anoche por 115.460 espectadores de RTVE Play, que generaron 203.425 visualizaciones totales, un 17,2% m\u00e1s de usuarios que el a\u00f1o anterior y una subida del 26,2% sobre 2021.<\/p>\n<p>El 98% de esas visualizaciones se generan en el directo de La 1 (190.462 visualizaciones de 112.115 espectadores) y un 2% en la se\u00f1al en lengua de signos (4.328 visualizaciones de 3.346 espectadores).<\/p>\n<p>El minuto m\u00e1s visto se localiza en torno a las 23.16 horas, con 26.905 espectadores concurrentes, cuando &#8216;Argentina, 1985&#8217; ganaba el Goya a Mejor pel\u00edcula Iberoamericana.<\/p>\n<p>Por otro lado, el programa especial desde el backstage registr\u00f3 52.240 visualizaciones de 35.058 espectadores en RTVE Play, sumando un 29,4% de espectadores respecto al dato del programa de backstage 2022.<\/p>\n<p>RTVE tambi\u00e9n ha destacado el \u00abgran dato de seguimiento\u00b7 de la alfombra roja de los Goya, cuyas distintas se\u00f1ales suman 122.184 visualizaciones de 66.174 espectadores totales este a\u00f1o, un 12% m\u00e1s que en 2022. Este crecimiento viene impulsado por el directo especial de RTVE Play, que consigue 67.000 visualizaciones de cerca de 43.000 espectadores, a las que hay que sumar 17.400 visualizaciones de YouTube.<\/p>\n<p>Tambi\u00e9n, gana un 60% de espectadores y supera 20.400 la se\u00f1al sin locuci\u00f3n, y la retransmisi\u00f3n especial de radio del programa &#8216;De pel\u00edcula&#8217; de RNE consigue 9.635 reproducciones de 5.114 oyentes.<\/p>\n<h2>EN REDES SOCIALES<\/h2>\n<p>Igualmente, los contenidos de la gala en todas las marcas de RTVE en sus <a href=\"https:\/\/www.facebook.com\/candas365digital\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>redes sociales<\/strong><\/span><\/a> han conseguido en total 2,12 millones de impresiones y 2,10 millones de visualizaciones de video. En concreto, con los directos en redes se ha registrado un total de 246.872 visualizaciones de video.<\/p>\n<p>Los contenidos m\u00e1s destacados han sido un video de TikTok de In\u00e9s Hernand de Playz con 339.000 visualizaciones y un tuit del agradecimiento de Luis Zahera al recoger el Goya a mejor actor de reparto, con 270.000 impresiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP)\u00a0 &#8211; La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos que la de 2022, si bien la cuota de pantalla alcanz\u00f3 el 23,4%, cinco d\u00e9cimas m\u00e1s que en el a\u00f1o anterior. La gala, que se<\/p>\n","protected":false},"author":1,"featured_media":7621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,36],"tags":[79],"class_list":["post-7620","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-titulares","tag-cultura"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias,titulares\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desciende la audiencia de los Premios Goya | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"994\" \/>\n\t\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-14T19:33:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-14T19:33:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Desciende la audiencia de los Premios Goya | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#listItem\",\"name\":\"Desciende la audiencia de los Premios Goya\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#listItem\",\"position\":3,\"name\":\"Desciende la audiencia de los Premios Goya\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#newsarticle\",\"name\":\"Desciende la audiencia de los Premios Goya | El Digital de Asturias\",\"headline\":\"Desciende la audiencia de los Premios Goya\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Premios-Goya.jpg\",\"width\":994,\"height\":653,\"caption\":\"Foto: Eduardo Parra - Europa Press\"},\"datePublished\":\"2023-02-14T20:33:42+01:00\",\"dateModified\":\"2023-02-14T20:33:42+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#webpage\"},\"articleSection\":\"Noticias, Titulares, cultura\",\"dateline\":\"Publicado el febrero 14, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/\",\"name\":\"Desciende la audiencia de los Premios Goya | El Digital de Asturias\",\"description\":\"(EP) - La emisi\\u00f3n de la gala de entrega de los Premios Goya 2023 logr\\u00f3 este s\\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Premios-Goya.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#mainImage\",\"width\":994,\"height\":653,\"caption\":\"Foto: Eduardo Parra - Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/desciende-la-audiencia-de-los-premios-goya\\\/#mainImage\"},\"datePublished\":\"2023-02-14T20:33:42+01:00\",\"dateModified\":\"2023-02-14T20:33:42+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Desciende la audiencia de los Premios Goya | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Desciende la audiencia de los Premios Goya | El Digital de Asturias","description":"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/","robots":"max-image-preview:large","keywords":"noticias,titulares","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#listItem","name":"Desciende la audiencia de los Premios Goya"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#listItem","position":3,"name":"Desciende la audiencia de los Premios Goya","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#newsarticle","name":"Desciende la audiencia de los Premios Goya | El Digital de Asturias","headline":"Desciende la audiencia de los Premios Goya","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg","width":994,"height":653,"caption":"Foto: Eduardo Parra - Europa Press"},"datePublished":"2023-02-14T20:33:42+01:00","dateModified":"2023-02-14T20:33:42+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#webpage"},"articleSection":"Noticias, Titulares, cultura","dateline":"Publicado el febrero 14, 2023."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/","name":"Desciende la audiencia de los Premios Goya | El Digital de Asturias","description":"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#mainImage","width":994,"height":653,"caption":"Foto: Eduardo Parra - Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/#mainImage"},"datePublished":"2023-02-14T20:33:42+01:00","dateModified":"2023-02-14T20:33:42+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Desciende la audiencia de los Premios Goya | El Digital de Asturias","og:description":"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg","og:image:width":994,"og:image:height":653,"article:published_time":"2023-02-14T19:33:42+00:00","article:modified_time":"2023-02-14T19:33:42+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Desciende la audiencia de los Premios Goya | El Digital de Asturias","twitter:description":"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Premios-Goya.jpg"},"aioseo_meta_data":{"post_id":"7620","title":null,"description":"(EP) - La emisi\u00f3n de la gala de entrega de los Premios Goya 2023 logr\u00f3 este s\u00e1bado en La 1 de TVE una audiencia media de 2.684.000 espectadores, 93.000 menos","keywords":[],"keyphrases":{"focus":{"keyphrase":" Goya ","score":83,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":" Premios Goya ","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 06:21:25","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2023-02-14 19:27:37","updated":"2026-05-15 06:21:25","focus_keyword":"Goya","additional_keywords":[{"word":"Premios Goya","score":100}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDesciende la audiencia de los Premios Goya\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Noticias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/"},{"label":"Desciende la audiencia de los Premios Goya","link":"https:\/\/eldigitaldeasturias.com\/radio\/desciende-la-audiencia-de-los-premios-goya\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=7620"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/7621"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=7620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=7620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=7620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}