{"id":7587,"date":"2023-02-05T00:01:27","date_gmt":"2023-02-04T23:01:27","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=7587"},"modified":"2023-02-05T00:01:27","modified_gmt":"2023-02-04T23:01:27","slug":"artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/","title":{"rendered":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear"},"content":{"rendered":"<p>(dpa) &#8211; Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta. <strong>Para los m\u00fasicos es poco alentador hacer sonar en el paseo peatonal de Grafton Street en la capital de Irlanda, Dubl\u00edn, todo el tiempo \u00abFairytale of New York\u00bb, de The Pogues, o \u00abFalling Down\u00bb, de Glen Hansard.<\/strong><\/p>\n<figure id=\"attachment_7588\" aria-describedby=\"caption-attachment-7588\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7588\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan-360x240.jpg\" alt=\"Shane Finan\" width=\"650\" height=\"434\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan-768x513.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg 992w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-7588\" class=\"wp-caption-text\">Shane Finan, artista visual y gestor de proyectos. La cultura y el arte gozan de gran prestigio en Irlanda, y no se consideran un pasatiempo. Unos 2.000 artistas recibir\u00e1n una renta b\u00e1sica estatal en un proyecto piloto. Foto: Amy Bunce\/Shane Finan\/dpa &#8211;<\/figcaption><\/figure>\n<p>Tambi\u00e9n los pintores y escultores suelen sumar trabajos frustrantes para sobrevivir, y los escritores se ganan la vida dando clases porque de otra forma no les alcanza. Sin embargo, un proyecto piloto busca ahora revertir esta situaci\u00f3n en Irlanda otorgando a los artistas aut\u00f3nomos una suma fija para que puedan seguir su vocaci\u00f3n.<\/p>\n<p><strong>Unos 2.000 artistas recibir\u00e1n durante tres a\u00f1os un ingreso b\u00e1sico estatal de 325 euros (353 d\u00f3lares) semanales durante tres a\u00f1os.<\/strong> M\u00e1s de 9.000 personas solicitaron los fondos del programa, dotado con 105 millones de euros. Para elegir a los beneficiarios se utiliz\u00f3 un proceso de selecci\u00f3n aleatorio.<\/p>\n<p>Irlanda no est\u00e1 sola en este proyecto. En Alemania, la asociaci\u00f3n Mein Grundeinkommen (\u00abMi Ingreso B\u00e1sico\u00bb) sortea 1.000 euros mensuales sin condiciones durante un a\u00f1o. Para un estudio de largo plazo que se lleva a cabo en conjunto con el Instituto Alem\u00e1n de Investigaci\u00f3n Econ\u00f3mica (DIW), <strong>122 personas elegidas al azar reciben 1.200 euros al mes durante tres a\u00f1os.<\/strong><\/p>\n<p>\u00abUn estudio de Visual Artists Ireland arroj\u00f3 que unas tres cuartas partes de todos los artistas en Irlanda viv\u00edan por debajo de la l\u00ednea de pobreza antes de la pandemia\u00bb, dice Shane Finan, artista visual y gestor de proyectos de la peque\u00f1a localidad de Manorhamilton, en el noroeste del pa\u00eds de la Uni\u00f3n Europea (UE). Antes de que el proyecto se pusiera en marcha, el gobierno cre\u00f3 un grupo de trabajo y la poblaci\u00f3n pudo hacer comentarios al respecto.<\/p>\n<p>Las personas que recibir\u00e1n el ingreso b\u00e1sico trabajan en distintos \u00e1mbitos. De los receptores, 707 son artistas visuales, a los que se suman 584 m\u00fasicos, pero tambi\u00e9n cineastas, escritores, actores, bailarines, core\u00f3grafos, artistas de circo y arquitectos.<\/p>\n<blockquote><p>Los candidatos no son sometidos a una evaluaci\u00f3n de sus recursos, y los solicitantes tambi\u00e9n pueden tener otros ingresos. En principio, los artistas irlandeses pueden trabajar libres de impuestos, siempre y cuando no ganen m\u00e1s de 50.000 euros al a\u00f1o.<\/p><\/blockquote>\n<p>La presidenta del Arts Council, Maureen Kennelly, habl\u00f3 en el diario \u00abIrish Times\u00bb de un \u00abd\u00eda verdaderamente hist\u00f3rico\u00bb y un \u00abenorme salto hacia adelante\u00bb que era esperado por la escena art\u00edstica irlandesa desde hace a\u00f1os. A\u00f1adi\u00f3 que la urgencia de la pandemia aceler\u00f3 estos cambios.<\/p>\n<p><strong>\u00abEl proyecto es realmente una se\u00f1al de que Irlanda valora a sus artistas y considera las ofertas culturales como un derecho humano\u00bb, afirm\u00f3 Kennelly<\/strong>. Indic\u00f3 que si el proyecto era exitoso iba a poder ser ampliado.<\/p>\n<p>M\u00fasicos como Steven Tynan, de la banda Left on Read, creen que \u00abtodos los artistas de Irlanda deber\u00edan beneficiarse\u00bb con este programa. Para \u00e9l, la suma semanal es una se\u00f1al de que el pa\u00eds \u00abconf\u00eda\u00bb en la gente del mundo de la cultura. Y a\u00f1ade que es \u00abuna motivaci\u00f3n poder sumarse y no pasar tanto tiempo en \u00e1mbitos no creativos, mal pagos, para poder financiar la propia m\u00fasica\u00bb.<\/p>\n<p>El joven de 28 a\u00f1os asegura que ahora tiene tiempo y la cabeza libre. \u00abPoder trabajar como artista de lunes a viernes es realmente incre\u00edble\u00bb, afirma.<\/p>\n<p>La escena cultural irlandesa es, en l\u00edneas generales, reconocida por la sociedad. La m\u00fasica, las artes visuales y la escritura no son considerados simples hobbies. Sin embargo, hasta ahora no hab\u00eda apoyo estatal.<\/p>\n<p>\u00abPor lo general, a nuestras profesiones les falta constancia porque trabajamos en proyectos puntuales y temporales, y a menudo no sabemos de d\u00f3nde vendr\u00e1 el pr\u00f3ximo ingreso\u00bb, dice la curadora y administradora de arte Rachel Botha, de Kilkenny. \u00abMe present\u00e9 para compensar la mala situaci\u00f3n salarial del sector cultural\u00bb, explica.<\/p>\n<p>Para percibir el ingreso b\u00e1sico, los participantes tienen que aceptar que se observe su trabajo durante el proyecto piloto e informar peri\u00f3dicamente sobre su trabajo con fines de investigaci\u00f3n. Otros 1.000 solicitantes forman un grupo de control y reciben un pago mucho menor por sus esfuerzos.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Mareike Graepel (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta. Para los m\u00fasicos es poco alentador hacer sonar en el paseo peatonal de Grafton Street en la capital de Irlanda, Dubl\u00edn, todo el tiempo<\/p>\n","protected":false},"author":1,"featured_media":7588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,36],"tags":[79],"class_list":["post-7587","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-titulares","tag-cultura"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias,titulares\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-04T23:01:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-04T23:01:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#listItem\",\"name\":\"Artistas de Irlanda recibir\\u00e1n un ingreso estatal para dedicarse a crear\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#listItem\",\"position\":3,\"name\":\"Artistas de Irlanda recibir\\u00e1n un ingreso estatal para dedicarse a crear\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#newsarticle\",\"name\":\"Artistas de Irlanda recibir\\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias\",\"headline\":\"Artistas de Irlanda recibir\\u00e1n un ingreso estatal para dedicarse a crear\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Shane-Finan.jpg\",\"width\":992,\"height\":662,\"caption\":\"Shane Finan, artista visual y gestor de proyectos. La cultura y el arte gozan de gran prestigio en Irlanda, y no se consideran un pasatiempo. Unos 2.000 artistas recibir\\u00e1n una renta b\\u00e1sica estatal en un proyecto piloto. Foto: Amy Bunce\\\/Shane Finan\\\/dpa -\"},\"datePublished\":\"2023-02-05T00:01:27+01:00\",\"dateModified\":\"2023-02-05T00:01:27+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#webpage\"},\"articleSection\":\"Noticias, Titulares, cultura\",\"dateline\":\"Publicado el febrero 5, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/\",\"name\":\"Artistas de Irlanda recibir\\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias\",\"description\":\"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\\u00edo, mientras que algunos peatones pagan un par de euros con el m\\u00f3vil o la tarjeta\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Shane-Finan.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#mainImage\",\"width\":992,\"height\":662,\"caption\":\"Shane Finan, artista visual y gestor de proyectos. La cultura y el arte gozan de gran prestigio en Irlanda, y no se consideran un pasatiempo. Unos 2.000 artistas recibir\\u00e1n una renta b\\u00e1sica estatal en un proyecto piloto. Foto: Amy Bunce\\\/Shane Finan\\\/dpa -\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\\\/#mainImage\"},\"datePublished\":\"2023-02-05T00:01:27+01:00\",\"dateModified\":\"2023-02-05T00:01:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias","description":"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/","robots":"max-image-preview:large","keywords":"noticias,titulares","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#listItem","name":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#listItem","position":3,"name":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#newsarticle","name":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias","headline":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg","width":992,"height":662,"caption":"Shane Finan, artista visual y gestor de proyectos. La cultura y el arte gozan de gran prestigio en Irlanda, y no se consideran un pasatiempo. Unos 2.000 artistas recibir\u00e1n una renta b\u00e1sica estatal en un proyecto piloto. Foto: Amy Bunce\/Shane Finan\/dpa -"},"datePublished":"2023-02-05T00:01:27+01:00","dateModified":"2023-02-05T00:01:27+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#webpage"},"articleSection":"Noticias, Titulares, cultura","dateline":"Publicado el febrero 5, 2023."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/","name":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias","description":"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#mainImage","width":992,"height":662,"caption":"Shane Finan, artista visual y gestor de proyectos. La cultura y el arte gozan de gran prestigio en Irlanda, y no se consideran un pasatiempo. Unos 2.000 artistas recibir\u00e1n una renta b\u00e1sica estatal en un proyecto piloto. Foto: Amy Bunce\/Shane Finan\/dpa -"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/#mainImage"},"datePublished":"2023-02-05T00:01:27+01:00","dateModified":"2023-02-05T00:01:27+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias","og:description":"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg","og:image:width":992,"og:image:height":662,"article:published_time":"2023-02-04T23:01:27+00:00","article:modified_time":"2023-02-04T23:01:27+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear | El Digital de Asturias","twitter:description":"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2023\/02\/Shane-Finan.jpg"},"aioseo_meta_data":{"post_id":"7587","title":null,"description":"(dpa) - Las monedas caen de a una en el sombrero apoyado sobre el asfalto fr\u00edo, mientras que algunos peatones pagan un par de euros con el m\u00f3vil o la tarjeta","keywords":[],"keyphrases":{"focus":{"keyphrase":" euros","score":80,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"monedas ","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 06:19:23","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2023-02-04 22:51:03","updated":"2026-05-15 06:19:23","focus_keyword":"euros","additional_keywords":[{"word":"monedas","score":83}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tArtistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Noticias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/"},{"label":"Artistas de Irlanda recibir\u00e1n un ingreso estatal para dedicarse a crear","link":"https:\/\/eldigitaldeasturias.com\/radio\/artistas-de-irlanda-recibiran-un-ingreso-estatal-para-dedicarse-a-crear\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=7587"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/7588"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=7587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=7587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=7587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}