{"id":7215,"date":"2022-08-28T12:36:50","date_gmt":"2022-08-28T10:36:50","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=7215"},"modified":"2022-08-28T12:36:50","modified_gmt":"2022-08-28T10:36:50","slug":"exito-del-foro-iberoamericano-de-la-rabida","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/","title":{"rendered":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida"},"content":{"rendered":"<p>(EP) &#8211; M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del <strong>Foro Iberoamericano de La R\u00e1bida<\/strong>, algo que confirma que la programaci\u00f3n de la Diputaci\u00f3n de Huelva en este espacio es \u00abuna de las propuestas m\u00e1s respaldadas por el p\u00fablico en la temporada estival\u00bb.<\/p>\n<figure id=\"attachment_7216\" aria-describedby=\"caption-attachment-7216\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7216\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida-360x239.jpg\" alt=\"La R\u00e1bida\" width=\"650\" height=\"432\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida-768x510.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg 1001w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-7216\" class=\"wp-caption-text\">FOTO: JES\u00daS GARC\u00cdA SERRANO\/DIPUTACI\u00d3N DE HUELVA \/ EP<\/figcaption><\/figure>\n<p>Seg\u00fan ha informado la instituci\u00f3n provincial en una nota de prensa el s\u00e1bado, seis espect\u00e1culos en julio y tres en agosto &#8211;uno de ellos doble&#8211; han conformado un cartel \u00abvariado y de calidad\u00bb, para todos los p\u00fablicos, que ha \u00abvuelto a atraer\u00bb a miles de onubenses y de visitantes que se encuentran en la provincia en verano.<\/p>\n<p>La programaci\u00f3n arrancaba el 8 de julio con una de las grandes voces del panorama nacional, <strong>Vanesa Mart\u00edn<\/strong>. Posteriormente, el rock andaluz fue protagonista &#8211;el 9 de julio&#8211; de la mano de<strong> Medina Azahara<\/strong> y el directo de su \u00faltimo \u00e1lbum de estudio, &#8216;Lleg\u00f3 el D\u00eda&#8217;.<\/p>\n<p><strong>El Arrebato<\/strong> subi\u00f3 a las tablas del escenario rabide\u00f1o el 15 de julio con su &#8216;Tour+Abrazos&#8217;, un directo con el que el artista vuelve renovado y celebrando dos d\u00e9cadas de esfuerzos, arte, talento, y enormes composiciones. Un d\u00eda despu\u00e9s, <strong>Manolo Garc\u00eda colg\u00f3 el cartel de \u00abno hay localidades\u00bb<\/strong>, como acostumbra cada vez que act\u00faa en el Foro. El ic\u00f3nico artista interpret\u00f3 en directo temas del doble disco que estren\u00f3 en primavera &#8216;Mi vida en Marte&#8217; y &#8216;Desatinos desplumados&#8217;.<\/p>\n<p>La feminidad, la fuerza y el talento sobre las tablas de<strong> India Mart\u00ednez cerr\u00f3 el triplete de conciertos de ese fin de semana<\/strong>. La cordobesa interpret\u00f3 ante el p\u00fablico rabide\u00f1o los temas de su \u00faltimo disco, &#8216;Palmeras&#8217;, en una noche inolvidable para los asistentes al concierto de esta artista esencial de la escena musical, que se entrega en cada concierto.<\/p>\n<p>El mes de julio se despidi\u00f3 con uno de los platos fuertes de la programaci\u00f3n. El s\u00e1bado, d\u00eda 30 de julio, <strong>Estopa trajo al verano onubense su gira &#8216;Fuego&#8217;, con la que los hermanos Mu\u00f1oz celebran sus m\u00e1s de 20 a\u00f1os de exitosa carrera musical presentando las canciones de su \u00faltimo disco, &#8216;Fuego<\/strong>&#8216;. Adem\u00e1s, no faltaron algunos de los grandes \u00e9xitos que han hecho de Estopa uno de los grupos referentes de la m\u00fasica nacional con m\u00e1s de cinco millones de discos vendidos en todo el mundo.<\/p>\n<p><strong>Melendi fue el encargado de inaugurar los conciertos de agosto el d\u00eda 12. El carism\u00e1tico artista asturiano interpret\u00f3 los temas de su \u00faltimo \u00e1lbum &#8216;Likes y cicatrices<\/strong>&#8216;, que vio la luz el pasado noviembre y que incluye una gran variedad de g\u00e9neros musicales como pop, rumba, salsa y latino.<\/p>\n<p>El s\u00e1bado 20, la cita fue doble y con una identidad cien por cien onubense: el d\u00fao <strong>Ant\u00edlopez y Cristian de Moret<\/strong>, que compartieron escenario. Y el broche de oro a los conciertos del Foro Iberoamericano de este verano ha sido la gran noche de &#8216;Raphael 6.0&#8217;. Una noche \u00abhist\u00f3rica\u00bb con el hechizo de <strong>Raphael<\/strong> en la que no faltaron himnos atemporales como &#8216;Mi gran noche&#8217;, &#8216;Qu\u00e9 sabe nadie&#8217; y &#8216;Yo soy aqu\u00e9l&#8217;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n de la Diputaci\u00f3n de Huelva en este espacio es \u00abuna de las propuestas m\u00e1s respaldadas por el p\u00fablico en la temporada estival\u00bb. Seg\u00fan ha informado la instituci\u00f3n provincial en una<\/p>\n","protected":false},"author":1,"featured_media":7216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[89],"class_list":["post-7215","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-musica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-08-28T10:36:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-08-28T10:36:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#listItem\",\"name\":\"\\u00c9xito del Foro Iberoamericano de La R\\u00e1bida\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#listItem\",\"position\":3,\"name\":\"\\u00c9xito del Foro Iberoamericano de La R\\u00e1bida\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#newsarticle\",\"name\":\"\\u00c9xito del Foro Iberoamericano de La R\\u00e1bida | El Digital de Asturias\",\"headline\":\"\\u00c9xito del Foro Iberoamericano de La R\\u00e1bida\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/La-Rabida.jpg\",\"width\":1001,\"height\":665,\"caption\":\"FOTO: JES\\u00daS GARC\\u00cdA SERRANO\\\/DIPUTACI\\u00d3N DE HUELVA \\\/ EP\"},\"datePublished\":\"2022-08-28T12:36:50+02:00\",\"dateModified\":\"2022-08-28T12:36:50+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#webpage\"},\"articleSection\":\"Noticias, m\\u00fasica\",\"dateline\":\"Publicado el agosto 28, 2022.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/\",\"name\":\"\\u00c9xito del Foro Iberoamericano de La R\\u00e1bida | El Digital de Asturias\",\"description\":\"(EP) - M\\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\\u00e1bida, algo que confirma que la programaci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/La-Rabida.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#mainImage\",\"width\":1001,\"height\":665,\"caption\":\"FOTO: JES\\u00daS GARC\\u00cdA SERRANO\\\/DIPUTACI\\u00d3N DE HUELVA \\\/ EP\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/exito-del-foro-iberoamericano-de-la-rabida\\\/#mainImage\"},\"datePublished\":\"2022-08-28T12:36:50+02:00\",\"dateModified\":\"2022-08-28T12:36:50+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias","description":"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/","robots":"max-image-preview:large","keywords":"noticias","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#listItem","name":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#listItem","position":3,"name":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#newsarticle","name":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias","headline":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg","width":1001,"height":665,"caption":"FOTO: JES\u00daS GARC\u00cdA SERRANO\/DIPUTACI\u00d3N DE HUELVA \/ EP"},"datePublished":"2022-08-28T12:36:50+02:00","dateModified":"2022-08-28T12:36:50+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#webpage"},"articleSection":"Noticias, m\u00fasica","dateline":"Publicado el agosto 28, 2022."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/","name":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias","description":"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#mainImage","width":1001,"height":665,"caption":"FOTO: JES\u00daS GARC\u00cdA SERRANO\/DIPUTACI\u00d3N DE HUELVA \/ EP"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/#mainImage"},"datePublished":"2022-08-28T12:36:50+02:00","dateModified":"2022-08-28T12:36:50+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias","og:description":"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg","og:image:width":1001,"og:image:height":665,"article:published_time":"2022-08-28T10:36:50+00:00","article:modified_time":"2022-08-28T10:36:50+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida | El Digital de Asturias","twitter:description":"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/La-Rabida.jpg"},"aioseo_meta_data":{"post_id":"7215","title":null,"description":"(EP) - M\u00e1s de 15.000 espectadores han asistido este verano a los conciertos del Foro Iberoamericano de La R\u00e1bida, algo que confirma que la programaci\u00f3n","keywords":[],"keyphrases":{"focus":{"keyphrase":"La R\u00e1bida","score":92,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase not found in the URL.","score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase found in image alt attribute(s).","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 05:46:33","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-08-28 10:30:08","updated":"2026-05-15 05:46:33","focus_keyword":"La R\u00e1bida","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u00c9xito del Foro Iberoamericano de La R\u00e1bida\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Noticias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/"},{"label":"\u00c9xito del Foro Iberoamericano de La R\u00e1bida","link":"https:\/\/eldigitaldeasturias.com\/radio\/exito-del-foro-iberoamericano-de-la-rabida\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=7215"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/7216"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=7215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=7215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=7215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}