{"id":7093,"date":"2022-08-06T03:35:40","date_gmt":"2022-08-06T01:35:40","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=7093"},"modified":"2022-08-06T03:35:40","modified_gmt":"2022-08-06T01:35:40","slug":"que-tener-en-cuenta-a-la-hora-de-comprar-un-dron","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/","title":{"rendered":"Qu\u00e9 tener en cuenta a la hora de comprar un dron"},"content":{"rendered":"<p>(dpa) &#8211; Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos de los compradores de drones, pero no todos los modelos los ofrecen.<\/p>\n<figure id=\"attachment_7094\" aria-describedby=\"caption-attachment-7094\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7094\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron-360x241.jpg\" alt=\"dron\" width=\"650\" height=\"434\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron-360x241.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron-768x513.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron-450x301.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg 995w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-7094\" class=\"wp-caption-text\">Foto: Alexander Prautzsch\/dpa<\/figcaption><\/figure>\n<p>A esta conclusi\u00f3n lleg\u00f3 una comparaci\u00f3n de doce cuadric\u00f3pteros, es decir, drones con cuatro rotores, realizada por la organizaci\u00f3n alemana de protecci\u00f3n al consumidor y evaluaci\u00f3n de productos Stiftung Warentest en la edici\u00f3n 1\/22 de su revista \u00abtest\u00bb.<\/p>\n<p>Como primer punto, seg\u00fan los expertos, aparte del hecho de que no tienen c\u00e1mara, debe quedar claro que los minidrones sin GPS son m\u00e1s adecuados para su uso en interiores que en exteriores.<\/p>\n<p>En las pruebas realizadas, los m\u00e1s ligeros movimientos de aire bastaban para desviarlos de su curso y la duraci\u00f3n de los vuelos no superaba los diez minutos con una carga de la bater\u00eda. Con los drones con GPS de mayor tama\u00f1o, en cambio, se puede esperar un tiempo de vuelo de algo menos de media hora.<\/p>\n<p>Antes de empezar a comparar modelos, se debe decidir el peso que deber\u00e1 tener el dron: de hasta 249 gramos o de 250 gramos o m\u00e1s.<\/p>\n<p>De acuerdo con la normativa europea, el uso de drones de un peso mayor a 250 gramos requiere el llamado certificado de competencia de piloto remoto (A1\/A3). Algunas agencias de seguridad a\u00e9rea ofrecen en sus p\u00e1ginas ex\u00e1menes en l\u00ednea para obtener esta licencia.<\/p>\n<p>Casi todos los modelos de drones tienen un mando a distancia que debe acoplarse a un m\u00f3vil a trav\u00e9s de una aplicaci\u00f3n. Los expertos criticaron el manejo de env\u00edo de datos de muchas aplicaciones, ya que estas tambi\u00e9n env\u00edan datos innecesarios, como el n\u00famero de serie del dron.<\/p>\n<p>En la categor\u00eda de drones de m\u00e1s de 250 gramos, los modelos DJI Air 2S y DJI Mavic Air 2 compartieron el primer puesto. Ambos recibieron la puntuaci\u00f3n general de 1,3. Esta nota equivalente a un \u00abMuy bueno\u00bb se debi\u00f3 a las excelentes funciones autom\u00e1ticas del dron, entre otras la funci\u00f3n de retorno, el seguimiento de objetos o la detecci\u00f3n de obst\u00e1culos, as\u00ed como a sus muy buenas c\u00e1maras.<\/p>\n<p>Ligeramente por detr\u00e1s, con la apreciaci\u00f3n \u00abBueno\u00bb (1,8), se ubic\u00f3 en segundo lugar el Parrot Anafi con buenas caracter\u00edsticas de vuelo y una buena c\u00e1mara. El \u00fanico dron de la prueba dentro de la categor\u00eda de menos de 250 gramos calificado como \u00abBueno\u00bb fue el DJI Mini 2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos de los compradores de drones, pero no todos los modelos los ofrecen. A esta conclusi\u00f3n lleg\u00f3 una comparaci\u00f3n de doce cuadric\u00f3pteros, es decir, drones con cuatro rotores, realizada por la organizaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":7094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[103],"class_list":["post-7093","post","type-post","status-publish","format-standard","has-post-thumbnail","category-variedades","tag-tecnologia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"variedades\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-08-06T01:35:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-08-06T01:35:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/variedades\\\/#listItem\",\"name\":\"Variedades\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/variedades\\\/#listItem\",\"position\":2,\"name\":\"Variedades\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/variedades\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#listItem\",\"name\":\"Qu\\u00e9 tener en cuenta a la hora de comprar un dron\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#listItem\",\"position\":3,\"name\":\"Qu\\u00e9 tener en cuenta a la hora de comprar un dron\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/variedades\\\/#listItem\",\"name\":\"Variedades\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#newsarticle\",\"name\":\"Qu\\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias\",\"headline\":\"Qu\\u00e9 tener en cuenta a la hora de comprar un dron\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/dron.jpg\",\"width\":995,\"height\":665,\"caption\":\"Foto: Alexander Prautzsch\\\/dpa\"},\"datePublished\":\"2022-08-06T03:35:40+02:00\",\"dateModified\":\"2022-08-06T03:35:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#webpage\"},\"articleSection\":\"Variedades, Tecnolog\\u00eda\",\"dateline\":\"Publicado el agosto 6, 2022.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/\",\"name\":\"Qu\\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias\",\"description\":\"(dpa) - Vuelo estable, f\\u00e1cil control, \\u00fatiles funciones de vuelo autom\\u00e1tico y magn\\u00edficas fotos a\\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/dron.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#mainImage\",\"width\":995,\"height\":665,\"caption\":\"Foto: Alexander Prautzsch\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\\\/#mainImage\"},\"datePublished\":\"2022-08-06T03:35:40+02:00\",\"dateModified\":\"2022-08-06T03:35:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias","description":"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/","robots":"max-image-preview:large","keywords":"variedades","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/variedades\/#listItem","name":"Variedades"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/variedades\/#listItem","position":2,"name":"Variedades","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/variedades\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#listItem","name":"Qu\u00e9 tener en cuenta a la hora de comprar un dron"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#listItem","position":3,"name":"Qu\u00e9 tener en cuenta a la hora de comprar un dron","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/variedades\/#listItem","name":"Variedades"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#newsarticle","name":"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias","headline":"Qu\u00e9 tener en cuenta a la hora de comprar un dron","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg","width":995,"height":665,"caption":"Foto: Alexander Prautzsch\/dpa"},"datePublished":"2022-08-06T03:35:40+02:00","dateModified":"2022-08-06T03:35:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#webpage"},"articleSection":"Variedades, Tecnolog\u00eda","dateline":"Publicado el agosto 6, 2022."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/","name":"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias","description":"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#mainImage","width":995,"height":665,"caption":"Foto: Alexander Prautzsch\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/#mainImage"},"datePublished":"2022-08-06T03:35:40+02:00","dateModified":"2022-08-06T03:35:40+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias","og:description":"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg","og:image:width":995,"og:image:height":665,"article:published_time":"2022-08-06T01:35:40+00:00","article:modified_time":"2022-08-06T01:35:40+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Qu\u00e9 tener en cuenta a la hora de comprar un dron | El Digital de Asturias","twitter:description":"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2022\/08\/dron.jpg"},"aioseo_meta_data":{"post_id":"7093","title":null,"description":"(dpa) - Vuelo estable, f\u00e1cil control, \u00fatiles funciones de vuelo autom\u00e1tico y magn\u00edficas fotos a\u00e9reas: todos estos aspectos pueden encabezar la lista de deseos","keywords":[],"keyphrases":{"focus":{"keyphrase":"dron","score":68,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase not found in meta description.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase not found in the URL.","score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase does not appear in the first paragraph. Make sure the topic is clear immediately.","score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase found in image alt attribute(s).","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 05:35:07","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-08-06 01:32:32","updated":"2026-05-15 05:35:07","focus_keyword":"dron","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/variedades\/\" title=\"Variedades\">Variedades<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tQu\u00e9 tener en cuenta a la hora de comprar un dron\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Variedades","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/variedades\/"},{"label":"Qu\u00e9 tener en cuenta a la hora de comprar un dron","link":"https:\/\/eldigitaldeasturias.com\/radio\/que-tener-en-cuenta-a-la-hora-de-comprar-un-dron\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=7093"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/7093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/7094"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=7093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=7093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=7093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}