{"id":3536,"date":"2019-11-24T03:44:31","date_gmt":"2019-11-24T03:44:31","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/radio\/?p=3536"},"modified":"2019-11-24T03:45:11","modified_gmt":"2019-11-24T03:45:11","slug":"la-cdu-alemana-inicia-su-congreso-anual","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/","title":{"rendered":"La CDU alemana inicia su congreso anual"},"content":{"rendered":"<figure id=\"attachment_3537\" aria-describedby=\"caption-attachment-3537\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-3537\" src=\"http:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU-360x203.jpg\" alt=\"\" width=\"360\" height=\"203\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU-360x203.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU-1024x576.jpg 1024w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU-768x434.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU-600x337.jpg 600w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg 1098w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-3537\" class=\"wp-caption-text\">Foto: Michael Kappeler\/dpa<\/figcaption><\/figure>\n<p>Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido.<\/p>\n<p>Las esperanzas de Merkel acerca de una transici\u00f3n de poder sin sobresaltos al frente del partido democratacristiano se han visto amenazadas por el fuerte descenso del apoyo que Kramp-Karrenbauer registra en las encuestas.<\/p>\n<p>La canciller alemana, ovacionada en su breve aparici\u00f3n en el congreso, pretende desviar toda la atenci\u00f3n hacia la tambi\u00e9n ministra de Defensa, en un intento por consolidar su posici\u00f3n como l\u00edder actual del partido.<\/p>\n<p>Kramp-Karrenbauer admiti\u00f3 esta semana que ha cometido errores desde que asumi\u00f3 el liderazgo de los conservadores hace un a\u00f1o. En relaci\u00f3n al congreso, ha tratado que la reuni\u00f3n federal de unos 1.000 delegados sea el escenario de un debate sobre pol\u00edticas fundamentales.<\/p>\n<p>En una serie de entrevistas concedidas antes del congreso, la l\u00edder de la CDU insisti\u00f3 en que el partido debe concentrarse en asuntos de importancia para los votantes, insistiendo en que ella es la responsable de elegir al candidato que reemplazar\u00e1 a Merkel como canciller de cara a las elecciones de 2021.<\/p>\n<p>\u00abSoy la l\u00edder del partido y la que dirige este proceso desde un principio\u00bb, declar\u00f3 al peri\u00f3dido \u00abFrankfurter Allgemeine Zeitung\u00bb.<\/p>\n<p>\u00abDecidiremos (el candidato) a finales de 2020 en el congreso de nuestro partido. Cualquiera que pretenda lo contrario tiene la oportunidad de hacerse o\u00edr aqu\u00ed en Leipzig\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Sin embargo, la bajada en las encuestas de Kramp-Karrenbauer ha motivado las especulaciones en torno a que pueda enfrentar un desaf\u00edo dentro del propio partido en su apuesta por suceder a Merkel.<\/p>\n<p>Durante el congreso, parte de la atenci\u00f3n se centrar\u00e1 en un posible enfrentamiento entre ella y el empresario Friedrich Merz, un antiguo peso pesado del partido, quien ostenta bastante popularidad en el ala conservadora y cuya participaci\u00f3n tambi\u00e9n est\u00e1 prevista en el congreso.<\/p>\n<p>Merz critic\u00f3 el mes pasado la imagen del Gobierno de coalici\u00f3n liderado por Angela Merkel, que calific\u00f3 de \u00abpat\u00e9tica\u00bb, al tiempo que manifest\u00f3 sus dudas en torno a la posibilidad de que pueda sobrevivir los dos pr\u00f3ximos a\u00f1os.<\/p>\n<p>Otros de los asuntos candentes del congreso, m\u00e1s all\u00e1 de la posible concesi\u00f3n de la red 5G al fabricante chino Huawei, son la relaci\u00f3n de la CDU con la ultraderechista Alternativa para Alemania (AfD) o la mencionada coalici\u00f3n de gobierno con el Partido Socialdem\u00f3crata (SPD).<\/p>\n<p>El debate sobre el liderazgo en la CDU ha adquirido un car\u00e1cter de urgencia en los \u00faltimos meses, debido a la posibilidad de que el SPD decida abandonar la coalici\u00f3n en su pr\u00f3ximo congreso en diciembre, lo que motivar\u00eda la celebraci\u00f3n de elecciones anticipadas.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Andrew McCathie (dpa)<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de<\/p>\n","protected":false},"author":1,"featured_media":3537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11],"class_list":["post-3536","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-politica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La CDU alemana inicia su congreso anual | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1098\" \/>\n\t\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-11-24T03:44:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-11-24T03:45:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La CDU alemana inicia su congreso anual | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#listItem\",\"name\":\"La CDU alemana inicia su congreso anual\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#listItem\",\"position\":3,\"name\":\"La CDU alemana inicia su congreso anual\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#newsarticle\",\"name\":\"La CDU alemana inicia su congreso anual | El Digital de Asturias\",\"headline\":\"La CDU alemana inicia su congreso anual\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CONGRESO-CDU.jpg\",\"width\":1098,\"height\":620,\"caption\":\"Foto: Michael Kappeler\\\/dpa\"},\"datePublished\":\"2019-11-24T03:44:31+01:00\",\"dateModified\":\"2019-11-24T03:45:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#webpage\"},\"articleSection\":\"Noticias, Pol\\u00edtica\",\"dateline\":\"Publicado el noviembre 24, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/\",\"name\":\"La CDU alemana inicia su congreso anual | El Digital de Asturias\",\"description\":\"Berl\\u00edn, 22 nov (dpa) \\u2013 El congreso anual de la Uni\\u00f3n Dem\\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\\u00f3n de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CONGRESO-CDU.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#mainImage\",\"width\":1098,\"height\":620,\"caption\":\"Foto: Michael Kappeler\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-cdu-alemana-inicia-su-congreso-anual\\\/#mainImage\"},\"datePublished\":\"2019-11-24T03:44:31+01:00\",\"dateModified\":\"2019-11-24T03:45:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La CDU alemana inicia su congreso anual | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La CDU alemana inicia su congreso anual | El Digital de Asturias","description":"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/","robots":"max-image-preview:large","keywords":"noticias","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#listItem","name":"La CDU alemana inicia su congreso anual"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#listItem","position":3,"name":"La CDU alemana inicia su congreso anual","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#newsarticle","name":"La CDU alemana inicia su congreso anual | El Digital de Asturias","headline":"La CDU alemana inicia su congreso anual","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg","width":1098,"height":620,"caption":"Foto: Michael Kappeler\/dpa"},"datePublished":"2019-11-24T03:44:31+01:00","dateModified":"2019-11-24T03:45:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#webpage"},"articleSection":"Noticias, Pol\u00edtica","dateline":"Publicado el noviembre 24, 2019."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/","name":"La CDU alemana inicia su congreso anual | El Digital de Asturias","description":"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#mainImage","width":1098,"height":620,"caption":"Foto: Michael Kappeler\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/#mainImage"},"datePublished":"2019-11-24T03:44:31+01:00","dateModified":"2019-11-24T03:45:11+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"La CDU alemana inicia su congreso anual | El Digital de Asturias","og:description":"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg","og:image:width":1098,"og:image:height":620,"article:published_time":"2019-11-24T03:44:31+00:00","article:modified_time":"2019-11-24T03:45:11+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"La CDU alemana inicia su congreso anual | El Digital de Asturias","twitter:description":"Berl\u00edn, 22 nov (dpa) \u2013 El congreso anual de la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) se inicia hoy en Leipzig en medio de una posible crisis sobre el liderazgo de la sucesora de Angela Merkel, Annegret Kramp-Karrenbauer, quien se esfuerza en ejercer su autoridad en el partido. Las esperanzas de Merkel acerca de una transici\u00f3n de","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/11\/CONGRESO-CDU.jpg"},"aioseo_meta_data":{"post_id":"3536","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 23:26:29","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 20:44:35","updated":"2026-05-14 23:26:29","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa CDU alemana inicia su congreso anual\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Noticias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/noticias\/"},{"label":"La CDU alemana inicia su congreso anual","link":"https:\/\/eldigitaldeasturias.com\/radio\/la-cdu-alemana-inicia-su-congreso-anual\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/3536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=3536"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/3536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/3537"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=3536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=3536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=3536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}