{"id":3383,"date":"2019-10-26T03:46:38","date_gmt":"2019-10-26T03:46:38","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=3383"},"modified":"2019-10-26T03:46:38","modified_gmt":"2019-10-26T03:46:38","slug":"el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/","title":{"rendered":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3384\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-360x248.jpg\" alt=\"\" width=\"360\" height=\"248\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-360x248.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-1024x706.jpg 1024w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-768x530.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-1536x1060.jpg 1536w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-2048x1413.jpg 2048w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero tambi\u00e9n antes, de ciertas operaciones de cirug\u00eda est\u00e9tica<\/p>\n<p>Una intervenci\u00f3n de cirug\u00eda pl\u00e1stica es una decisi\u00f3n muy seria en la vida de quien desea someterse a ella, por eso:<\/p>\n<p><strong>Antes de una liposucci\u00f3n, mamoplastia o abdominoplastia es recomendable realizar ciertas pautas de entrenamiento con el fin de que el cuerpo llegue a la operaci\u00f3n lo m\u00e1s preparado posible.\u00a0<\/strong>El objetivo es el de potenciar el tono muscular y mejorar los sistemas linf\u00e1tico y circulatorio<strong>.<\/strong>\u00a0Esto ayudar\u00e1 a que la regeneraci\u00f3n de estructuras sea lo m\u00e1s r\u00e1pida posible tras la intervenci\u00f3n y tambi\u00e9n a que el paciente reduzca su ansiedad. Las t\u00e9cnicas de relajaci\u00f3n: masajes, drenajes linf\u00e1ticos y venosos, etc. son una parte importante de estos ejercicios pre-operaci\u00f3n.<\/p>\n<p>Las\u00a0<strong>personas que han sufrido sobrepeso, adelgazado muy r\u00e1pido o viceversa, o las que su abdomen se ha visto deformado tras varios embarazos<\/strong>, son perfectas para someterse a una liposucci\u00f3n o abdominoplastia. \u00c9stas necesitar\u00e1n realizar ejercicio y llevar una dieta sana y equilibrada tras la operaci\u00f3n. Ya que hay que tener claro que estas intervenciones son un \u2018\u2019plus\u2019\u2019 a la hora de mantenerse en forma, y sirven para extraer una cantidad determinada de grasa que no se modifica con dieta ni con ejercicio. Por lo que la combinaci\u00f3n perfecta ser\u00eda:\u00a0<strong>DIETA + GYM + OPERACI\u00d3N<\/strong><\/p>\n<p><strong>Pasados dos meses desde una mamoplastia\u00a0<\/strong>se debe practicar deporte para mantener la musculatura. Pero se debe tener en cuenta lo siguiente:<\/p>\n<p><strong>No a los deportes de contacto<\/strong>. Ya que \u00e9stos podr\u00edan da\u00f1ar o desplazar el implante.<\/p>\n<p><strong>Si se sale a correr, se practica aerobic, zumba,\u2026 se debe utilizar un calzado adecuado y un sujetador deportivo<\/strong>\u00a0completamente\u00a0<strong>adaptado a las nuevas pr\u00f3tesis<\/strong>, para evitar as\u00ed el cimbreo y los movimientos del pecho.<\/p>\n<p><strong>Si se practican deportes de raqueta<\/strong>\u00a0se deben realizar a raja tabla los estiramientos de brazos antes y despu\u00e9s del ejercicio en s\u00ed.<\/p>\n<p><strong>Tratamientos en la cl\u00ednica del Dr Diego Tom\u00e1s Ivancich<\/strong><\/p>\n<p><strong>Abdominoplastia<\/strong>: esta operaci\u00f3n se realiza bajo anestesia general y la recuperaci\u00f3n puede llevar de unas semanas a unos meses, seg\u00fan el estado f\u00edsico del paciente.\u00a0<strong>PVP: desde 5.900 \u20ac<\/strong><\/p>\n<p><strong>Liposucci\u00f3n:<\/strong>\u00a0se trata de un \u2018\u2019plus\u2019\u2019 a la hora de mantenerse en forma, ya que sirve para extraer una cantidad determinada de grasa que no se modifica con la dieta y amoldar el cuerpo. No hay que olvidar seguir una buena dieta y unas pautas de ejercicio tras la operaci\u00f3n.\u00a0<strong>PVP: desde 2.500 \u20ac<\/strong><\/p>\n<p><strong>Mamoplastia<\/strong>: consiste en un cambio de volumen y\/o forma de los senos, y hay de dos tipos: aumento o reducci\u00f3n. Para esta intervenci\u00f3n se realiza un estudio preoperatorio, requiere de anestesia general y se realiza mediante una peque\u00f1a incisi\u00f3n en el pliegue submamario o alrededor de la areola, dependiendo del caso.\u00a0<strong>PVP:<\/strong><strong>\u00a0desde 5.500 \u20ac<\/strong><\/p>\n<p><strong>\u200bAcerca del Doctor Diego Tom\u00e1s Ivancich<\/strong><\/p>\n<p>El Dr Diego Tom\u00e1s Ivancich es especialista en Cirug\u00eda Pl\u00e1stica v\u00eda MIR y miembro numerario de la SECPRE, contando con m\u00e1s de 20 a\u00f1os de experiencia centrados en el campo de la cirug\u00eda est\u00e9tica.<\/p>\n<p>Cuenta con m\u00e1s de 10.000 cirug\u00edas realizadas y asiste peri\u00f3dicamente a los congresos m\u00e1s importantes de su especialidad para estar siempre al d\u00eda, y con los a\u00f1os se ha convertido en un referente para los medios de comunicaci\u00f3n, donde es habitual verle o escucharle, as\u00ed como para las periodistas de belleza, por su solvencia en la materia y credibilidad. Por su dilatada experiencia es uno de los profesionales m\u00e1s preciados en Espa\u00f1a y solicitado para casos de secuelas y malos resultados de cirug\u00eda est\u00e9tica.<br \/>\nSus consultas se caracterizan por su empat\u00eda con los pacientes, su trato exquisito y sobre todo por resolver complejos y problemas de autoestima con discreci\u00f3n y con trato individual y personalizado, dedicando a cada paciente el tiempo necesario para resolver todas sus dudas.<br \/>\nTodos los tratamientos se realizan en hospitales de la CAM y los postoperatorios son llevados directamente por \u00e9l, contando los pacientes con su tel\u00e9fono personal para localizarle las 24horas del d\u00eda para su tranquilidad.<\/p>\n<p>El Dr Tom\u00e1s no trabaja para empresas comerciales o cl\u00ednicas franquicias, para asegurar una atenci\u00f3n rigurosa y los mejores est\u00e1ndares de calidad.<\/p>\n<p>El \u00e9xito del Dr Diego Tom\u00e1s en cirug\u00eda mamaria se basa en la resoluci\u00f3n de problemas de pr\u00f3tesis ya operados y en su enfoque quir\u00fargico basado en dar prioridad a la forma y no solo al volumen de las mamas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero<\/p>\n","protected":false},"author":1,"featured_media":3384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3383","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1766\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-10-26T03:46:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-10-26T03:46:38+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#listItem\",\"name\":\"El Dr. Diego Tom\\u00e1s Ivancich explica c\\u00f3mo puede ayudar el deporte antes y despu\\u00e9s de una intervenci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#listItem\",\"position\":3,\"name\":\"El Dr. Diego Tom\\u00e1s Ivancich explica c\\u00f3mo puede ayudar el deporte antes y despu\\u00e9s de una intervenci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#newsarticle\",\"name\":\"El Dr. Diego Tom\\u00e1s Ivancich explica c\\u00f3mo puede ayudar el deporte antes y despu\\u00e9s de una intervenci\\u00f3n | El Digital de Asturias\",\"headline\":\"El Dr. Diego Tom\\u00e1s Ivancich explica c\\u00f3mo puede ayudar el deporte antes y despu\\u00e9s de una intervenci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg\",\"width\":2560,\"height\":1766},\"datePublished\":\"2019-10-26T03:46:38+02:00\",\"dateModified\":\"2019-10-26T03:46:38+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el octubre 26, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/\",\"name\":\"El Dr. Diego Tom\\u00e1s Ivancich explica c\\u00f3mo puede ayudar el deporte antes y despu\\u00e9s de una intervenci\\u00f3n | El Digital de Asturias\",\"description\":\"Tras algunas intervenciones de cirug\\u00eda pl\\u00e1stica, como la mamoplastia, liposucci\\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\\u00e1s Ivancich, especialista en cirug\\u00eda pl\\u00e1stica, est\\u00e9tica y reparadora, explica c\\u00f3mo de importante es la pr\\u00e1ctica de deporte despu\\u00e9s, pero\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#mainImage\",\"width\":2560,\"height\":1766},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\\\/#mainImage\"},\"datePublished\":\"2019-10-26T03:46:38+02:00\",\"dateModified\":\"2019-10-26T03:46:38+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias","description":"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#listItem","name":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#listItem","position":3,"name":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#newsarticle","name":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias","headline":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg","width":2560,"height":1766},"datePublished":"2019-10-26T03:46:38+02:00","dateModified":"2019-10-26T03:46:38+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#webpage"},"articleSection":"Live","dateline":"Publicado el octubre 26, 2019."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/","name":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias","description":"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#mainImage","width":2560,"height":1766},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/#mainImage"},"datePublished":"2019-10-26T03:46:38+02:00","dateModified":"2019-10-26T03:46:38+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias","og:description":"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg","og:image:width":2560,"og:image:height":1766,"article:published_time":"2019-10-26T03:46:38+00:00","article:modified_time":"2019-10-26T03:46:38+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n | El Digital de Asturias","twitter:description":"Tras algunas intervenciones de cirug\u00eda pl\u00e1stica, como la mamoplastia, liposucci\u00f3n o abdominoplastia, los expertos recomiendan un mantenimiento del cuerpo, tanto mediante el deporte, como a trav\u00e9s de una dieta sana y equilibrada. El Dr Diego Tom\u00e1s Ivancich, especialista en cirug\u00eda pl\u00e1stica, est\u00e9tica y reparadora, explica c\u00f3mo de importante es la pr\u00e1ctica de deporte despu\u00e9s, pero","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/10\/1571903407_bruce_mars_HHXdPGeTIQ_unsp-scaled.jpg"},"aioseo_meta_data":{"post_id":"3383","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 23:18:06","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 20:31:19","updated":"2026-05-14 23:18:06"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"El Dr. Diego Tom\u00e1s Ivancich explica c\u00f3mo puede ayudar el deporte antes y despu\u00e9s de una intervenci\u00f3n","link":"https:\/\/eldigitaldeasturias.com\/radio\/el-dr-diego-tomas-ivancich-explica-como-puede-ayudar-el-deporte-antes-y-despues-de-una-intervencion\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/3383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=3383"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/3383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/3384"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=3383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=3383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=3383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}