{"id":3039,"date":"2019-08-06T15:13:22","date_gmt":"2019-08-06T15:13:22","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=3039"},"modified":"2019-08-06T15:13:22","modified_gmt":"2019-08-06T15:13:22","slug":"la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/","title":{"rendered":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3040\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720-768x512.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Colonia, 5 ago (dpa) &#8211; La jubilaci\u00f3n es a menudo un <strong>riesgo para la salud de las personas con ingresos elevados en Alemania<\/strong>, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy.<\/p>\n<p>Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.<\/p>\n<p>En la investigaci\u00f3n se analizaron los datos del seguro de pensiones alem\u00e1n para casi 800.000 jubilados que nacieron entre 1934 y 1936.<\/p>\n<p>El resultado del estudio se\u00f1ala que la jubilaci\u00f3n y los cambios dram\u00e1ticos que vienen asociados al ritmo cotidiano y a las relaciones sociales pueden afectar el \u00edndice de mortalidad de este grupo tanto en forma positiva como negativa.<\/p>\n<p>Los m\u00e1s favorecidos por el pase a retiro son los desempleados y los trabajadores con menores ingresos. Cuando se jubilan a los 63 a\u00f1os, desciende notablemente la tasa de mortalidad de este grupo.<\/p>\n<p>En tanto, los que pasan de desocupados a jubilados son los que m\u00e1s se benefician, porque dejan de cargar el estigma del desempleo, seg\u00fan se\u00f1ala el informe del RWI.<\/p>\n<p>Para los trabajadores de bajos ingresos, el hecho de que muchos de sus trabajos son f\u00edsicamente exigentes o implican riesgos en el lugar de trabajo es un factor importante. <strong>Estos riesgos y cargas se eliminan con la pensi\u00f3n<\/strong>.<\/p>\n<p>Seg\u00fan el estudio, la situaci\u00f3n es muy diferente entre las personas con mayores ingresos, ya sean hombres o mujeres, que se jubilan a los 65 a\u00f1os. En este caso, la mortalidad aumenta de forma apreciable con la jubilaci\u00f3n.<\/p>\n<p>\u00abPara ellos, el aislamiento social en la edad de jubilaci\u00f3n est\u00e1 probablemente en el primer plano, porque tambi\u00e9n pierden prestigio en su profesi\u00f3n y en sus redes sociales\u00bb, apunt\u00f3 Matthias Giesecke, autor del estudio, al explicar la tendencia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colonia, 5 ago (dpa) &#8211; La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.<\/p>\n","protected":false},"author":1,"featured_media":3040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3039","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-08-06T15:13:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-06T15:13:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#listItem\",\"name\":\"La jubilaci\\u00f3n es riesgo de salud para quienes ganan m\\u00e1s en Alemania\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#listItem\",\"position\":3,\"name\":\"La jubilaci\\u00f3n es riesgo de salud para quienes ganan m\\u00e1s en Alemania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#newsarticle\",\"name\":\"La jubilaci\\u00f3n es riesgo de salud para quienes ganan m\\u00e1s en Alemania | El Digital de Asturias\",\"headline\":\"La jubilaci\\u00f3n es riesgo de salud para quienes ganan m\\u00e1s en Alemania\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/hands-981400_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2019-08-06T15:13:22+02:00\",\"dateModified\":\"2019-08-06T15:13:22+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el agosto 6, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/\",\"name\":\"La jubilaci\\u00f3n es riesgo de salud para quienes ganan m\\u00e1s en Alemania | El Digital de Asturias\",\"description\":\"Colonia, 5 ago (dpa) - La jubilaci\\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\\u00fan revela un estudio del Instituto de Investigaci\\u00f3n Econ\\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\\u00f3n, sostiene el estudio.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/hands-981400_960_720.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\\\/#mainImage\"},\"datePublished\":\"2019-08-06T15:13:22+02:00\",\"dateModified\":\"2019-08-06T15:13:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias","description":"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#listItem","name":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#listItem","position":3,"name":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#newsarticle","name":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias","headline":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg","width":960,"height":640},"datePublished":"2019-08-06T15:13:22+02:00","dateModified":"2019-08-06T15:13:22+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#webpage"},"articleSection":"Live","dateline":"Publicado el agosto 6, 2019."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/","name":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias","description":"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/#mainImage"},"datePublished":"2019-08-06T15:13:22+02:00","dateModified":"2019-08-06T15:13:22+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias","og:description":"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2019-08-06T15:13:22+00:00","article:modified_time":"2019-08-06T15:13:22+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania | El Digital de Asturias","twitter:description":"Colonia, 5 ago (dpa) - La jubilaci\u00f3n es a menudo un riesgo para la salud de las personas con ingresos elevados en Alemania, seg\u00fan revela un estudio del Instituto de Investigaci\u00f3n Econ\u00f3mica (RWI) de Essen publicado hoy. Los desempleados y los hombres de bajos ingresos, en cambio, suelen beneficiarse de esta prestaci\u00f3n, sostiene el estudio.","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/08\/hands-981400_960_720.jpg"},"aioseo_meta_data":{"post_id":"3039","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 22:39:09","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 22:44:44","updated":"2026-05-14 22:39:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"La jubilaci\u00f3n es riesgo de salud para quienes ganan m\u00e1s en Alemania","link":"https:\/\/eldigitaldeasturias.com\/radio\/la-jubilacion-es-riesgo-de-salud-para-quienes-ganan-mas-en-alemania\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/3039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=3039"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/3039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/3040"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=3039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=3039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=3039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}