{"id":2866,"date":"2019-07-21T00:14:22","date_gmt":"2019-07-21T00:14:22","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=2866"},"modified":"2019-07-21T00:14:22","modified_gmt":"2019-07-21T00:14:22","slug":"los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/","title":{"rendered":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a"},"content":{"rendered":"<div id=\"texto\" class=\"flex mb15\">\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2867\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete-768x509.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>En el \u00faltimo a\u00f1o el uso del\u00a0<a href=\"https:\/\/ipatineteelectrico.com\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #ff6600;\"><strong>patinete el\u00e9ctrico<\/strong><\/span><\/a>\u00a0ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema que tambi\u00e9n se han expandido a otros sitios del mundo como en Par\u00eds donde en la capital francesa han empezado a prohibir aparcarlos en las calles debido a la gran multitud de ellos.<\/p>\n<p>Esta es una nueva moda que est\u00e1 para quedarse ya que cada vez se ven m\u00e1s patinetes el\u00e9ctricos por las calles de todas las ciudades espa\u00f1olas. Aun as\u00ed, todav\u00eda queda un paso para que esto sea una constante y esa ser\u00e1 la aprobaci\u00f3n de la normativa impuesta por la Direcci\u00f3n General de Tr\u00e1fico para la cual regular\u00e1 el uso del veh\u00edculo. Algunas de los elementos principales son que no podr\u00e1n superar los 25 kil\u00f3metros\/hora, no podr\u00e1n estar por las aceras, se prohibir\u00e1 su uso con cascos puestos o estar bajo los efectos del alcohol.<\/p>\n<p><strong>\u201cLa gente est\u00e1 cada vez m\u00e1s c\u00f3moda con los patinetes y eso se nota en las ventas que cada vez son mayores\u201d<\/strong><\/p>\n<p>Seg\u00fan la DGT habr\u00e1 en torno de 100.000 patinetes el\u00e9ctricos en Espa\u00f1a y es un mercado en auge debido a que las ventas cada vez son mayores. Uno de las empresas que llevan este tipo de mercado es iPatines el\u00e9ctrico, para ello se ha podido contar con la declaraci\u00f3n de \u00c1lvaro L\u00f3pez Parra ,jefe de la empresa: \u201cLa gente est\u00e1 cada vez m\u00e1s c\u00f3moda con los patinetes y eso se nota en las ventas que cada vez son mayores.\u201d, dec\u00eda con una sonrisa.<\/p>\n<p><strong>Los peligros del patinete el\u00e9ctrico llegan a las carreteras espa\u00f1olas<\/strong><\/p>\n<p>Pero el problema ha llegado al punto que en las \u00faltimas semanas dos personas han utilizado dichos patinetes en las carreteras de algunas ciudades espa\u00f1olas como Zaragoza, donde se avist\u00f3 a un hombre utiliz\u00e1ndolo mientras llevaba unos cascos en una zona prohibida para su utilizaci\u00f3n. Cada vez es m\u00e1s normal ver estas situaciones y hace que sea un peligro para los propios conductores ya que los coches van a velocidades donde un golpe podr\u00eda llegar a ser mortal. Las multas de estas infracciones podr\u00edan llegar hasta los 200 euros.<\/p>\n<p>Uno de los sectores m\u00e1s enfadados son los ciclistas los cuales tiene que compartir ahora el mismo carril que con los patinetes. Esto no ha gustado ya que tendr\u00e1n menos espacio por el cual circular por las ciudades, algo ya complicado por s\u00ed por el espacio que tienen para circular.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div id=\"datos_extra\" class=\"clearblock\">\n<div id=\"datos_contacto\" class=\"g6 flex\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el \u00faltimo a\u00f1o el uso del\u00a0patinete el\u00e9ctrico\u00a0ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema<\/p>\n","protected":false},"author":1,"featured_media":2867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2866","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-21T00:14:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-21T00:14:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#listItem\",\"name\":\"Los patinetes el\\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\\u00f1a\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#listItem\",\"position\":3,\"name\":\"Los patinetes el\\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\\u00f1a\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#newsarticle\",\"name\":\"Los patinetes el\\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\\u00f1a | El Digital de Asturias\",\"headline\":\"Los patinetes el\\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\\u00f1a\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/1562920097_Patinete.jpg\",\"width\":800,\"height\":530},\"datePublished\":\"2019-07-21T00:14:22+02:00\",\"dateModified\":\"2019-07-21T00:14:22+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el julio 21, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/\",\"name\":\"Los patinetes el\\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\\u00f1a | El Digital de Asturias\",\"description\":\"En el \\u00faltimo a\\u00f1o el uso del patinete el\\u00e9ctrico ha sido uno de los temas m\\u00e1s comentados en Espa\\u00f1a debido a que cada vez hay m\\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\\u00edan las normativas. Un problema\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/1562920097_Patinete.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#mainImage\",\"width\":800,\"height\":530},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\\\/#mainImage\"},\"datePublished\":\"2019-07-21T00:14:22+02:00\",\"dateModified\":\"2019-07-21T00:14:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias","description":"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#listItem","name":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#listItem","position":3,"name":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#newsarticle","name":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias","headline":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg","width":800,"height":530},"datePublished":"2019-07-21T00:14:22+02:00","dateModified":"2019-07-21T00:14:22+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#webpage"},"articleSection":"Live","dateline":"Publicado el julio 21, 2019."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/","name":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias","description":"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#mainImage","width":800,"height":530},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/#mainImage"},"datePublished":"2019-07-21T00:14:22+02:00","dateModified":"2019-07-21T00:14:22+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias","og:description":"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg","og:image:width":800,"og:image:height":530,"article:published_time":"2019-07-21T00:14:22+00:00","article:modified_time":"2019-07-21T00:14:22+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a | El Digital de Asturias","twitter:description":"En el \u00faltimo a\u00f1o el uso del patinete el\u00e9ctrico ha sido uno de los temas m\u00e1s comentados en Espa\u00f1a debido a que cada vez hay m\u00e1s por las calles, llegando al punto que hace unos meses se prohibi\u00f3 el uso de las empresas que las alquilaban en Madrid debido a que no cumpl\u00edan las normativas. Un problema","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/07\/1562920097_Patinete.jpg"},"aioseo_meta_data":{"post_id":"2866","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 22:19:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 13:39:56","updated":"2026-05-14 22:19:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLos patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"Los patinetes el\u00e9ctricos a una normativa de llegar a los 100.000 en Espa\u00f1a","link":"https:\/\/eldigitaldeasturias.com\/radio\/los-patinetes-electricos-a-una-normativa-de-llegar-a-los-100-000-en-espana\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=2866"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/2867"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=2866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=2866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=2866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}