{"id":2715,"date":"2019-05-30T15:51:54","date_gmt":"2019-05-30T15:51:54","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=2715"},"modified":"2025-07-10T05:03:44","modified_gmt":"2025-07-10T03:03:44","slug":"un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/","title":{"rendered":"Un toque crujiente para los c\u00f3cteles de verano con Joe&#038;Seph&#8217;s"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2716\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg 400w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los\u00a0<em>cocktail bars\u00a0<\/em>ofrezcan peque\u00f1os\u00a0<em>snacks\u00a0<\/em>salados como frutos secos o patatas fritas para acompa\u00f1ar las bebidas. Sin embargo,\u00a0<strong>Joe&amp;Seph\u2019s\u00a0<\/strong>propone una manera mucho m\u00e1s original, rica y sabrosa de hacerlo con sus exclusivas palomitas gourmet.<\/p>\n<p>\u00bfUn punto ex\u00f3tico y sorprendente? Para aquellos paladares m\u00e1s exigentes que buscan nuevas experiencias sensoriales est\u00e1 la variedad\u00a0<strong>Thai Sweet Chili<\/strong>, en la que las palomitas se infusionan con especies orientales delicadas y un acabado dulce de pimiento chili. Esta opci\u00f3n de sabor de estilo tailand\u00e9s puede combinar perfectamente con aquellas bebidas que quiz\u00e1s necesitan ese aporte extra de sabor placentero para los sentidos.<\/p>\n<p>En cambio, los amantes de los c\u00f3cteles m\u00e1s dulces como el m\u00edtico Pi\u00f1a Colada, encontrar\u00e1n el acompa\u00f1ante perfecto en la variedad\u00a0<strong>Coconut &amp; Chia Seed<\/strong>, que combina coco desecado con crujientes semillas de ch\u00eda. \u00a1Viajar a una isla tropical bocado tras bocado y desde lo alto de una terraza nunca hab\u00eda sido tan f\u00e1cil!<\/p>\n<p><em>Hand-made<\/em><strong>\u00a0ingl\u00e9s<\/strong><\/p>\n<p>Las palomitas Joe&amp;Seph\u2019s est\u00e1n hechas a mano en Inglaterra por un peque\u00f1o equipo de chefs.<\/p>\n<p>Utilizan el mejor ma\u00edz del mercado y lo inflan con aire, proceso m\u00e1s saludable que el frito y consiguiendo granos extragrandes con una mejor textura y sabor. Para ello, usan los mejores ingredientes naturales.<\/p>\n<p>Esta t\u00e9cnica \u00fanica permite que el sabor se vaya descubriendo a medida que se mastica la palomita. En la actualidad, Joe&amp;Seph\u2019s cuenta con\u00a0<strong>m\u00e1s de 60 variedades<\/strong>\u00a0de sabores dulces y salados, y se encuentran continuamente desarrollando nuevas propuestas innovadoras para el paladar. La marca tambi\u00e9n comercializa sus m\u00e1s de 10 exclusivas salsas con las que ba\u00f1a sus palomitas para a\u00f1adir un toque de sabor a cualquier plato que se desee.<\/p>\n<p>Entre sus\u00a0<em>top sellers<\/em>\u00a0est\u00e1n las de queso de cabra y pimienta,\u00a0<em>Gin&amp;tonic<\/em>, caramelo y sal, chocolate belga y manzana con\u00a0<em>toffee<\/em>\u00a0y canela. Sus exquisitas creaciones han llevado a Joe&amp;Seph\u2019s a ganar m\u00e1s de 40 premios Great Taste Awards.<\/p>\n<p>Joe&amp;Seph\u2019s se distribuye en exclusiva en Espa\u00f1a a trav\u00e9s de Berenpop S.L.<\/p>\n<p>www.joeandsephs.co.uk www.berenpop.es<\/p>\n<p><strong>IG<\/strong>: @beren.pop<\/p>\n<p><strong>FB<\/strong>: Beren.pop<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los\u00a0cocktail bars\u00a0ofrezcan peque\u00f1os\u00a0snacks\u00a0salados como frutos secos o patatas fritas para<\/p>\n","protected":false},"author":1,"featured_media":2716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144,38],"tags":[],"class_list":["post-2715","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gastronomia","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"gastronom\u00eda,live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Un toque crujiente para los c\u00f3cteles de verano con Joe&amp;Seph\u2019s | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-30T15:51:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-10T03:03:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Un toque crujiente para los c\u00f3cteles de verano con Joe&amp;Seph\u2019s | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#listItem\",\"name\":\"Un toque crujiente para los c\\u00f3cteles de verano con Joe&#038;Seph&#8217;s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#listItem\",\"position\":3,\"name\":\"Un toque crujiente para los c\\u00f3cteles de verano con Joe&#038;Seph&#8217;s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#newsarticle\",\"name\":\"Un toque crujiente para los c\\u00f3cteles de verano con Joe&Seph\\u2019s | El Digital de Asturias\",\"headline\":\"Un toque crujiente para los c\\u00f3cteles de verano con Joe&#038;Seph&#8217;s\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/1559216568_IMG8418_opt.jpg\",\"width\":400,\"height\":267},\"datePublished\":\"2019-05-30T15:51:54+02:00\",\"dateModified\":\"2025-07-10T05:03:44+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#webpage\"},\"articleSection\":\"Gastronom\\u00eda, Live\",\"dateline\":\"Publicado el mayo 30, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/\",\"name\":\"Un toque crujiente para los c\\u00f3cteles de verano con Joe&Seph\\u2019s | El Digital de Asturias\",\"description\":\"La temporada de terrazas al aire libre ya est\\u00e1 aqu\\u00ed, y ahora que los d\\u00edas se van alargando, resulta m\\u00e1s y m\\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\\u00f3cteles, buena m\\u00fasica, y mejor compa\\u00f1\\u00eda. Hablando de compa\\u00f1\\u00eda, lo m\\u00e1s com\\u00fan es que en los cocktail bars ofrezcan peque\\u00f1os snacks salados como frutos secos o patatas fritas para\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/1559216568_IMG8418_opt.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#mainImage\",\"width\":400,\"height\":267},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\\\/#mainImage\"},\"datePublished\":\"2019-05-30T15:51:54+02:00\",\"dateModified\":\"2025-07-10T05:03:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Un toque crujiente para los c\u00f3cteles de verano con Joe&amp;Seph\u2019s | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Un toque crujiente para los c\u00f3cteles de verano con Joe&Seph\u2019s | El Digital de Asturias","description":"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/","robots":"max-image-preview:large","keywords":"gastronom\u00eda,live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#listItem","name":"Un toque crujiente para los c\u00f3cteles de verano con Joe&#038;Seph&#8217;s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#listItem","position":3,"name":"Un toque crujiente para los c\u00f3cteles de verano con Joe&#038;Seph&#8217;s","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#newsarticle","name":"Un toque crujiente para los c\u00f3cteles de verano con Joe&Seph\u2019s | El Digital de Asturias","headline":"Un toque crujiente para los c\u00f3cteles de verano con Joe&#038;Seph&#8217;s","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg","width":400,"height":267},"datePublished":"2019-05-30T15:51:54+02:00","dateModified":"2025-07-10T05:03:44+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#webpage"},"articleSection":"Gastronom\u00eda, Live","dateline":"Publicado el mayo 30, 2019."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/","name":"Un toque crujiente para los c\u00f3cteles de verano con Joe&Seph\u2019s | El Digital de Asturias","description":"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#mainImage","width":400,"height":267},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/#mainImage"},"datePublished":"2019-05-30T15:51:54+02:00","dateModified":"2025-07-10T05:03:44+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Un toque crujiente para los c\u00f3cteles de verano con Joe&amp;Seph\u2019s | El Digital de Asturias","og:description":"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg","og:image:width":400,"og:image:height":267,"article:published_time":"2019-05-30T15:51:54+00:00","article:modified_time":"2025-07-10T03:03:44+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Un toque crujiente para los c\u00f3cteles de verano con Joe&amp;Seph\u2019s | El Digital de Asturias","twitter:description":"La temporada de terrazas al aire libre ya est\u00e1 aqu\u00ed, y ahora que los d\u00edas se van alargando, resulta m\u00e1s y m\u00e1s apetecible relajarse y disfrutar en veladas tranquilas con c\u00f3cteles, buena m\u00fasica, y mejor compa\u00f1\u00eda. Hablando de compa\u00f1\u00eda, lo m\u00e1s com\u00fan es que en los cocktail bars ofrezcan peque\u00f1os snacks salados como frutos secos o patatas fritas para","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2019\/05\/1559216568_IMG8418_opt.jpg"},"aioseo_meta_data":{"post_id":"2715","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 22:04:16","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 22:58:19","updated":"2026-05-14 22:04:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tUn toque crujiente para los c\u00f3cteles de verano con Joe&amp;Seph\u2019s\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"Un toque crujiente para los c\u00f3cteles de verano con Joe&#038;Seph&#8217;s","link":"https:\/\/eldigitaldeasturias.com\/radio\/un-toque-crujiente-para-los-cocteles-de-verano-con-joesephs\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=2715"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/2716"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=2715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=2715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=2715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}