{"id":2041,"date":"2018-11-24T18:07:07","date_gmt":"2018-11-24T18:07:07","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=2041"},"modified":"2018-11-24T18:08:31","modified_gmt":"2018-11-24T18:08:31","slug":"diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/","title":{"rendered":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar"},"content":{"rendered":"<figure id=\"attachment_2042\" aria-describedby=\"caption-attachment-2042\" style=\"width: 198px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2042\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar-198x300.jpg\" alt=\"\" width=\"198\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar-198x300.jpg 198w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg 447w\" sizes=\"(max-width: 198px) 100vw, 198px\" \/><figcaption id=\"caption-attachment-2042\" class=\"wp-caption-text\">Foto: Franziska Gabbert\/dpa-tmn<\/figcaption><\/figure>\n<p>(dpa) &#8211; Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados.<\/p>\n<p>En el caso de personas con diabetes tipo dos, el tipo de diabetes m\u00e1s frecuente, el cuerpo produce insulina, que baja el nivel de az\u00facar, pero esta ya no tiene el efecto adecuado en las c\u00e9lulas. Esta llamada resistencia a la insulina puede producir que los \u00f3rganos acumulen grasa.<\/p>\n<p>Si las personas con diabetes tipo dos pierden peso y se mueven m\u00e1s, pueden impulsar la quema de grasas, lo cual hace que los \u00f3rganos y m\u00fasculos respondan mejor a la insulina. Los medicamentos solo se recomiendan cuando el cambio de estilo de vida no surte efecto.<\/p>\n<p>De acuerdo con un estudio brit\u00e1nico, quien pierde al menos 15 kilos en los seis a\u00f1os posteriores tras recibir el diagn\u00f3stico de diabetes tiene mejores posibilidades.<\/p>\n<p>Una de las formas m\u00e1s simples y efectivas de perder peso es con una dieta a base de f\u00f3rmulas o polvos diet\u00e9ticos con las que se reemplazan parcial o totalmente comidas. Todo esto, por supuesto, con supervisi\u00f3n m\u00e9dica.<\/p>\n<p>Lo m\u00e1s dif\u00edcil es, de todas formas, mantener luego el peso. Por eso, es importante el asesoramiento m\u00e9dico y hacer una dieta que permita no sufrir un efecto rebote. Tambi\u00e9n es ideal que la familia acompa\u00f1e: es muy dif\u00edcil mantener una alimentaci\u00f3n sana cuando otros no lo hacen. Y de paso se beneficia toda la familia.<\/p>\n<p>El movimiento es importante para perder peso pero no masa muscular. En grupo es adem\u00e1s m\u00e1s f\u00e1cil de sostener. Por eso, lo ideal es buscar un grupo con el que salir a caminar, por ejemplo, o hacer cualquier otra actividad grupal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso<\/p>\n","protected":false},"author":1,"featured_media":2042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2041","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"447\" \/>\n\t\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-24T18:07:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-24T18:08:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#listItem\",\"name\":\"Diabetes tipo dos: consejos para mejorar los niveles de az\\u00facar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#listItem\",\"position\":3,\"name\":\"Diabetes tipo dos: consejos para mejorar los niveles de az\\u00facar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#newsarticle\",\"name\":\"Diabetes tipo dos: consejos para mejorar los niveles de az\\u00facar | El Digital de Asturias\",\"headline\":\"Diabetes tipo dos: consejos para mejorar los niveles de az\\u00facar\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/consejos-para-mejorar-los-niveles-de-az\\u00facar.jpg\",\"width\":447,\"height\":676,\"caption\":\"Foto: Franziska Gabbert\\\/dpa-tmn\"},\"datePublished\":\"2018-11-24T18:07:07+01:00\",\"dateModified\":\"2018-11-24T18:08:31+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el noviembre 24, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/\",\"name\":\"Diabetes tipo dos: consejos para mejorar los niveles de az\\u00facar | El Digital de Asturias\",\"description\":\"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\\u00f3n y movi\\u00e9ndose m\\u00e1s. Los especialistas afirman que los diab\\u00e9ticos con sobrepeso son los primeros que deber\\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\\u00e1s est\\u00e1n estrechamente ligados. En el caso\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/consejos-para-mejorar-los-niveles-de-az\\u00facar.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#mainImage\",\"width\":447,\"height\":676,\"caption\":\"Foto: Franziska Gabbert\\\/dpa-tmn\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\\\/#mainImage\"},\"datePublished\":\"2018-11-24T18:07:07+01:00\",\"dateModified\":\"2018-11-24T18:08:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias","description":"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#listItem","name":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#listItem","position":3,"name":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#newsarticle","name":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias","headline":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg","width":447,"height":676,"caption":"Foto: Franziska Gabbert\/dpa-tmn"},"datePublished":"2018-11-24T18:07:07+01:00","dateModified":"2018-11-24T18:08:31+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#webpage"},"articleSection":"Live","dateline":"Publicado el noviembre 24, 2018."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/","name":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias","description":"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#mainImage","width":447,"height":676,"caption":"Foto: Franziska Gabbert\/dpa-tmn"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/#mainImage"},"datePublished":"2018-11-24T18:07:07+01:00","dateModified":"2018-11-24T18:08:31+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias","og:description":"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg","og:image:width":447,"og:image:height":676,"article:published_time":"2018-11-24T18:07:07+00:00","article:modified_time":"2018-11-24T18:08:31+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar | El Digital de Asturias","twitter:description":"(dpa) - Las personas con diabetes tipo 2 tienen buenas posibilidades de revertir su enfermedad cambiando su alimentaci\u00f3n y movi\u00e9ndose m\u00e1s. Los especialistas afirman que los diab\u00e9ticos con sobrepeso son los primeros que deber\u00edan intentar perder unos kilos, ya que la diabetes tipo dos y los kilos de m\u00e1s est\u00e1n estrechamente ligados. En el caso","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/consejos-para-mejorar-los-niveles-de-az\u00facar.jpg"},"aioseo_meta_data":{"post_id":"2041","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 20:49:19","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 15:36:35","updated":"2026-05-14 20:49:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDiabetes tipo dos: consejos para mejorar los niveles de az\u00facar\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"Diabetes tipo dos: consejos para mejorar los niveles de az\u00facar","link":"https:\/\/eldigitaldeasturias.com\/radio\/diabetes-tipo-dos-consejos-para-mejorar-los-niveles-de-azucar\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=2041"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/2042"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=2041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=2041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=2041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}