{"id":2010,"date":"2018-11-24T04:16:18","date_gmt":"2018-11-24T04:16:18","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=2010"},"modified":"2018-11-24T04:16:18","modified_gmt":"2018-11-24T04:16:18","slug":"las-varices-todo-lo-que-debes-saber","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/","title":{"rendered":"Las varices: Todo lo que debes saber"},"content":{"rendered":"<figure id=\"attachment_2011\" aria-describedby=\"caption-attachment-2011\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2011\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices-360x257.jpg\" alt=\"\" width=\"360\" height=\"257\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices-360x257.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices-768x548.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg 937w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-2011\" class=\"wp-caption-text\">Foto: Andrea Warnecke\/dpa-tmn<\/figcaption><\/figure>\n<p>(dpa) &#8211; Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo.<\/p>\n<p>Los problemas en las venas son un mal muy generalizado. La versi\u00f3n m\u00e1s \u00ableve\u00bb son las venitas que asoman en la superficie de la piel ramificadas. \u00abSuelen ser s\u00f3lo un problema est\u00e9tico\u00bb, explica el cirujano Thomas Noppeney. Hay muy pocos casos en los que se convierten en un verdadero problema.<\/p>\n<p>Las v\u00e1rices tampoco son necesariamente un gran problema de salud, pero con el tiempo eso puede llegar a cambiar. Cuanto antes uno las aborde con un tratamiento, mejor, porque \u00abson una indicaci\u00f3n de que las venas no est\u00e1n bien\u00bb, comenta el Dr. Lothar Br\u00fcmmer, especialista en el tema.<\/p>\n<p>Las venas transportan sangre al coraz\u00f3n yendo en contra de la fuerza de gravedad. Tienen unas \u00abtapitas\u00bb que se encargan de que la sangre no fluya hacia abajo. Si esas \u00abtapitas\u00bb dejan de funcionar al cien por cien y no se cierran por completo, la sangre se acumula en las piernas y, en consecuencia, forma v\u00e1rices.<\/p>\n<p>Si uno detecta y trata el problema en una etapa temprana, puede llegar a generar una diferencia consumiendo las pastillas adecuadas. \u00abSe trata de extractos vegetales que pueden comprarse sin receta\u00bb, comenta la farmac\u00e9utica Ursula Sellerberg de Alemania. \u00abEl efecto suele verse despu\u00e9s de varias semanas\u00bb, advierte. En las farmacias tambi\u00e9n venden cremas especiales para las venas, pero esos ung\u00fcentos por lo general s\u00f3lo tienen un efecto refrescante, que alivia y cuida la zona, pero no trata el problema.<\/p>\n<p>Si las pastillas y los ung\u00fcentos no generan mayor cambio o si los s\u00edntomas empeoran con el tiempo, es bueno recurrir a un fleb\u00f3logo o a un cirujano especializado, porque si uno no trata el problema puede que comience a tener dolores o incluso \u00falceras y trombosis.<\/p>\n<p>El m\u00e9dico suele evaluar el estado de las venas con ayuda de una ecograf\u00eda. A veces es suficiente con que el paciente use medias que le compriman las piernas. En otros casos el m\u00e9dico decide inyectar l\u00edquido en las venas para obturarlas y de ese modo eliminarlas. Lo que se busca por esta v\u00eda es evitar complicaciones y mejorar la est\u00e9tica, pero nada garantiza que no aparezcan v\u00e1rices nuevas.<\/p>\n<p>Otro modo de tratarlas es con terapia l\u00e1ser. Los rayos l\u00e1ser recalientan las paredes de las venas y hacen que el conducto se contraiga y se cierre. Si las v\u00e1rices son grandes y dolorosas, es posible retirar las partes m\u00e1s da\u00f1adas con un procedimiento que se conoce como safenectom\u00eda (\u00abstripping\u00bb en ingl\u00e9s).<\/p>\n<p>\u00abLo importante es decirles todo a los pacientes, y comentarles desde un primer momento que es posible que algunos a\u00f1os despu\u00e9s de la intervenci\u00f3n las v\u00e1rices vuelvan a aparecer\u00bb, advierte Noppeney. La reaparici\u00f3n o no del problema depende en cierta medida del estilo de vida. Si uno pasa muchas horas sentado o de pie en el trabajo, corre m\u00e1s peligro de que la sangre se estanque en las venas. El sobrepeso tambi\u00e9n es un gran problema.<\/p>\n<p>De todos modos, no es que podamos solucionar todo cambiando nuestro modo de vida. Tambi\u00e9n hay casos definidos por la gen\u00e9tica. Las mujeres suelen verse m\u00e1s afectadas por las v\u00e1rices que los hombres. \u00abHasta hoy no se tienen pruebas cient\u00edficas claras de por qu\u00e9 es as\u00ed\u00bb, comenta Noppeney.<\/p>\n<p>Si uno quiere hacer algo para prevenir este problema, lo mejor que pude hacer es poner las piernas a menudo en alto. \u00abIncluso cuando uno est\u00e1 mucho tiempo sentado o de pie puede mover los pies de vez en cuando. Eso ya ayuda a evitar que la sangre se estanque\u00bb, comenta Sellerberg.<\/p>\n<p>Hacer deportes tambi\u00e9n resulta muy favorable. Y cuando uno se ducha, antes de terminar, es muy bueno darles a las piernas un golpe de agua fr\u00eda. Tamb\u00eden hace muy bien beber mucho l\u00edquido. Dos litros al d\u00eda es lo ideal. No vale cualquier l\u00edquido. Debe ser agua o alg\u00fan t\u00e9 sin az\u00facar.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Sabine Meuter (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en<\/p>\n","protected":false},"author":1,"featured_media":2011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2010","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las varices: Todo lo que debes saber | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"937\" \/>\n\t\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-24T04:16:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-24T04:16:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las varices: Todo lo que debes saber | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#listItem\",\"name\":\"Las varices: Todo lo que debes saber\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#listItem\",\"position\":3,\"name\":\"Las varices: Todo lo que debes saber\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#newsarticle\",\"name\":\"Las varices: Todo lo que debes saber | El Digital de Asturias\",\"headline\":\"Las varices: Todo lo que debes saber\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/varices.jpg\",\"width\":937,\"height\":668,\"caption\":\"Foto: Andrea Warnecke\\\/dpa-tmn\"},\"datePublished\":\"2018-11-24T04:16:18+01:00\",\"dateModified\":\"2018-11-24T04:16:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el noviembre 24, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/\",\"name\":\"Las varices: Todo lo que debes saber | El Digital de Asturias\",\"description\":\"(dpa) - Las v\\u00e1rices no son un inconveniente meramente est\\u00e9tico, tambi\\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\\u00e1rices s\\u00ed pueden llegar a serlo. Los problemas en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/varices.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#mainImage\",\"width\":937,\"height\":668,\"caption\":\"Foto: Andrea Warnecke\\\/dpa-tmn\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/las-varices-todo-lo-que-debes-saber\\\/#mainImage\"},\"datePublished\":\"2018-11-24T04:16:18+01:00\",\"dateModified\":\"2018-11-24T04:16:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las varices: Todo lo que debes saber | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Las varices: Todo lo que debes saber | El Digital de Asturias","description":"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#listItem","name":"Las varices: Todo lo que debes saber"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#listItem","position":3,"name":"Las varices: Todo lo que debes saber","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#newsarticle","name":"Las varices: Todo lo que debes saber | El Digital de Asturias","headline":"Las varices: Todo lo que debes saber","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg","width":937,"height":668,"caption":"Foto: Andrea Warnecke\/dpa-tmn"},"datePublished":"2018-11-24T04:16:18+01:00","dateModified":"2018-11-24T04:16:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#webpage"},"articleSection":"Live","dateline":"Publicado el noviembre 24, 2018."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/","name":"Las varices: Todo lo que debes saber | El Digital de Asturias","description":"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#mainImage","width":937,"height":668,"caption":"Foto: Andrea Warnecke\/dpa-tmn"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/#mainImage"},"datePublished":"2018-11-24T04:16:18+01:00","dateModified":"2018-11-24T04:16:18+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Las varices: Todo lo que debes saber | El Digital de Asturias","og:description":"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg","og:image:width":937,"og:image:height":668,"article:published_time":"2018-11-24T04:16:18+00:00","article:modified_time":"2018-11-24T04:16:18+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Las varices: Todo lo que debes saber | El Digital de Asturias","twitter:description":"(dpa) - Las v\u00e1rices no son un inconveniente meramente est\u00e9tico, tambi\u00e9n pueden generarnos ciertos problemas de salud. Las venitas peque\u00f1as llegan a verse azules en la zona de los pies y de las piernas no son lo mismo. Esas no son tanto problema. En cambio las v\u00e1rices s\u00ed pueden llegar a serlo. Los problemas en","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/varices.jpg"},"aioseo_meta_data":{"post_id":"2010","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 20:45:21","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 18:54:02","updated":"2026-05-14 20:45:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLas varices: Todo lo que debes saber\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"Las varices: Todo lo que debes saber","link":"https:\/\/eldigitaldeasturias.com\/radio\/las-varices-todo-lo-que-debes-saber\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=2010"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/2010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/2011"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=2010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=2010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=2010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}