{"id":1710,"date":"2018-11-01T02:11:41","date_gmt":"2018-11-01T02:11:41","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=1710"},"modified":"2018-11-01T02:11:41","modified_gmt":"2018-11-01T02:11:41","slug":"eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/","title":{"rendered":"Eider S\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\u00fas, como la lista de la compra&#8217;"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-1711\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg 400w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los efectos negativos de la comida r\u00e1pida?<\/p>\n<p>Este tipo de comida se caracteriza por carecer de valor nutritivo y aportar alta densidad cal\u00f3rica. En palabras de Eider S\u00e1nchez, nutricionista de Policl\u00ednica Gipuzkoa,\u00a0<strong>\u201cson alimentos que carecen de valor nutritivo, ya que son pobres a nivel nutricional, est\u00e1n repletos de aditivos, suelen ser ricos en az\u00facares, sal y grasas de mala calidad, como las grasas hidrogenadas y grasas saturadas\u201d.<\/strong>\u00a0Adem\u00e1s, debido a que suelen contener potenciadores de sabor, son alimentos que crean adicci\u00f3n.<\/p>\n<p>Si se consumen de forma continua, adem\u00e1s de crear malos h\u00e1bitos alimenticios y situaciones de d\u00e9ficits nutricionales, como falta de vitaminas y minerales, pueden llegar a ser todo un riesgo para la salud. Seg\u00fan la especialista, \u201cla comida r\u00e1pida puede llegar a causar enfermedades tales como la obesidad, diabetes, enfermedades cardiovasculares, hipertensi\u00f3n arterial, arteroesclerosis, etc. Tambi\u00e9n dislipemias como hipercolesterolemia o hipertrigliceridema, trastornos digestivos, y trastornos renales y hep\u00e1ticos\u201d.<\/p>\n<p>El estilo de vida tan fren\u00e9tico puede estar relacionado con el consumo, cada vez m\u00e1s frecuente, de la comida r\u00e1pida. Sin embargo, la nutricionista indica que \u201cno debemos ponernos excusas a la hora de alimentarnos de forma adecuada\u201d. A\u00f1ade que \u201cpara comer saludable no hace falta invertir mucho tiempo. Las personas que recurren a fre\u00edrse unas croquetas, tardar\u00edan el mismo tiempo en prepararse cualquier comida saludable, como una ensalada, verdura o pescado a la plancha, y adem\u00e1s, ahorrar\u00edan dinero\u201d.\u00a0<strong>S\u00e1nchez subraya que \u201ca diferencia de otros pa\u00edses como Inglaterra o Estados Unidos, aqu\u00ed el consumo de este tipo de comidas se reserva m\u00e1s para el fin de semana, curiosamente donde menos prisas tenemos y m\u00e1s relajados estamos\u201d.<\/strong>\u00a0As\u00ed, el consumo de comida r\u00e1pida podr\u00eda estar m\u00e1s asociado a h\u00e1bitos de alimentaci\u00f3n o apetencias, m\u00e1s que a la falta de tiempo.<\/p>\n<p>En Espa\u00f1a, el 61% de la poblaci\u00f3n adulta sufre sobrepeso u obesidad, de las cuales el 39% tienen sobrepeso y el 22% son obsesas. Sin embargo,\u00a0<strong>Euskadi ser\u00eda la tercera comunidad con una tasa de prevalencia m\u00e1s baja en el Estado, ya que la tasa de obesidad se sit\u00faa en un 16,1%.<\/strong>\u00a0La nutricionista se\u00f1ala que para alimentarse de forma sana y prevenir enfermedades como la obesidad hay que cambiar los h\u00e1bitos: \u201cnecesitamos una educaci\u00f3n nutricional, que la poblaci\u00f3n aprenda a comer de forma saludable. Para ello, tambi\u00e9n hay que llevar un estilo de vida saludable, con una correcta actividad f\u00edsica y una correcta alimentaci\u00f3n\u201d.<\/p>\n<p>Asimismo,\u00a0<strong>se recomienda evitar alimentos procesados y de alta densidad cal\u00f3rica\u00a0<\/strong>como boller\u00eda, pasteler\u00eda, galletas, snacks, refrescos, bebidas alcoh\u00f3licas, embutidos y evitar abusar de alimentos de origen animal. \u201cSe recomienda aumentar el consumo de verduras, hortalizas, legumbre, frutas, frutos secos naturales y entre el origen animal elegir antes el pescado que la carne. Tambi\u00e9n se recomienda realizar una correcta ingesta de l\u00edquidos como agua, caldos o infusiones, y se debe cocinar limpio (plancha, horno, vapor, microondas), evitando fritos\u201d.<\/p>\n<p>Por otro lado, S\u00e1nchez afirma que \u201cen el caso de que tuvi\u00e9ramos poco tiempo para cocinar entre semana, se puede cocinar durante el fin de semana y dejarlo preparado para la semana congelado por raciones\u201d. Otra opci\u00f3n ser\u00eda recurrir a las conservas de calidad de verduras y legumbres. Respecto al ejercicio f\u00edsico, se recomienda realizar ejercicio f\u00edsico adecuado a cada persona de forma diaria m\u00ednimo 30-40 minutos.<\/p>\n<p>Adem\u00e1s, para poder llevar a cabo una dieta variada, equilibrada y completa, se debe planificar tanto la lista de la compra, como los men\u00fas.\u00a0<strong>\u201cHay que planificar tanto los men\u00fas, como la lista de la compra. Es importante realizar una planificaci\u00f3n de lo que se va a comer y, en base a ello, preparar la lista de la compra. Se debe acudir al supermercado sin apetito, ya que de esta manera, evitaremos comprar alimentos superfluos o innecesarios que pueden crear tentaci\u00f3n a la hora de llegar a casa y hay que evitar todos los alimentos procesados\u201d<\/strong>\u00a0se\u00f1ala la especialista.<\/p>\n<p><strong>Sobre Quir\u00f3nsalud<\/strong><\/p>\n<p>Quir\u00f3nsalud es el grupo hospitalario m\u00e1s importante de Espa\u00f1a y el tercero de Europa. Est\u00e1 presente en 13 comunidades aut\u00f3nomas, cuenta con la tecnolog\u00eda m\u00e1s avanzada y dispone de una oferta superior a 6.500 camas en m\u00e1s de 100 centros, como la Fundaci\u00f3n Jim\u00e9nez D\u00edaz, Hospital Universitario Quir\u00f3nsalud Madrid, Hospital Universitario Dexeus, Ruber, Centro M\u00e9dico Teknon, Hospital La Luz, Policl\u00ednica Gipuzkoa, etc, as\u00ed como con un gran equipo de profesionales altamente especializados y de prestigio internacional.<\/p>\n<p>Trabajan en la promoci\u00f3n de la docencia (siete de sus\u00a0hospitales son universitarios) y la investigaci\u00f3n m\u00e9dico-cient\u00edfica (cuentan con el Instituto de Investigaci\u00f3n Sanitaria de la FJD, \u00fanico centro investigador privado acreditado por la Secretar\u00eda de Estado de Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n).<\/p>\n<p>Asimismo, su servicio asistencial est\u00e1 organizado en unidades y redes transversales que permiten optimizar la experiencia acumulada en los distintos centros, y la traslaci\u00f3n cl\u00ednica de sus investigaciones. Actualmente, Quir\u00f3nsalud est\u00e1 desarrollando numerosos proyectos de investigaci\u00f3n en toda Espa\u00f1a y muchos de sus centros realizan en este \u00e1mbito una labor puntera, siendo pioneros en diferentes especialidades como cardiolog\u00eda, endocrinolog\u00eda, ginecolog\u00eda, neurolog\u00eda, oncolog\u00eda, y medicina deportiva entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los<\/p>\n","protected":false},"author":1,"featured_media":1711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1710","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-01T02:11:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-01T02:11:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#listItem\",\"name\":\"Eider S\\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\\u00fas, como la lista de la compra&#8217;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#listItem\",\"position\":3,\"name\":\"Eider S\\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\\u00fas, como la lista de la compra&#8217;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#newsarticle\",\"name\":\"Eider S\\u00e1nchez, nutricionista: \\u2018Hay que planificar tanto los men\\u00fas, como la lista de la compra\\u2019 | El Digital de Asturias\",\"headline\":\"Eider S\\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\\u00fas, como la lista de la compra&#8217;\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg\",\"width\":400,\"height\":265},\"datePublished\":\"2018-11-01T02:11:41+01:00\",\"dateModified\":\"2018-11-01T02:11:41+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el noviembre 1, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/\",\"name\":\"Eider S\\u00e1nchez, nutricionista: \\u2018Hay que planificar tanto los men\\u00fas, como la lista de la compra\\u2019 | El Digital de Asturias\",\"description\":\"En un contexto donde a trav\\u00e9s de las aplicaciones se puede obtener comida r\\u00e1pida casi a cualquier momento del d\\u00eda, cada vez es m\\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \\u00bfcu\\u00e1les son los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#mainImage\",\"width\":400,\"height\":265},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\\\/#mainImage\"},\"datePublished\":\"2018-11-01T02:11:41+01:00\",\"dateModified\":\"2018-11-01T02:11:41+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias","description":"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#listItem","name":"Eider S\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\u00fas, como la lista de la compra&#8217;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#listItem","position":3,"name":"Eider S\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\u00fas, como la lista de la compra&#8217;","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#newsarticle","name":"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias","headline":"Eider S\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\u00fas, como la lista de la compra&#8217;","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg","width":400,"height":265},"datePublished":"2018-11-01T02:11:41+01:00","dateModified":"2018-11-01T02:11:41+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#webpage"},"articleSection":"Live","dateline":"Publicado el noviembre 1, 2018."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/","name":"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias","description":"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#mainImage","width":400,"height":265},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/#mainImage"},"datePublished":"2018-11-01T02:11:41+01:00","dateModified":"2018-11-01T02:11:41+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias","og:description":"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg","og:image:width":400,"og:image:height":265,"article:published_time":"2018-11-01T02:11:41+00:00","article:modified_time":"2018-11-01T02:11:41+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Eider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019 | El Digital de Asturias","twitter:description":"En un contexto donde a trav\u00e9s de las aplicaciones se puede obtener comida r\u00e1pida casi a cualquier momento del d\u00eda, cada vez es m\u00e1s frecuente consumir este tipo alimentos poco saludables y procesados. Sin embargo, la comida r\u00e1pida o fast food nunca ha estado presente en las dietas que recomiendan los nutricionistas: \u00bfcu\u00e1les son los","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/11\/1540913882_eidersanchez_nutricionista_policlinica_gipuzkoa_2_opt.jpg"},"aioseo_meta_data":{"post_id":"1710","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 20:05:08","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 20:34:49","updated":"2026-05-14 20:05:08"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEider S\u00e1nchez, nutricionista: \u2018Hay que planificar tanto los men\u00fas, como la lista de la compra\u2019\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"Eider S\u00e1nchez, nutricionista: &#8216;Hay que planificar tanto los men\u00fas, como la lista de la compra&#8217;","link":"https:\/\/eldigitaldeasturias.com\/radio\/eider-sanchez-nutricionista-hay-que-planificar-tanto-los-menus-como-la-lista-de-la-compra\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/1710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=1710"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/1710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/1711"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=1710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=1710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=1710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}