{"id":1676,"date":"2018-10-29T03:42:00","date_gmt":"2018-10-29T03:42:00","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=1676"},"modified":"2018-10-29T03:42:00","modified_gmt":"2018-10-29T03:42:00","slug":"el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/","title":{"rendered":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-1677\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_-350x300.jpg\" alt=\"\" width=\"350\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_-350x300.jpg 350w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_-1024x878.jpg 1024w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_-768x659.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_-1536x1318.jpg 1536w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_-2048x1757.jpg 2048w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo.<\/p>\n<p>Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n en directo a los asistentes a ORTO Medical Care, que sufren trastornos neurol\u00f3gicos como la atrofia muscular espinal que les impiden caminar y estos robots son una aut\u00e9ntica esperanza de vida para ellos. De hecho, su vida se alarga hasta un 50% m\u00e1s que si permanecieran atados a una silla de ruedas.<\/p>\n<p>Garc\u00eda Armada ha explicado a los participantes que estas peticiones fueron las que la animaron a crear la empresa Marsi Bionics como v\u00eda de \u201ctransferencia\u201d de las investigaciones desarrolladas por el CSIC.<\/p>\n<p>As\u00ed empez\u00f3 el proyecto Atlas, materializado en varios modelos de exoesqueletos pedi\u00e1tricos aptos para ni\u00f1os de hasta 40 kilos de peso. \u201cAl principio, los ni\u00f1os se asustaban\u201d, relata la doctora Garc\u00eda Armada, pero tres meses despu\u00e9s \u201cestaban encantados\u201d y no quer\u00edan prescindir de \u00e9l. Y con una mejor\u00eda muy notable, seg\u00fan destacan las familias. En todo el mundo hay m\u00e1s de 17 millones de ni\u00f1os que no pueden caminar y el robot de la doctora Garc\u00eda Armada puede ser un nuevo horizonte en las terapias.<\/p>\n<p>Se habla de alta tecnolog\u00eda a todos los niveles, desde la maquinaria propiamente dicha hasta el verdadero coraz\u00f3n del exoesqueleto: los sensores que detectan la \u2018intenci\u00f3n\u2019 del ni\u00f1o de moverse, aprenden a decodificar la se\u00f1al y la transfieren amplificada a la articulaci\u00f3n que act\u00faa como un verdadero m\u00fasculo artificial para generar el movimiento correspondiente.<\/p>\n<p>En la actualidad, se trabaja en el modelo Kinder, que ha saltado del laboratorio a los hogares directamente. Durante dos meses, varios ni\u00f1os han descubierto que incluso pueden jugar con una pelota y encestarla en una canasta con sus propias manos, algo que hasta ahora les estaba vedado.<\/p>\n<p>La doctora Garc\u00eda Armada ha ampliado ahora su trabajo a adultos, a pacientes de ictus -uno de los males m\u00e1s extendidos de la sociedad actual- con problemas de movilidad en las rodillas. Para ellos ha dise\u00f1ado el proyecto MAK, una \u00f3rtesis robotizada que les aporta la energ\u00eda necesaria para caminar casi con total normalidad.<\/p>\n<p>Este minirobot tambi\u00e9n pertenece a la era de las pr\u00f3tesis inteligentes ya que es capaz de aprender el patr\u00f3n de caminar de cada usuario y, adem\u00e1s, recabar todo tipo de datos que el m\u00e9dico se descarga para mejorar el tratamiento.<\/p>\n<p>Tras la demostraci\u00f3n del exoesqueleto de \u00c1lvaro por los pasillos de Ifema, ORTO Medical Care era un hervidero de novedades en Ortopedia. Desde pr\u00f3tesis decoradas como una Harley Davidson hasta la impresi\u00f3n en 3D de plantillas, que se considera uno de los futuros m\u00e1s prometedores de esta especialidad, o las sofisticadas piernas artificiales de las atletas paral\u00edmpicas Sara Andr\u00e9s y Desir\u00e9e Vila.<\/p>\n<p>Y, por supuesto, las manos mioel\u00e9ctricas con capacidad sensorial, las grandes protagonistas de ORTO Medical Care 2018 junto al exoesqueleto de la doctora Garc\u00eda Armada.<\/p>\n<p>La inauguraci\u00f3n de la gran feria europea de la Ortopedia ha corrido a cargo del consejero de Sanidad de la Comunidad de Madrid, Enrique Ruiz Escudero, la subdirectora general de Cartera B\u00e1sica de Servicios del Ministerio de Sanidad, Cristina Gonz\u00e1lez del Yerro, y el presidente de Fedop, Pablo P\u00e9rez Aragundi. ORTO Medical Care se celebra este jueves y viernes y por sus instalaciones se prev\u00e9 la asistencia de m\u00e1s de 10.000 personas que tendr\u00e1n a su disposici\u00f3n m\u00e1s de un centenar de expositores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":1677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1676","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2159\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1852\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-10-29T03:42:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-10-29T03:42:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#listItem\",\"name\":\"El sector de la Ortopedia mira al futuro con las nuevas pr\\u00f3tesis inteligentes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#listItem\",\"position\":3,\"name\":\"El sector de la Ortopedia mira al futuro con las nuevas pr\\u00f3tesis inteligentes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#newsarticle\",\"name\":\"El sector de la Ortopedia mira al futuro con las nuevas pr\\u00f3tesis inteligentes | El Digital de Asturias\",\"headline\":\"El sector de la Ortopedia mira al futuro con las nuevas pr\\u00f3tesis inteligentes\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg\",\"width\":2159,\"height\":1852},\"datePublished\":\"2018-10-29T03:42:00+01:00\",\"dateModified\":\"2018-10-29T03:42:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el octubre 29, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/\",\"name\":\"El sector de la Ortopedia mira al futuro con las nuevas pr\\u00f3tesis inteligentes | El Digital de Asturias\",\"description\":\"La creadora del exoesqueleto para ni\\u00f1os, la doctora en Rob\\u00f3tica del CSIC Elena Garc\\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\\u00f3 en 2010 el primer prototipo, esta cient\\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\\u00f1os como el peque\\u00f1o \\u00c1lvaro, encargado de la demostraci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#mainImage\",\"width\":2159,\"height\":1852},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\\\/#mainImage\"},\"datePublished\":\"2018-10-29T03:42:00+01:00\",\"dateModified\":\"2018-10-29T03:42:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias","description":"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#listItem","name":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#listItem","position":3,"name":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#newsarticle","name":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias","headline":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg","width":2159,"height":1852},"datePublished":"2018-10-29T03:42:00+01:00","dateModified":"2018-10-29T03:42:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#webpage"},"articleSection":"Live","dateline":"Publicado el octubre 29, 2018."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/","name":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias","description":"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#mainImage","width":2159,"height":1852},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/#mainImage"},"datePublished":"2018-10-29T03:42:00+01:00","dateModified":"2018-10-29T03:42:00+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias","og:description":"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg","og:image:width":2159,"og:image:height":1852,"article:published_time":"2018-10-29T03:42:00+00:00","article:modified_time":"2018-10-29T03:42:00+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes | El Digital de Asturias","twitter:description":"La creadora del exoesqueleto para ni\u00f1os, la doctora en Rob\u00f3tica del CSIC Elena Garc\u00eda Armada ha sido la encargada de abrir ORTO Medical Care 2018. Desde que present\u00f3 en 2010 el primer prototipo, esta cient\u00edfica y empresaria ha recibido numerosas peticiones de todo el mundo. Son ni\u00f1os como el peque\u00f1o \u00c1lvaro, encargado de la demostraci\u00f3n","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540541356_Inauguraci_n_de_la_Feria_ORTO_Medical_Care_2018_1_.jpg"},"aioseo_meta_data":{"post_id":"1676","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 19:59:19","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 20:36:14","updated":"2026-05-14 19:59:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"El sector de la Ortopedia mira al futuro con las nuevas pr\u00f3tesis inteligentes","link":"https:\/\/eldigitaldeasturias.com\/radio\/el-sector-de-la-ortopedia-mira-al-futuro-con-las-nuevas-protesis-inteligentes\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/1676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=1676"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/1676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/1677"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=1676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=1676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=1676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}