{"id":1537,"date":"2018-10-23T07:56:38","date_gmt":"2018-10-23T07:56:38","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/radio\/?p=1537"},"modified":"2018-10-23T07:58:03","modified_gmt":"2018-10-23T07:58:03","slug":"consejos-para-fomentar-la-lectura-entre-los-mas-pequenos","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/","title":{"rendered":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-1538\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_-360x235.jpg\" alt=\"\" width=\"360\" height=\"235\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_-360x235.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_-768x501.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg 1000w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos.<\/p>\n<p>Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones.<\/p>\n<p>Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os.<\/p>\n<p>La lectura es un juego m\u00e1s para los ni\u00f1os, pero adem\u00e1s les ayuda a desarrollar el lenguaje, la imaginaci\u00f3n, la creatividad, mejora la comprensi\u00f3n lectora y la concentraci\u00f3n, y permite desarrollar la personalidad desde edades tempranas. Descubrir las sorpresas que se esconden tras un libro o un cuento infantil es esencial, teniendo para ello gran protagonismo los padres, ya que ser\u00e1n ellos los que deber\u00e1n fomentar desde peque\u00f1os esta pasi\u00f3n por la lectura.<\/p>\n<p><strong>\u00bfQu\u00e9 deben hacer los padres?<\/strong><\/p>\n<p>La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda de Atenci\u00f3n Primaria (AEPap) ofrece un\u00a0<a href=\"https:\/\/www.aepap.org\/sites\/default\/files\/noticia\/archivos-adjuntos\/abc_23.04.13.pdf\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff6600;\"><strong>decano de consejos<\/strong><\/span><\/a>\u00a0a los padres para fomentar desde casa que los ni\u00f1os lean, lo que adem\u00e1s favorece el correcto desarrollo del lenguaje. En este sentido, los progenitores deben ayudar a los ni\u00f1os cada d\u00eda desde peque\u00f1os a organizar su tiempo para que puedan realizar todas las tareas o actividades programadas, reservando un rato para la lectura. Este tiempo para leer siempre debe ser en momentos de ocio y con buena disposici\u00f3n.<\/p>\n<p>Los padres son los primeros que deben dedicar ratos del d\u00eda a la lectura y compartir esos momentos con los peque\u00f1os. Los ni\u00f1os imitan los comportamientos de los adultos, por lo que es esencial dar ejemplo desde el principio. Seg\u00fan datos del Ministerio de Educaci\u00f3n, Cultura y Deporte, recogidos por la\u00a0<a href=\"http:\/\/www.aepap.org\/sites\/default\/files\/noticia\/archivos-adjuntos\/np_fomento_lectura_def.pdf\" target=\"_blank\" rel=\"nofollow noopener\"><strong><span style=\"color: #ff6600;\">AEPap<\/span><\/strong><\/a>, el 78.3% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos, mientras que el 79% de las familias con ni\u00f1os menores de 6 a\u00f1os les leen en casa una media de 3 horas a la semana y el 84.7% de los ni\u00f1os entre 6 y 13 a\u00f1os leen libros que no son de texto durante m\u00e1s de 3 horas semanales. La estimulaci\u00f3n es otra buena opci\u00f3n para fomentar la lectura entre los peque\u00f1os, por lo que se deben poner al alcance de ellos libros y cuentos. Destinar una parte de su habitaci\u00f3n, mueble o espacio de la casa a guardar todos los libros y cuentos.<\/p>\n<p>Escucharlos es clave para aprender m\u00e1s sobre sus gustos y motivaciones, por lo que se debe respetar su derecho a elegir. Nunca se debe tratar de obligar e imponerles una determinada lectura, aunque s\u00ed es importante que se le sugieran. Si se tienen\u00a0dudas sobre qu\u00e9 tipo de libros o cuentos son m\u00e1s adecuados por su edad, pedir consejo en el colegio, ya que la AEPap recomienda que no se creen contradicciones entre el m\u00e9todo de la escuela y el empleado en casa. Las bibliotecas y librer\u00edas infantiles tambi\u00e9n son buenos lugares para pedir consejo o sugerencias de lectura en funci\u00f3n de la edad o necesidades del ni\u00f1o.<\/p>\n<p><strong>\u00bfQu\u00e9 cuento elegir para los hijos?<\/strong><\/p>\n<p>Al igual que en los juguetes, para elegir los libros o cuentos para los ni\u00f1os se debe\u00a0tener en cuenta su edad. En el primer a\u00f1o de vida es esencial optar por cuentos con m\u00fasica y sonidos, de tela o especiales para el ba\u00f1o con el fin de que los beb\u00e9s puedan manipularlos y jugar con ellos sin que se estropeen. Poco a poco ir\u00e1n cogiendo la idea de qu\u00e9 es un libro.<\/p>\n<p>Para los primeros cuatro a\u00f1os, en los libros deben predominar las im\u00e1genes, ya que permitir\u00e1 desarrollar la imaginaci\u00f3n y creatividad del ni\u00f1o y tener conocimiento de la historia del cuento por los propios dibujos. Adem\u00e1s, los textos deben ser cortos y con una estructura repetitiva.<\/p>\n<p>A partir de los 4 a\u00f1os, continuar\u00e1 predominando los dibujos y los textos con historias m\u00e1s largas, pero con una argumentaci\u00f3n sencilla. Se empezar\u00e1n a introducir conocimientos sobre la naturaleza, las letras y los n\u00fameros, as\u00ed como las expresiones de las emociones y sentimientos de una forma sencilla y did\u00e1ctica. Ejemplo de ello es el libro &#8216;<a href=\"https:\/\/www.mapanda.eu\/es\/ropa-y-vestidos-para-ninas\/141-kit-para-aventurarse-a-ser-diferente.html\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff6600;\"><strong>Hipo, un hipop\u00f3tamo azu<\/strong><\/span>l<\/a>&#8216; una bella historia sobre un peque\u00f1o hipop\u00f3tamo que es diferente a los dem\u00e1s y \u00e9l mismo aprende c\u00f3mo estas diferencias le hacen especial y \u00fanico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego<\/p>\n","protected":false},"author":1,"featured_media":1538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1537","post","type-post","status-publish","format-standard","has-post-thumbnail","category-live"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"live\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-10-23T07:56:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-10-23T07:58:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#listItem\",\"name\":\"Consejos para fomentar la lectura entre los m\\u00e1s peque\\u00f1os\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#listItem\",\"position\":3,\"name\":\"Consejos para fomentar la lectura entre los m\\u00e1s peque\\u00f1os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#newsarticle\",\"name\":\"Consejos para fomentar la lectura entre los m\\u00e1s peque\\u00f1os | El Digital de Asturias\",\"headline\":\"Consejos para fomentar la lectura entre los m\\u00e1s peque\\u00f1os\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg\",\"width\":1000,\"height\":652},\"datePublished\":\"2018-10-23T07:56:38+02:00\",\"dateModified\":\"2018-10-23T07:58:03+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#webpage\"},\"articleSection\":\"Live\",\"dateline\":\"Publicado el octubre 23, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/\",\"name\":\"Consejos para fomentar la lectura entre los m\\u00e1s peque\\u00f1os | El Digital de Asturias\",\"description\":\"M\\u00e1s del 78% de los ni\\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\\u00e1bito en ellos. Escuchar a los ni\\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\\u00f1os. La lectura es un juego\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#mainImage\",\"width\":1000,\"height\":652},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\\\/#mainImage\"},\"datePublished\":\"2018-10-23T07:56:38+02:00\",\"dateModified\":\"2018-10-23T07:58:03+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias","description":"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/","robots":"max-image-preview:large","keywords":"live","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#listItem","name":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#listItem","position":3,"name":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#newsarticle","name":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias","headline":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg","width":1000,"height":652},"datePublished":"2018-10-23T07:56:38+02:00","dateModified":"2018-10-23T07:58:03+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#webpage"},"articleSection":"Live","dateline":"Publicado el octubre 23, 2018."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/","name":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias","description":"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#mainImage","width":1000,"height":652},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/#mainImage"},"datePublished":"2018-10-23T07:56:38+02:00","dateModified":"2018-10-23T07:58:03+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias","og:description":"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg","og:image:width":1000,"og:image:height":652,"article:published_time":"2018-10-23T07:56:38+00:00","article:modified_time":"2018-10-23T07:58:03+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os | El Digital de Asturias","twitter:description":"M\u00e1s del 78% de los ni\u00f1os aseguran que sus padres leen habitualmente, lo cual es muy importante para dar ejemplo y crear el h\u00e1bito en ellos. Escuchar a los ni\u00f1os es clave para conocer sus gustos y motivaciones. Siempre es mejor sugerir que imponer una determinada lectura a los ni\u00f1os. La lectura es un juego","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2018\/10\/1540197805_MAPANDA_FOMENTAR_LECTURA_NIN_OS_1_.jpg"},"aioseo_meta_data":{"post_id":"1537","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 19:41:26","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-25 20:33:17","updated":"2026-05-14 19:41:26"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" title=\"Live\">Live<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tConsejos para fomentar la lectura entre los m\u00e1s peque\u00f1os\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"},{"label":"Consejos para fomentar la lectura entre los m\u00e1s peque\u00f1os","link":"https:\/\/eldigitaldeasturias.com\/radio\/consejos-para-fomentar-la-lectura-entre-los-mas-pequenos\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/1537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=1537"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/1537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/1538"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=1537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=1537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=1537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}