{"id":12893,"date":"2026-07-14T15:18:58","date_gmt":"2026-07-14T13:18:58","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=12893"},"modified":"2026-07-14T15:18:58","modified_gmt":"2026-07-14T13:18:58","slug":"madre-asturias-supera-las-2-000-visitas-en-su-primer-mes","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/","title":{"rendered":"Madre Asturias supera las 2.000 visitas en su primer mes"},"content":{"rendered":"<p>La <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/\"><strong>exposici\u00f3n Madre Asturias<\/strong><\/a><\/span>. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero, consolidando la buena acogida de la muestra.<\/p>\n<figure id=\"attachment_12894\" aria-describedby=\"caption-attachment-12894\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-12894\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-650x420.jpg\" alt=\"Madre Asturias supera las 2.000 visitas en su primer mes\" width=\"650\" height=\"420\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-650x420.jpg 650w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-360x233.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-768x496.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-150x97.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-450x291.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes-1200x775.jpg 1200w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg 1255w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-12894\" class=\"wp-caption-text\">Foto: Prensa Principado de Asturias<\/figcaption><\/figure>\n<p>La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada, organizada por la Consejer\u00eda de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Deporte del <a href=\"https:\/\/actualidad.asturias.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>Principado<\/strong><\/span><\/a> y comisariada por Luis Fe\u00e1s, ha superado las 2.000 visitas en su primer mes de apertura en la Sala Sabadell Herrero de Oviedo\/Uvi\u00e9u. La cifra consolida la buena acogida de una muestra que propone un recorrido por m\u00e1s de 150 a\u00f1os de creaci\u00f3n art\u00edstica vinculada con el Principado.<\/p>\n<p>La exhibici\u00f3n re\u00fane 59 obras de 37 artistas y plantea un di\u00e1logo entre distintas generaciones y corrientes para explorar c\u00f3mo ha evolucionado la representaci\u00f3n de Asturias desde el siglo XIX hasta ahora. A trav\u00e9s de la pintura y otras manifestaciones creativas, aborda algunos de los grandes temas que han configurado el imaginario colectivo asturiano, como el paisaje, el mundo rural, la industrializaci\u00f3n, las transformaciones sociales o la construcci\u00f3n de la identidad cultural de la comunidad.<\/p>\n<p>El recorrido permite contemplar obras de algunos de los nombres m\u00e1s relevantes de la historia del arte asturiano, entre ellos, Le\u00f3n y Escosura, Dar\u00edo de Regoyos, Evaristo Valle y Nicanor Pi\u00f1ole, junto con creadores contempor\u00e1neos que ampl\u00edan la reflexi\u00f3n sobre Asturias y su evoluci\u00f3n. Adem\u00e1s, la exposici\u00f3n acoge la primera exhibici\u00f3n p\u00fablica de Despedida a los novios en Monasterio de Hermo (1897), de Luis \u00c1lvarez Catal\u00e1, incorporada recientemente a la colecci\u00f3n art\u00edstica del Principado.<\/p>\n<p>Madre Asturias. De la Espa\u00f1a negra al arte de avanzada podr\u00e1 visitarse hasta el 30 de septiembre en la Sala Sabadell Herrero de Oviedo\/Uvi\u00e9u.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero, consolidando la buena acogida de la muestra. La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada, organizada por la Consejer\u00eda de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Deporte<\/p>\n","protected":false},"author":1,"featured_media":12894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[141],"tags":[42,79],"class_list":["post-12893","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-asturias","tag-asturias","tag-cultura"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1255\" \/>\n\t\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T13:18:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T13:18:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/actualidad-asturias\\\/#listItem\",\"name\":\"Actualidad Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/actualidad-asturias\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Asturias\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/actualidad-asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#listItem\",\"name\":\"Madre Asturias supera las 2.000 visitas en su primer mes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#listItem\",\"position\":3,\"name\":\"Madre Asturias supera las 2.000 visitas en su primer mes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/actualidad-asturias\\\/#listItem\",\"name\":\"Actualidad Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#newsarticle\",\"name\":\"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias\",\"headline\":\"Madre Asturias supera las 2.000 visitas en su primer mes\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg\",\"width\":1255,\"height\":811,\"caption\":\"Foto: Prensa Principado de Asturias\"},\"datePublished\":\"2026-07-14T15:18:58+02:00\",\"dateModified\":\"2026-07-14T15:18:58+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#webpage\"},\"articleSection\":\"Actualidad Asturias, Asturias, cultura\",\"dateline\":\"Publicado el julio 14, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/\",\"name\":\"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias\",\"description\":\"La exposici\\u00f3n Madre Asturias. De la Espa\\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#mainImage\",\"width\":1255,\"height\":811,\"caption\":\"Foto: Prensa Principado de Asturias\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\\\/#mainImage\"},\"datePublished\":\"2026-07-14T15:18:58+02:00\",\"dateModified\":\"2026-07-14T15:18:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias","description":"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/","robots":"max-image-preview:large","keywords":"actualidad asturias","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/#listItem","name":"Actualidad Asturias"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/#listItem","position":2,"name":"Actualidad Asturias","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#listItem","name":"Madre Asturias supera las 2.000 visitas en su primer mes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#listItem","position":3,"name":"Madre Asturias supera las 2.000 visitas en su primer mes","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/#listItem","name":"Actualidad Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#newsarticle","name":"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias","headline":"Madre Asturias supera las 2.000 visitas en su primer mes","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg","width":1255,"height":811,"caption":"Foto: Prensa Principado de Asturias"},"datePublished":"2026-07-14T15:18:58+02:00","dateModified":"2026-07-14T15:18:58+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#webpage"},"articleSection":"Actualidad Asturias, Asturias, cultura","dateline":"Publicado el julio 14, 2026."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/","name":"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias","description":"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#mainImage","width":1255,"height":811,"caption":"Foto: Prensa Principado de Asturias"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/#mainImage"},"datePublished":"2026-07-14T15:18:58+02:00","dateModified":"2026-07-14T15:18:58+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias","og:description":"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg","og:image:width":1255,"og:image:height":811,"article:published_time":"2026-07-14T13:18:58+00:00","article:modified_time":"2026-07-14T13:18:58+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Madre Asturias supera las 2.000 visitas en su primer mes | El Digital de Asturias","twitter:description":"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2026\/07\/Madre-Asturias-supera-las-2000-visitas-en-su-primer-mes.jpg"},"aioseo_meta_data":{"post_id":"12893","title":null,"description":"La exposici\u00f3n Madre Asturias. De la Espa\u00f1a negra al arte de avanzada ha superado las 2.000 visitas durante su primer mes en la Sala Sabadell Herrero","keywords":null,"keyphrases":{"focus":{"keyphrase":"Madre Asturias","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Madre Asturias","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-14 13:20:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-14 13:12:45","updated":"2026-07-14 13:24:30","focus_keyword":"Madre Asturias","additional_keywords":[{"word":"Madre Asturias","score":100}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/\" title=\"Actualidad Asturias\">Actualidad Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMadre Asturias supera las 2.000 visitas en su primer mes\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Actualidad Asturias","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/actualidad-asturias\/"},{"label":"Madre Asturias supera las 2.000 visitas en su primer mes","link":"https:\/\/eldigitaldeasturias.com\/radio\/madre-asturias-supera-las-2-000-visitas-en-su-primer-mes\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/12893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=12893"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/12893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/12894"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=12893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=12893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=12893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}