{"id":11058,"date":"2025-09-20T20:26:47","date_gmt":"2025-09-20T18:26:47","guid":{"rendered":"https:\/\/eldigitaldeasturias.com\/radio\/?p=11058"},"modified":"2025-09-20T20:26:47","modified_gmt":"2025-09-20T18:26:47","slug":"medallas-de-asturias-2026-los-galardonados","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/","title":{"rendered":"Medallas de Asturias 2026: Los galardonados"},"content":{"rendered":"<p>El presidente del <a href=\"https:\/\/actualidad.asturias.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>Principado de Asturias<\/strong><\/span><\/a>, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas de Asturias el pr\u00f3ximo a\u00f1o. En 2026, las m\u00e1ximas distinciones institucionales de la comunidad premiar\u00e1n la historia centenaria del Real Oviedo, as\u00ed como la inclusi\u00f3n de las personas con discapacidad, el periodismo con visi\u00f3n territorial y la m\u00fasica como v\u00eda de difusi\u00f3n y promoci\u00f3n de la cultura regional y de las lenguas propias.<\/p>\n<figure id=\"attachment_11059\" aria-describedby=\"caption-attachment-11059\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-11059\" src=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026-650x432.jpg\" alt=\"Medallas de Asturias 2026\" width=\"650\" height=\"432\" srcset=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026-768x510.jpg 768w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg 1014w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-11059\" class=\"wp-caption-text\">Foto: Prensa Gobierno de Asturias<\/figcaption><\/figure>\n<p>El pr\u00f3ximo 8 de septiembre, con motivo del <a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/agenda\/\"><span style=\"color: #ff6600;\"><strong>D\u00eda de Asturias<\/strong><\/span><\/a>, se otorgar\u00e1 este reconocimiento a:<\/p>\n<ul>\n<li><strong>Real Oviedo<\/strong>. El club de f\u00fatbol celebra su centenario en 2026 y lo har\u00e1 en primera divisi\u00f3n despu\u00e9s de 24 temporadas. El ascenso del equipo ha logrado movilizar a la sociedad ovetense y ha fortalecido una afici\u00f3n azul que se extiende por toda la comunidad. Fundado en la capital del Principado el 26 de marzo de 1926 por la uni\u00f3n del Real Stadium Club Ovetense y el Real Club Deportivo de Oviedo, en la actualidad cuenta con una potente cantera de m\u00e1s de 180 ni\u00f1os y con ocho equipos femeninos de f\u00fatbol base. El Real Oviedo Femenino tambi\u00e9n ha logrado ascender este a\u00f1o y ahora milita en Primera RFEF, la segunda categor\u00eda nacional.<\/li>\n<li><strong>Asociaci\u00f3n Emburria<\/strong>. Esta entidad sin \u00e1nimo de lucro se fund\u00f3 en el concejo de Cangas de On\u00eds en 2002 con el objetivo de favorecer la plena inclusi\u00f3n social de las personas con diversidad funcional. Desde entonces, se ha convertido en una aut\u00e9ntica referencia en su campo. La organizaci\u00f3n ofrece servicios de apoyo desde los primeros a\u00f1os hasta la edad adulta, al tiempo que acompa\u00f1a a las familias y busca recursos para facilitarles la vida cotidiana. Su prop\u00f3sito principal consiste en ayudar a cada persona con discapacidad a construir su propia identidad y alcanzar el bienestar en todos los \u00e1mbitos de la vida: educativo, social, familiar y laboral.<\/li>\n<li><strong>Joaqu\u00edn Pix\u00e1n<\/strong>. Tenor, gestor cultural y gran divulgador de la canci\u00f3n asturiana, naci\u00f3 en Cangas del Narcea y lleva m\u00e1s de cincuenta a\u00f1os dedicado a la m\u00fasica. Se form\u00f3 en la Scala de Mil\u00e1n bajo la tutela de Alfredo Kraus y ha colaborado con artistas y poetas como \u00c1ngel Gonz\u00e1lez o Antonio Gamoneda. Cantante polifac\u00e9tico, ha grabado m\u00e1s de 35 discos, que abarcan desde la canci\u00f3n l\u00edrica cl\u00e1sica hasta innovadoras composiciones que fusionan poes\u00eda y m\u00fasica. Asturias siempre ha tenido un lugar destacado en la trayectoria de Pix\u00e1n, que en sus obras ha dejado constancia de su defensa de la tradici\u00f3n y el patrimonio regionales.<\/li>\n<li><strong>Isidoro Nicieza<\/strong>. El periodista gijon\u00e9s desarroll\u00f3 una carrera laboral de m\u00e1s de 40 a\u00f1os, mayoritariamente vinculada a la editorial Prensa Ib\u00e9rica. Fue director de los diarios La Nueva Espa\u00f1a y El Faro de Vigo, as\u00ed como director general de La Nueva Espa\u00f1a y de Contenidos del grupo. Figura destacada del periodismo asturiano de los \u00faltimos a\u00f1os, persigui\u00f3 siempre una informaci\u00f3n de calidad y con sensibilidad territorial. Se distingui\u00f3 por su empe\u00f1o en anticiparse, a veces contracorriente, a la hora de adecuar y conciliar el periodismo impreso con nuevos formatos digitales. De igual modo, siempre se preocup\u00f3 de preservar tanto la independencia editorial como la pluralidad de los medios.<\/li>\n<li><strong>Nacho Fonseca<\/strong>. Maestro, especialista en filolog\u00eda, supo fomentar la ense\u00f1anza de la lengua asturiana a trav\u00e9s de la m\u00fasica. En el curso 1987-1988 fund\u00f3 el grupo Xentiquina en el Colegio P\u00fablico Solvay-Lieres, en Siero, que ahora lleva el nombre de aquel coro infantil de gran \u00e9xito por el que pasaron m\u00e1s de 200 estudiantes. En un momento en el que apenas hab\u00eda materiales pedag\u00f3gicos para el aprendizaje de la llingua asturiana, Fonseca utiliz\u00f3 cantares populares y composiciones propias para ense\u00f1ar a su alumnado durante 25 a\u00f1os.<\/li>\n<\/ul>\n<blockquote><p>La Medalla de Asturias se reserva para premiar m\u00e9ritos verdaderamente singulares que concurren en personas o instituciones cuya importancia y trascendencia para los intereses generales de la comunidad les hagan acreedores del reconocimiento.<\/p><\/blockquote>\n<p>La Junta General aprob\u00f3 en abril de 2022 la ley que unifica en una \u00fanica categor\u00eda los dos tipos de medallas (oro y plata) que exist\u00edan antes, al entender que los merecimientos para recibir este honor deben ser de gran relevancia en todos los casos.<\/p>\n<h2>Hijos predilectos<\/h2>\n<p>El Consejo de Gobierno ha acordado proponer la concesi\u00f3n del t\u00edtulo de hijos predilectos a las siguientes personas.<\/p>\n<ul>\n<li>Juan Antonio P\u00e9rez Sim\u00f3n. El empresario y coleccionista de arte, nacido en Llanes y residente en M\u00e9xico, ha mantenido un estrecho v\u00ednculo con su tierra natal. Fue presidente del Consejo Social de la Universidad de Oviedo, es patrono de la Fundaci\u00f3n Princesa de Asturias y forma parte de la Asociaci\u00f3n de Amigos del Archivo de Indianos-Museo de la Emigraci\u00f3n. Tambi\u00e9n ha depositado importantes obras en el Museo de Bellas Artes.<\/li>\n<li>\u2060Isidro Fern\u00e1ndez Rozada. Nacido en San Mart\u00edn el Rey Aurelio en 1943, fue fundador de Alianza Popular, presidente y secretario general del Partido Popular en Asturias, adem\u00e1s de diputado y senador. En la actualidad preside el Instituto del Conocimiento para el Avance de Asturias, la organizaci\u00f3n que ha fundado como espacio de discusi\u00f3n y an\u00e1lisis para seguir contribuyendo al desarrollo de la comunidad.<\/li>\n<li>Mari Luz Crist\u00f3bal Caunedo. Natural de Tineo, es una de las voces m\u00e1s respetadas y reconocidas de la m\u00fasica tradicional, especialmente de la asturianada. Tambi\u00e9n ha participado activamente en la recuperaci\u00f3n de la misa de gaita, declarada bien de inter\u00e9s cultural (BIC). Form\u00f3 parte del Colectivu Etnogr\u00e1ficu Muyeres y colabor\u00f3 en la grabaci\u00f3n del exitoso disco Tierra de Nadie, del gaitero Jos\u00e9 \u00c1ngel Hevia.<\/li>\n<li>Jos\u00e9 Sierra Fern\u00e1ndez. Pol\u00edtico y sindicalista, fue alcalde durante 23 a\u00f1os de Grado, su concejo natal. Form\u00f3 parte del Partido Comunista y de Izquierda Unida. Tras abandonar la pol\u00edtica activa, sigue comprometido con la b\u00fasqueda del inter\u00e9s general y con la recuperaci\u00f3n de la memoria democr\u00e1tica. En la actualidad, colabora en la identificaci\u00f3n de restos de la fosa com\u00fan de El Rell\u00e1n, una de las mayores de Asturias<\/li>\n<\/ul>\n<h2>Hijos adoptivos<\/h2>\n<p>El Ejecutivo ha acordado, adem\u00e1s, proponer la concesi\u00f3n del t\u00edtulo de hijos adoptivos a las siguientes personas.<\/p>\n<ul>\n<li>Paz Fern\u00e1ndez Felgueroso. Abogada de formaci\u00f3n y pol\u00edtica, naci\u00f3 en San Sebasti\u00e1n, pero ha pasado la mayor parte de su vida en Asturias, donde ha sido docente, consejera, diputada, alcaldesa de Gij\u00f3n y presidenta del Consejo de Comunidades Asturianas. Fue la primera abogada que ejerci\u00f3 en Gij\u00f3n\/Xix\u00f3n y ocup\u00f3 la Secretar\u00eda de Estado de Asuntos Penitenciarios de 1993 a 1996. Siempre ha destacado por su permanente defensa de la igualdad y los derechos de las mujeres.<\/li>\n<li>Sa\u00fal Craviotto. El pirag\u00fcista leridano, residente en Asturias desde hace a\u00f1os, es el m\u00e1ximo medallista ol\u00edmpico espa\u00f1ol, con seis metales. Compagina su faceta deportiva con su trabajo como polic\u00eda nacional. Su extraordinario palmar\u00e9s, que incluye t\u00edtulos en campeonatos mundiales y europeos, constituye un ejemplo de superaci\u00f3n para las generaciones m\u00e1s j\u00f3venes del pirag\u00fcismo, una disciplina con s\u00f3lida tradici\u00f3n en Asturias.<\/li>\n<li>Maruja Torres. La escritora y periodista Maruja Torres, natural de Barcelona, ha ganado los premios Planeta y Nadal y ha sido corresponsal de guerra en L\u00edbano, Panam\u00e1 e Israel. Atesora una larga y fruct\u00edfera trayectoria en medios como El Pa\u00eds, Fotogramas o Diario 16 y ha encontrado en Asturias un refugio y una segunda casa, concretamente en Oviedo\/Uvi\u00e9u, donde ahora pasa largas temporadas.<\/li>\n<li>Yayoi Kawamura. Nacida en Osaka (Jap\u00f3n), es profesora titular del Departamento de Historia del Arte y Musicolog\u00eda de la Universidad de Oviedo, instituci\u00f3n en la que se doctor\u00f3. Desde su llegada al Principado con una beca, en 1977, ha contribuido a estrechar los lazos acad\u00e9micos y culturales entre Jap\u00f3n y Espa\u00f1a, por lo que ha recibido la Orden del Tesoro Sagrado, una condecoraci\u00f3n que otorga el emperador nip\u00f3n.<\/li>\n<li>Adolfo Rivas Fern\u00e1ndez. La trayectoria del director de la Fundaci\u00f3n Vinjoy, natural de Barakaldo, ha estado marcada por el compromiso social y la lucha contra las desigualdades. Doctor en Psicolog\u00eda, desde 1997 dirige una fundaci\u00f3n que se ha convertido en un motor socioeducativo en Asturias para la integraci\u00f3n de personas con sordera, discapacidad, riesgo de exclusi\u00f3n o trastornos de conducta.<\/li>\n<li>Consuelo Mart\u00ednez L\u00f3pez. Nacida en Galicia, es catedr\u00e1tica de \u00c1lgebra de la Universidad de Oviedo, colabora con el gran matem\u00e1tico ruso Efim Zelmanov y ha realizado estancias de investigaci\u00f3n en universidades como Oxford o Yale y en el KIAS de Corea del Sur. Entre otros galardones, ha recibido la medalla de la Real Sociedad Matem\u00e1tica de Espa\u00f1a y el premio Julio Pel\u00e1ez para mujeres destacadas en el campo cient\u00edfico.<\/li>\n<\/ul>\n<p>La distinci\u00f3n de hijo adoptivo se reserva para quienes hayan destacado por sus servicios en beneficio de Asturias sin haber nacido en la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas de Asturias el pr\u00f3ximo a\u00f1o. En 2026, las m\u00e1ximas distinciones institucionales de la comunidad premiar\u00e1n la historia centenaria del Real Oviedo, as\u00ed como la inclusi\u00f3n de las personas con discapacidad, el periodismo<\/p>\n","protected":false},"author":1,"featured_media":11059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[141,36],"tags":[42],"class_list":["post-11058","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-asturias","category-titulares","tag-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"NBAsturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad asturias,titulares\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1014\" \/>\n\t\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-20T18:26:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-20T18:26:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/#listItem\",\"name\":\"Titulares\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/#listItem\",\"position\":2,\"name\":\"Titulares\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#listItem\",\"name\":\"Medallas de Asturias 2026: Los galardonados\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#listItem\",\"position\":3,\"name\":\"Medallas de Asturias 2026: Los galardonados\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/titulares\\\/#listItem\",\"name\":\"Titulares\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#newsarticle\",\"name\":\"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias\",\"headline\":\"Medallas de Asturias 2026: Los galardonados\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Medallas-de-Asturias-2026.jpg\",\"width\":1014,\"height\":674,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"datePublished\":\"2025-09-20T20:26:47+02:00\",\"dateModified\":\"2025-09-20T20:26:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#webpage\"},\"articleSection\":\"Actualidad Asturias, Titulares, Asturias\",\"dateline\":\"Publicado el septiembre 20, 2025.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/\",\"name\":\"NBAsturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"NBAsturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/\",\"name\":\"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias\",\"description\":\"El presidente del Principado de Asturias, Adri\\u00e1n Barb\\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\\u00e1n las Medallas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/author\\\/nbasturias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Medallas-de-Asturias-2026.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#mainImage\",\"width\":1014,\"height\":674,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/medallas-de-asturias-2026-los-galardonados\\\/#mainImage\"},\"datePublished\":\"2025-09-20T20:26:47+02:00\",\"dateModified\":\"2025-09-20T20:26:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Medallas de Asturias 2026: Los galardonados | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias","description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/","robots":"max-image-preview:large","keywords":"actualidad asturias,titulares","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/#listItem","name":"Titulares"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/#listItem","position":2,"name":"Titulares","item":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#listItem","name":"Medallas de Asturias 2026: Los galardonados"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#listItem","position":3,"name":"Medallas de Asturias 2026: Los galardonados","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/#listItem","name":"Titulares"}}]},{"@type":"NewsArticle","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#newsarticle","name":"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias","headline":"Medallas de Asturias 2026: Los galardonados","author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg","width":1014,"height":674,"caption":"Foto: Prensa Gobierno de Asturias"},"datePublished":"2025-09-20T20:26:47+02:00","dateModified":"2025-09-20T20:26:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#webpage"},"articleSection":"Actualidad Asturias, Titulares, Asturias","dateline":"Publicado el septiembre 20, 2025."},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author","url":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/","name":"NBAsturias","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"NBAsturias"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/","name":"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias","description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/author\/nbasturias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#mainImage","width":1014,"height":674,"caption":"Foto: Prensa Gobierno de Asturias"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/#mainImage"},"datePublished":"2025-09-20T20:26:47+02:00","dateModified":"2025-09-20T20:26:47+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias","og:description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/","og:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg","og:image:width":1014,"og:image:height":674,"article:published_time":"2025-09-20T18:26:47+00:00","article:modified_time":"2025-09-20T18:26:47+00:00","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Medallas de Asturias 2026: Los galardonados | El Digital de Asturias","twitter:description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas","twitter:creator":"@bercodi","twitter:image":"https:\/\/eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2025\/09\/Medallas-de-Asturias-2026.jpg"},"aioseo_meta_data":{"post_id":"11058","title":null,"description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha informado al Consejo de Gobierno de las personas e instituciones que recibir\u00e1n las Medallas","keywords":null,"keyphrases":{"focus":{"keyphrase":"Asturias","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Medallas","score":80,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:51:15","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-20 18:17:07","updated":"2026-05-15 10:51:15","focus_keyword":"Asturias","additional_keywords":[{"word":"Medallas","score":80}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/\" title=\"Titulares\">Titulares<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMedallas de Asturias 2026: Los galardonados\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Titulares","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/titulares\/"},{"label":"Medallas de Asturias 2026: Los galardonados","link":"https:\/\/eldigitaldeasturias.com\/radio\/medallas-de-asturias-2026-los-galardonados\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/11058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/comments?post=11058"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts\/11058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media\/11059"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/media?parent=11058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories?post=11058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/tags?post=11058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}