{"id":38,"count":478,"description":"","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","name":"Live","slug":"live","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"consumo,salud,belleza,mundo curioso,\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias | Diario de informaci\u00f3n y noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Live | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@bercodi\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Live | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"name\":\"Live\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/category\\\/live\\\/#listItem\",\"position\":2,\"name\":\"Live\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#collectionpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/\",\"name\":\"Live | El Digital de Asturias\",\"description\":\"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\\u00e1cticos y contenidos \\u00fatiles sobre sociedad, h\\u00e1bitos y cultura cotidiana.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\",\"name\":\"El digital de Asturias Radio\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/radio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/x.com\\\/bercodi\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Diario de informaci\\u00f3n y noticias\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/radio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Live | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Live | El Digital de Asturias","description":"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.","canonical_url":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","robots":"max-image-preview:large","keywords":"consumo,salud,belleza,mundo curioso,","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","position":1,"name":"Inicio","item":"https:\/\/eldigitaldeasturias.com\/radio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","name":"Live"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/#listItem","position":2,"name":"Live","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/radio#listItem","name":"Inicio"}}]},{"@type":"CollectionPage","@id":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38\/#collectionpage","url":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38\/","name":"Live | El Digital de Asturias","description":"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization","name":"El digital de Asturias Radio","description":"Diario de informaci\u00f3n y noticias","url":"https:\/\/eldigitaldeasturias.com\/radio\/","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/x.com\/bercodi","https:\/\/www.instagram.com\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/radio\/#website","url":"https:\/\/eldigitaldeasturias.com\/radio\/","name":"El Digital de Asturias","description":"Diario de informaci\u00f3n y noticias","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/radio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias | Diario de informaci\u00f3n y noticias","og:type":"article","og:title":"Live | El Digital de Asturias","og:description":"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.","og:url":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/","og:image":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","og:image:secure_url":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg","twitter:card":"summary_large_image","twitter:site":"@bercodi","twitter:title":"Live | El Digital de Asturias","twitter:description":"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/radio\/wp-content\/uploads\/2021\/03\/EDA.jpg"},"aioseo_meta_data":{"term_id":"38","title":null,"description":"Estilo de vida desde Asturias: ideas, tendencias, consejos pr\u00e1cticos y contenidos \u00fatiles sobre sociedad, h\u00e1bitos y cultura cotidiana.","keywords":[{"label":"consumo","value":"consumo"},{"label":"salud","value":"salud"},{"label":"belleza","value":"belleza"},{"label":"mundo curioso","value":"mundo curioso"},{"label":"","value":""}],"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"none","priority":1,"frequency":"always","local_seo":null,"seo_analyzer_scan_date":"2026-05-14 16:43:10","breadcrumb_settings":null,"created":"2021-06-26 11:15:00","updated":"2026-05-14 16:43:10","pillar_content":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/radio\" title=\"Inicio\">Inicio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLive\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/eldigitaldeasturias.com\/radio"},{"label":"Live","link":"https:\/\/eldigitaldeasturias.com\/radio\/category\/live\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/eldigitaldeasturias.com\/radio\/wp-json\/wp\/v2\/posts?categories=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}