{"id":99396,"date":"2019-05-17T22:55:26","date_gmt":"2019-05-17T22:55:26","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/magazine365\/?p=99396"},"modified":"2019-05-17T22:55:26","modified_gmt":"2019-05-17T22:55:26","slug":"quien-es-billy-muebles-famosos-y-sus-historias","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/","title":{"rendered":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-99397\" src=\"http:\/\/www.eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-357x300.jpg\" alt=\"\" width=\"357\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-357x300.jpg 357w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-650x546.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-768x645.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-150x126.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-450x378.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-696x584.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles-500x420.jpg 500w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg 803w\" sizes=\"(max-width: 357px) 100vw, 357px\" \/>(dpa) &#8211; \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho&#8230; una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y otros caen r\u00e1pidamente en el olvido. Repasemos algunos de los que m\u00e1s llamaron la atenci\u00f3n.<\/p>\n<p>Billy, del fabricante sueco de muebles Ikea, lleva el nombre de Billy Liljedahl. En realidad fue su compa\u00f1ero Gillis Lundgren el que dise\u00f1\u00f3 el mueble en 1979 para Liljedahl. En aquel momento, seg\u00fan cuenta la historia, Billy estaba necesitando una \u00abbuena\u00bb estanter\u00eda, algo que le fuera realmente \u00fatil, y se la encarg\u00f3 a Lundgren. Hoy el dise\u00f1o cumple 40 a\u00f1os y este famoso mueble se produce unas 4,5 millones de veces al a\u00f1o.<\/p>\n<p>Con el tiempo se volvi\u00f3 tan popular que en 1992 Ikea fue blanco de protestas cuando decidi\u00f3 dejar de fabricarla. \u00abNos insultaron. Nos alabaron. Finalmente nos sobornaron y lo lograron: Billy ha vuelto\u00bb, dec\u00eda el comercial de Ikea poco despu\u00e9s de que la empresa reanudara la producci\u00f3n.<\/p>\n<p>Muchos muebles tienen este tipo de historia, y algunos suelen ser una especie de testigos de toda una \u00e9poca. Muchos hicieron furor porque de alg\u00fan modo condensaron las posibilidades que ofrec\u00edan los nuevos materiales y sus nuevas aplicaciones en la producci\u00f3n.<\/p>\n<p>Un buen ejemplo es la silla 214 de la firma Thonet del siglo XIX. El modelo fue vendido 50 millones de veces s\u00f3lo hasta 1930 y fue copiado exponencialmente. Actualmente casi todos conocen la 214 aunque no lo sepan: es el dise\u00f1o que en algunas partes se conoce como \u00absilla vienesa\u00bb.<\/p>\n<p>Es de madera, de l\u00edneas sencillas, y tiene la superficie para sentarse de esterilla. Se la vio en cientos de caf\u00e9s y restaurantes, por ejemplo en el caf\u00e9 de la Torre Eiffel en Par\u00eds. Cuenta la leyenda (difundida por el propio Thonet) que una de estas sillas cay\u00f3 en 1889 desde una altura de 57 metros y no sufri\u00f3 ning\u00fan da\u00f1o.<\/p>\n<p>El dise\u00f1o data del a\u00f1o 1859. Fue una creaci\u00f3n del maestro carpintero germano-austr\u00edaco Michael Thonet, que logr\u00f3 dar elasticidad a cortes largos y rectos de madera aplicando presi\u00f3n y calor por medio de vapor. Fue la piedra fundamental para poder producirla en serie y en masa. La silla, actualmente, sigue siendo producida de la misma manera que por entonces.<\/p>\n<p>Hay otra silla que much\u00edsimas personas tienen en casa, sea en original o en copia: la superficie del respaldo y la zona para sentarse est\u00e1n compuestas de una pieza de pl\u00e1stico y esa pieza est\u00e1 colocada sobre unas patas finas de madera o de metal. Son las \u00abplastic chairs\u00bb concebidas por una dupla de dise\u00f1adores estadounidenses, Charles y Ray Eames.<\/p>\n<p>Los dise\u00f1adores entregaron su propuesta en 1948 en un concurso de dise\u00f1o de muebles econ\u00f3micos. Quer\u00edan ofrecer una silla que pudiera ser fabricada industrialmente y ser utilizada en el \u00e1mbito privado. Como la versi\u00f3n original con zona alta de metal era demasiado costosa, buscaron alternativas m\u00e1s baratas y se toparon con la resina de poli\u00e9ster reforzada con fibra de vidrio, que comenz\u00f3 a venderse a partir de 1950.<\/p>\n<p>Seg\u00fan la compa\u00f1\u00eda Vitra, fueron las primeras sillas de pl\u00e1stico que fueron fabricadas en forma serial. Tras una breve pausa, volvieron a ser fabricadas en los a\u00f1os 90 con polipropileno, que resulta m\u00e1s econ\u00f3mico y m\u00e1s ecol\u00f3gico que la fibra de vidrio.<\/p>\n<p>La primera silla que fue fabricada completamente en una \u00fanica pieza de pl\u00e1stico fue la Panton Chair, tambi\u00e9n de Vitra. Su desarrollo llev\u00f3 un tiempo extraordinario. Si bien el dise\u00f1o ya exist\u00eda en la d\u00e9cada del 50, no se fabric\u00f3 hasta 1999 tal como hab\u00eda sido pensada. Eso fue, lamentablemente, posterior a la muerte de su dise\u00f1ador, el dan\u00e9s Verner Panton (1926-1998).<\/p>\n<p>El problema era el pl\u00e1stico. Vitra dec\u00eda que era un \u00abdesaf\u00edo casi imposible\u00bb hacer confluir la forma tal cual la hab\u00eda concebido su dise\u00f1ador con las posibilidades que exist\u00edan por ese entonces en el trabajo con pl\u00e1stico.<\/p>\n<p>Y ese fue un problema que persisti\u00f3 hasta los 90. Fue realmente s\u00f3lo en 1999 que se logr\u00f3 una soluci\u00f3n tal como la hab\u00eda pensado Vernon Panton desde un primer momento. Y entonces, gracias a un nuevo procedimiento de inyecci\u00f3n de polipropileno, se pudo fabricar la silla a un precio accesible.<\/p>\n<p>Las sillas han marcado innumerable cantidad de veces la historia del dise\u00f1o. Otro caso fue el de la Tulip Chair del dise\u00f1ador estadounidense de origen finland\u00e9s Eero Saarinen para Knoll International. O el de la mesa que llevaba el mismo nombre. Su forma alude de alg\u00fan modo a una tulipa. La parte superior es sostenida por una \u00fanica pieza que tiene un pie que se va ensanchando en la parte baja.<\/p>\n<p>El creador dijo en su momento que, con este dise\u00f1o, quer\u00eda ponerle un punto final \u00abal mundo espantoso, confuso y desasosegado\u00bb que se manifiesta sobre todo en la zona de los pies de mesas y sillas.<\/p>\n<p>El dise\u00f1o le llev\u00f3 cinco a\u00f1os. Hoy esos muebles est\u00e1n entre los cl\u00e1sicos. Tanto la mesa como la silla fueron copiadas innumerables veces, y todos tenemos su forma en la retina. Las hemos visto. S\u00f3lo desconoc\u00edamos su historia. Knoll Intnernational sigui\u00f3 produciendo la Colecci\u00f3n Pedestal desde 1958 sin parar.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Simone Andrea Mayer (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho&#8230; una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y<\/p>\n","protected":false},"author":1,"featured_media":99397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[213],"tags":[],"class_list":["post-99396","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hogar"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"hogar\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"803\" \/>\n\t\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-17T22:55:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-17T22:55:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#article\",\"name\":\"\\u00bfQui\\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias\",\"headline\":\"\\u00bfQui\\u00e9n es Billy? Muebles famosos y sus historias\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/hisorias-de-muebles.jpg\",\"width\":803,\"height\":674},\"datePublished\":\"2019-05-17T22:55:26+02:00\",\"dateModified\":\"2019-05-17T22:55:26+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#webpage\"},\"articleSection\":\"Hogar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/#listItem\",\"position\":2,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#listItem\",\"name\":\"\\u00bfQui\\u00e9n es Billy? Muebles famosos y sus historias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfQui\\u00e9n es Billy? Muebles famosos y sus historias\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/#listItem\",\"name\":\"Hogar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/\",\"name\":\"\\u00bfQui\\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias\",\"description\":\"(dpa) - \\u00a1Qui\\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\\u00eda de Ikea que prendi\\u00f3 como la p\\u00f3lvora. \\u00bfAlguien sabe por qu\\u00e9 se llama as\\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\\u00f1o, otros se convierten en un producto muy popular y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/hisorias-de-muebles.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#mainImage\",\"width\":803,\"height\":674},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/quien-es-billy-muebles-famosos-y-sus-historias\\\/#mainImage\"},\"datePublished\":\"2019-05-17T22:55:26+02:00\",\"dateModified\":\"2019-05-17T22:55:26+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias","description":"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/","robots":"max-image-preview:large","keywords":"hogar","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#article","name":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias","headline":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg","width":803,"height":674},"datePublished":"2019-05-17T22:55:26+02:00","dateModified":"2019-05-17T22:55:26+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#webpage"},"articleSection":"Hogar"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/#listItem","position":2,"name":"Hogar","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#listItem","name":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#listItem","position":3,"name":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/#listItem","name":"Hogar"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/","name":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias","description":"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#mainImage","width":803,"height":674},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/#mainImage"},"datePublished":"2019-05-17T22:55:26+02:00","dateModified":"2019-05-17T22:55:26+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias","og:description":"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg","og:image:width":803,"og:image:height":674,"article:published_time":"2019-05-17T22:55:26+00:00","article:modified_time":"2019-05-17T22:55:26+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias | El Digital de Asturias","twitter:description":"(dpa) - \u00a1Qui\u00e9n no conoce a Billy! O mejor dicho... una Billy. Se trata de una estanter\u00eda de Ikea que prendi\u00f3 como la p\u00f3lvora. \u00bfAlguien sabe por qu\u00e9 se llama as\u00ed? Muchos muebles llevan un nombre. Algunos alcanzan una fama inusitada en la historia del dise\u00f1o, otros se convierten en un producto muy popular y","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/05\/hisorias-de-muebles.jpg"},"aioseo_meta_data":{"post_id":"99396","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 06:16:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:45:25","updated":"2026-05-26 06:16:01","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/\" title=\"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias\">\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Hogar","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/"},{"label":"\u00bfQui\u00e9n es Billy? Muebles famosos y sus historias","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/quien-es-billy-muebles-famosos-y-sus-historias\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/99396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=99396"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/99396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/99397"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=99396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=99396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=99396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}