{"id":97704,"date":"2019-02-24T20:21:56","date_gmt":"2019-02-24T20:21:56","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/magazine365\/?p=97704"},"modified":"2019-02-24T20:21:56","modified_gmt":"2019-02-24T20:21:56","slug":"doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/","title":{"rendered":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-97705\" src=\"http:\/\/www.eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-650x433.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-768x512.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-1536x1024.jpg 1536w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-2048x1365.jpg 2048w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-1200x800.jpg 1200w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-696x464.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-1068x712.jpg 1068w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-630x420.jpg 630w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la est\u00e9tica y la vida de cada uno . Porque hay una cosa que ya se sabe: La cocina no es solo una estancia donde se guisa, se ensucia y se limpia sino un lugar mucho m\u00e1s abierto e interesante donde poder mirar, sentir, hablar y\u00a0pensar.<\/p>\n<p>Sobre esta premisa fundamental est\u00e1 trabajando\u00a0<span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.doca.es\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><strong>DOCA<\/strong><\/a><\/span>\u00a0desde 1978, y as\u00ed es como ha llegado a establecer una comunicaci\u00f3n muy natural entre arquitectura, interiorismo y gastronom\u00eda. Tres disciplinas que, adem\u00e1s, pueden ser muy distintas y que por esa raz\u00f3n esta compa\u00f1\u00eda internacional las atiende con m\u00e1s de doscientos acabados en diferentes estilos. Pero siempre mediante una comunicaci\u00f3n fluida y honesta entre esos tres prescriptores.<\/p>\n<p>Dentro de la corriente \u201ctransitional\u201d, un estilo que viaja con desenvoltura entre lo cl\u00e1sico y lo contempor\u00e1neo, entre la tecnolog\u00eda y la artesan\u00eda, DOCA ha desvelado este a\u00f1o su modelo STEP. La l\u00f3gica de la evoluci\u00f3n aparece de nuevo en sus dise\u00f1os porque en esta ocasi\u00f3n proponen nogal macizo y vitrinas enmarcadas en acero, pero a\u00f1aden, atenci\u00f3n, la magia de las puertas correderas coplanar, un innovador sistema que mantiene las dos hojas en el mismo plano cuando est\u00e1n cerradas. Exactitud, pureza, armon\u00eda. Y un gobierno absoluto del espacio porque existe la posibilidad de que esas puertas se puedan abrir y cerrar mediante control remoto. Anticipaci\u00f3n.<\/p>\n<p>En el stand de DOCA se han visto puertas de acero de 12 mm que ignoran absolutamente el paso del tiempo, paneles armados con el robusto tablero fen\u00f3lico, bisagras imposibles que se abren hasta 270 grados, cajoneras que se deslizan el\u00e9ctricamente con solo tocarlas, chapas de maderas nobles y materiales formidables. Es as\u00ed como el dise\u00f1o no encuentra l\u00edmites para avanzar.<\/p>\n<p>Y todo este\u00a0<em>background\u00a0<\/em>se materializa, adem\u00e1s, en dos sorprendentes propuestas de vestidores que interpretan la intimidad de la alcoba con el mismo concepto de est\u00e9tica, resistencia y funcionalidad. Mas una aportaci\u00f3n extra de confort. Puertas de piel, estantes de madera natural, accesorios que no se imaginaban pero que ya parecen totalmente imprescindibles y una iluminaci\u00f3n tan c\u00e1lida y sugerente como los mejores sue\u00f1os.<\/p>\n<p>Profesionales de diversos pa\u00edses como Estados Unidos, Inglaterra, Emiratos \u00c1rabes, India, China o Azerbaiy\u00e1n han estado en el stand de DOCA de Espacio Cocina SICI 2019 para comprobar personalmente el proceso de esa evoluci\u00f3n.<\/p>\n<p>Comunicaci\u00f3n entre arquitectura, interiorismo y gastronom\u00eda. Esa es la idea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la<\/p>\n","protected":false},"author":1,"featured_media":97705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[213],"tags":[],"class_list":["post-97704","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hogar"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"hogar\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-24T20:21:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-24T20:21:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#article\",\"name\":\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias\",\"headline\":\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/1550663623_Doca_Valencia_3-scaled.jpg\",\"width\":2560,\"height\":1706},\"datePublished\":\"2019-02-24T20:21:56+01:00\",\"dateModified\":\"2019-02-24T20:21:56+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#webpage\"},\"articleSection\":\"Hogar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/#listItem\",\"position\":2,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#listItem\",\"name\":\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#listItem\",\"position\":3,\"name\":\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/hogar\\\/#listItem\",\"name\":\"Hogar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/\",\"name\":\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias\",\"description\":\"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/1550663623_Doca_Valencia_3-scaled.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#mainImage\",\"width\":2560,\"height\":1706},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\\\/#mainImage\"},\"datePublished\":\"2019-02-24T20:21:56+01:00\",\"dateModified\":\"2019-02-24T20:21:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias","description":"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/","robots":"max-image-preview:large","keywords":"hogar","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#article","name":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias","headline":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg","width":2560,"height":1706},"datePublished":"2019-02-24T20:21:56+01:00","dateModified":"2019-02-24T20:21:56+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#webpage"},"articleSection":"Hogar"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/#listItem","position":2,"name":"Hogar","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#listItem","name":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#listItem","position":3,"name":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/#listItem","name":"Hogar"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/","name":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias","description":"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#mainImage","width":2560,"height":1706},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/#mainImage"},"datePublished":"2019-02-24T20:21:56+01:00","dateModified":"2019-02-24T20:21:56+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias","og:description":"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg","og:image:width":2560,"og:image:height":1706,"article:published_time":"2019-02-24T20:21:56+00:00","article:modified_time":"2019-02-24T20:21:56+00:00","twitter:card":"summary_large_image","twitter:title":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019 | El Digital de Asturias","twitter:description":"La idea es sencilla y extremadamente compleja al mismo tiempo. Consiste en poder cortar una simple zanahoria con la m\u00e1xima elegancia en casa pero con la misma naturalidad que si se hiciese en los fogones de un conocido restaurante. Se trata de crear un entorno perfectamente acorde con la forma de entender el espacio, la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2019\/02\/1550663623_Doca_Valencia_3-scaled.jpg"},"aioseo_meta_data":{"post_id":"97704","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 02:35:05","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:47:29","updated":"2026-05-26 02:35:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/\" title=\"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019\">Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Hogar","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/hogar\/"},{"label":"Doca presenta un nuevo concepto de cocina en Espacio Cocina SICI 2019","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/doca-presenta-un-nuevo-concepto-de-cocina-en-espacio-cocina-sici-2019\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/97704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=97704"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/97704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/97705"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=97704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=97704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=97704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}