{"id":94336,"date":"2018-09-02T14:21:40","date_gmt":"2018-09-02T14:21:40","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/magazine365\/?p=94336"},"modified":"2018-09-02T14:21:40","modified_gmt":"2018-09-02T14:21:40","slug":"el-secreto-de-una-buena-barbacoa","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/","title":{"rendered":"El \u201csecreto\u201d de una buena barbacoa"},"content":{"rendered":"<figure id=\"attachment_94337\" aria-describedby=\"caption-attachment-94337\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-94337\" src=\"http:\/\/www.eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-360x233.jpg\" alt=\"\" width=\"360\" height=\"233\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-360x233.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-650x420.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-768x496.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-150x97.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-450x291.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa-696x450.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg 980w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-94337\" class=\"wp-caption-text\">Jenjibre, soja, ajo, ketchup y az\u00facar permiten preparar una salsa fant\u00e1stica para la barbacoa. Foto: Doreen Hassek\/dpa-tmn<\/figcaption><\/figure>\n<p>(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta:<\/p>\n<p>Ingredientes para 500 ml:<\/p>\n<p>250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2 dientes de ajo, 2 cucharadas de jenjibre fresco, 65 gramos de az\u00facar negra, 40 ml de vinagre de vino.<\/p>\n<p>Preparaci\u00f3n:<\/p>\n<p>1. Lavar los cebollines, el ajo y el jenjibre y picar peque\u00f1o. Colocar en una olla con el resto de los ingredientes y hervir revolviendo permanentemente.<\/p>\n<p>2. Reducir la temperatura y dejar hervir suavemente la salsa al menos 10 minutos con la olla destapada, hasta que tenga una consistencia l\u00edquida pero algo espesa. Enfriar hasta el momento de consumirla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2<\/p>\n","protected":false},"author":1,"featured_media":94337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-94336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sabores"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"sabores\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t\t<meta property=\"og:image:height\" content=\"633\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-09-02T14:21:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-09-02T14:21:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#article\",\"name\":\"El \\u201csecreto\\u201d de una buena barbacoa | El Digital de Asturias\",\"headline\":\"El \\u201csecreto\\u201d de una buena barbacoa\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/salsa-barbacoa.jpg\",\"width\":980,\"height\":633,\"caption\":\"Jenjibre, soja, ajo, ketchup y az\\u00facar permiten preparar una salsa fant\\u00e1stica para la barbacoa. Foto: Doreen Hassek\\\/dpa-tmn\"},\"datePublished\":\"2018-09-02T14:21:40+02:00\",\"dateModified\":\"2018-09-02T14:21:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#webpage\"},\"articleSection\":\"Sabores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/sabores\\\/#listItem\",\"name\":\"Sabores\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/sabores\\\/#listItem\",\"position\":2,\"name\":\"Sabores\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/sabores\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#listItem\",\"name\":\"El \\u201csecreto\\u201d de una buena barbacoa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#listItem\",\"position\":3,\"name\":\"El \\u201csecreto\\u201d de una buena barbacoa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/sabores\\\/#listItem\",\"name\":\"Sabores\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/\",\"name\":\"El \\u201csecreto\\u201d de una buena barbacoa | El Digital de Asturias\",\"description\":\"(dpa) Pocas cosas m\\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/salsa-barbacoa.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#mainImage\",\"width\":980,\"height\":633,\"caption\":\"Jenjibre, soja, ajo, ketchup y az\\u00facar permiten preparar una salsa fant\\u00e1stica para la barbacoa. Foto: Doreen Hassek\\\/dpa-tmn\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-secreto-de-una-buena-barbacoa\\\/#mainImage\"},\"datePublished\":\"2018-09-02T14:21:40+02:00\",\"dateModified\":\"2018-09-02T14:21:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias","description":"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/","robots":"max-image-preview:large","keywords":"sabores","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#article","name":"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias","headline":"El \u201csecreto\u201d de una buena barbacoa","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg","width":980,"height":633,"caption":"Jenjibre, soja, ajo, ketchup y az\u00facar permiten preparar una salsa fant\u00e1stica para la barbacoa. Foto: Doreen Hassek\/dpa-tmn"},"datePublished":"2018-09-02T14:21:40+02:00","dateModified":"2018-09-02T14:21:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#webpage"},"articleSection":"Sabores"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/#listItem","name":"Sabores"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/#listItem","position":2,"name":"Sabores","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#listItem","name":"El \u201csecreto\u201d de una buena barbacoa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#listItem","position":3,"name":"El \u201csecreto\u201d de una buena barbacoa","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/#listItem","name":"Sabores"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/","name":"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias","description":"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#mainImage","width":980,"height":633,"caption":"Jenjibre, soja, ajo, ketchup y az\u00facar permiten preparar una salsa fant\u00e1stica para la barbacoa. Foto: Doreen Hassek\/dpa-tmn"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/#mainImage"},"datePublished":"2018-09-02T14:21:40+02:00","dateModified":"2018-09-02T14:21:40+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias","og:description":"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg","og:image:width":980,"og:image:height":633,"article:published_time":"2018-09-02T14:21:40+00:00","article:modified_time":"2018-09-02T14:21:40+00:00","twitter:card":"summary_large_image","twitter:title":"El \u201csecreto\u201d de una buena barbacoa | El Digital de Asturias","twitter:description":"(dpa) Pocas cosas m\u00e1s bonitas que reunir a los amigos alrededor de una buena barbacoa el domingo al mediod\u00eda. Sin embargo, para destacar el sabor de la carne, conviene tener siempre a mano una salsa especial como esta: Ingredientes para 500 ml: 250 g de ketchup, 80 ml de salsa de soja, 4 cebollines, 2","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2018\/09\/salsa-barbacoa.jpg"},"aioseo_meta_data":{"post_id":"94336","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 19:20:46","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:59:00","updated":"2026-05-25 19:20:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/\" title=\"Sabores\">Sabores<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/\" title=\"El \u201csecreto\u201d de una buena barbacoa\">El \u201csecreto\u201d de una buena barbacoa<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Sabores","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/"},{"label":"El \u201csecreto\u201d de una buena barbacoa","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-secreto-de-una-buena-barbacoa\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/94336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=94336"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/94336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/94337"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=94336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=94336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=94336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}