{"id":86110,"date":"2017-04-19T12:14:45","date_gmt":"2017-04-19T10:14:45","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=86110"},"modified":"2017-04-19T12:14:45","modified_gmt":"2017-04-19T10:14:45","slug":"los-misterios-sin-resolver-de-los-andes","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/","title":{"rendered":"Los misterios sin resolver de los Andes"},"content":{"rendered":"<p>La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-86111\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press-282x300.jpg\" alt=\"\" width=\"282\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press-282x300.jpg 282w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press-150x160.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press-450x479.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg 465w\" sizes=\"(max-width: 282px) 100vw, 282px\" \/>Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado que a\u00fan hoy asombra a estudiosos y que lleva a m\u00faltiples interpretaciones. Es lo que ocurre con los restos arqueol\u00f3gicos encontrados en Tiahuanaco.<\/p>\n<p>Tiahuanaco es una de las ciudades arqueol\u00f3gicas m\u00e1s importantes de Sudam\u00e9rica, situada a tan s\u00f3lo 15 kil\u00f3metros del Lago Titicaca. Aunque actualmente pertenece a territorio boliviano, hist\u00f3ricamente ha estado ligado con Per\u00fa. La importante cultura prehisp\u00e1nica que se desarroll\u00f3 en esta zona andina ha permitido poder contar con un legado que ha llevado a muchos a considerarla, en realidad, la cultura madre de las civilizaciones que luego poblar\u00edan lo que hoy conocemos como Sudam\u00e9rica.<\/p>\n<p>Uno de los grandes misterios que siempre han rodeado a esta cultura ha tenido que ver con el hecho de su desaparici\u00f3n all\u00e1 por el a\u00f1o 1000, dejando tras ella muchos de los petroglifos y geoglifos que quedaron atr\u00e1s y que, seg\u00fan interpretaciones, daban a entender un contacto con otras civilizaciones, en muchos casos, incluso m\u00e1s avanzadas que las que entonces conviv\u00edan en estos parajes Sudamericanos.<\/p>\n<p>Al igual que en el caso de las Pir\u00e1mides de Egipto, donde se demostr\u00f3 c\u00f3mo fue posible la construcci\u00f3n sin ninguna otra ayuda que los medios de los que dispon\u00edan, hay algunos misterios en Per\u00fa que a\u00fan no se han podido responder. Una nueva web, <a href=\"http:\/\/extraterrestre.pe\" target=\"_blank\"><span style=\"color: #000000;\"><strong>http:\/\/extraterrestre.pe<\/strong><\/span><\/a>, trata de dar respuesta a alguna de estas preguntas que a\u00fan siguen sin respuesta. Bas\u00e1ndose en los rasgos de algunas de las figuras que se repiten en Tiahuanaco se ha dado a entender , seg\u00fan conclusiones de muchos estudiosos, que se trata de un dios astronauta.<\/p>\n<p>Sobre estas teor\u00edas y muchas otras variantes de los estudios realizados en Nazca y en Tiahuanaco, surge esta nueva web. Sobre todo si se toman como referencia los Escritos del Sol para descifrar c\u00f3mo la influencia de este dios benefici\u00f3 a los pueblos andinos. S\u00f3lo basta con ver, entre los restos de este \u00e1rea, la puerta dedicada al Sol y a la Luna para entender la relevancia de los astros.<\/p>\n<p>Como se puede comprobar, el misterio precolombino a\u00fan hoy no est\u00e1 del todo resuelto. Tiahuanaco, una antigua ciudad de Alto Per\u00fa, hoy Bolivia, sigue teniendo cosas por descifrar, im\u00e1genes que interpretar y leyendas que acumular.<\/p>\n<p>Vinculado, adem\u00e1s, a esto est\u00e1n las famosas L\u00edneas de Nazca y el reconstruido Disco Solar del Cusco, formando un misterio singular que empieza de nuevo a atraer la mirada de los amantes de la cultura de los pueblos precolombinos.<\/p>\n<p>Tras echar un vistazo a las interpretaciones de los dioses y de los dibujos que aparecieron, surgen nuevas teor\u00edas a las que agarrarse y que pueden ser enunciadas en la nueva web peruana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado<\/p>\n","protected":false},"author":1,"featured_media":86111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[199],"tags":[],"class_list":["post-86110","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo-curioso"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"mundo curioso\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los misterios sin resolver de los Andes | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"465\" \/>\n\t\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-19T10:14:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-04-19T10:14:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los misterios sin resolver de los Andes | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#article\",\"name\":\"Los misterios sin resolver de los Andes | El Digital de Asturias\",\"headline\":\"Los misterios sin resolver de los Andes\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Dios-Pescador-Iberian-Press.jpg\",\"width\":465,\"height\":495},\"datePublished\":\"2017-04-19T12:14:45+02:00\",\"dateModified\":\"2017-04-19T12:14:45+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#webpage\"},\"articleSection\":\"Mundo Curioso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/#listItem\",\"name\":\"Mundo Curioso\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/#listItem\",\"position\":2,\"name\":\"Mundo Curioso\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#listItem\",\"name\":\"Los misterios sin resolver de los Andes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#listItem\",\"position\":3,\"name\":\"Los misterios sin resolver de los Andes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/#listItem\",\"name\":\"Mundo Curioso\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/\",\"name\":\"Los misterios sin resolver de los Andes | El Digital de Asturias\",\"description\":\"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Dios-Pescador-Iberian-Press.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#mainImage\",\"width\":465,\"height\":495},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-misterios-sin-resolver-de-los-andes\\\/#mainImage\"},\"datePublished\":\"2017-04-19T12:14:45+02:00\",\"dateModified\":\"2017-04-19T12:14:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los misterios sin resolver de los Andes | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los misterios sin resolver de los Andes | El Digital de Asturias","description":"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/","robots":"max-image-preview:large","keywords":"mundo curioso","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#article","name":"Los misterios sin resolver de los Andes | El Digital de Asturias","headline":"Los misterios sin resolver de los Andes","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg","width":465,"height":495},"datePublished":"2017-04-19T12:14:45+02:00","dateModified":"2017-04-19T12:14:45+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#webpage"},"articleSection":"Mundo Curioso"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/#listItem","name":"Mundo Curioso"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/#listItem","position":2,"name":"Mundo Curioso","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#listItem","name":"Los misterios sin resolver de los Andes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#listItem","position":3,"name":"Los misterios sin resolver de los Andes","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/#listItem","name":"Mundo Curioso"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/","name":"Los misterios sin resolver de los Andes | El Digital de Asturias","description":"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#mainImage","width":465,"height":495},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/#mainImage"},"datePublished":"2017-04-19T12:14:45+02:00","dateModified":"2017-04-19T12:14:45+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Los misterios sin resolver de los Andes | El Digital de Asturias","og:description":"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg","og:image:width":465,"og:image:height":495,"article:published_time":"2017-04-19T10:14:45+00:00","article:modified_time":"2017-04-19T10:14:45+00:00","twitter:card":"summary_large_image","twitter:title":"Los misterios sin resolver de los Andes | El Digital de Asturias","twitter:description":"La cultura precolombina ha sido siempre uno de los grandes misterios a descifrar por los estudiosos. Arte, cultura y tradici\u00f3n se unieron en un momento vital en el que, con la llegada de los Europeos, supuso una ruptura con sus ra\u00edces. Sin embargo, antes siquiera de la llegada, ya habitaban pueblos que dejaron un legado","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2017\/04\/Dios-Pescador-Iberian-Press.jpg"},"aioseo_meta_data":{"post_id":"86110","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 02:16:23","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 14:29:31","updated":"2026-05-25 02:16:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/\" title=\"Mundo Curioso\">Mundo Curioso<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/\" title=\"Los misterios sin resolver de los Andes\">Los misterios sin resolver de los Andes<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Mundo Curioso","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/"},{"label":"Los misterios sin resolver de los Andes","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-misterios-sin-resolver-de-los-andes\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/86110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=86110"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/86110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/86111"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=86110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=86110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=86110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}