{"id":62717,"date":"2016-02-02T16:12:53","date_gmt":"2016-02-02T15:12:53","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62717"},"modified":"2016-02-02T16:12:53","modified_gmt":"2016-02-02T15:12:53","slug":"las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/","title":{"rendered":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62718\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-360x239.jpg\" alt=\"fotonoticia_20160129120204_800\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-650x431.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-768x510.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-696x462.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-633x420.jpg 633w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-121x79.jpg 121w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800-101x66.jpg 101w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE).<\/p>\n<p>Esta tasa de variaci\u00f3n es 1,2 puntos superior a la registrada en 2014, que fue del 3,5%. Este incremento se debi\u00f3 al aumento del 7,7% de las pernoctaciones de residentes y al incremento del 3% de las de no residentes.<\/p>\n<p>El 60% de las pernoctaciones se realizaron en apartamentos tur\u00edsticos, el 30% en campings, el 8% en alojamientos de turismo rural y el 2% restante en albergues.<\/p>\n<p>En el mes de diciembre, las pernoctaciones en alojamientos extrahoteleros aumentaron un 8,3% con respecto al mismo mes de 2014, hasta 5,7 millones. La estancia media fue de 5,4 pernoctaciones por viajero, con un aumento del 16,6% de los residentes y 5% de las de los no residentes.<\/p>\n<p>De junio a octubre hubo un repunte en las pernoctaciones, siendo agosto el mes con m\u00e1s pernoctaciones con 11,4 millones.<\/p>\n<p>Las pernoctaciones en el conjunto de alojamientos tur\u00edsticos colectivos espa\u00f1oles superaron los 422 millones de pernoctaciones en el conjunto del a\u00f1o, con un aumento del 4,5% respecto a 2014. Las de residentes crecieron un 5,9% y las de no residentes un 3,6%. La estancia media baj\u00f3 un 1,6% y se situ\u00f3 en 3,7 pernoctaciones por viajero.<\/p>\n<p>Del total de pernoctaciones, un 73% correspondi\u00f3 a hoteles y el 27% a alojamientos tur\u00edsticos extrahoteleros.<\/p>\n<p>POR CATEGOR\u00cdAS.<\/p>\n<p>Los principales mercados emisores en el conjunto de alojamientos tur\u00edsticos reglados fueron el brit\u00e1nico, con el 27,5% del total de pernoctaciones de no residentes, seguido del alem\u00e1n (21,6%) y el franc\u00e9s (9%).<\/p>\n<p>En 2015 se ocuparon el 35,2% de las plazas ofertadas en apartamentos tur\u00edsticos, un 5,9% m\u00e1s que un a\u00f1o antes. El grado de ocupaci\u00f3n medio en fin de semana se situ\u00f3 en un 36,1%, un aumento anual del 2,9%. El \u00cdndice e Precios en Apartamentos Tur\u00edsticos creci\u00f3 un 4,2%.<\/p>\n<p>Las pernoctaciones en apartamentos aumentaron un 2,9% en 2015, con un crecimiento del 8,2% de las de residentes y del 1,3% de los no residentes. Los viajeros no residentes, que representaron un 64,2% del total, realizaron el 75,8% de las pernoctaciones en apartamentos tur\u00edsticos.<\/p>\n<p>Reino Unido se consolid\u00f3 como primer mercado emisor en apartamentos tur\u00edsticos, con 18,3 millones de pernoctaciones, un 0,2% m\u00e1s que en 2014, siendo Alemania el siguiente mercado, con 8,1 millones de pernoctaciones, un 1,3% menos.<\/p>\n<p>Las pernoctaciones de los viajeros procedentes de Francia, Pa\u00edses Bajos y Suecia, siguientes mercados emisores, registraron tasas anuales del 6,8%, del 6,6% y del 4,8%, respectivamente.<\/p>\n<p>Canarias fue el destino preferido para alojarse en apartamentos, con 29,7 millones de pernoctaciones y un crecimiento del 2% respecto a 2014. Baleares fue el segundo destino con m\u00e1s de 9,5 millones de pernoctaciones, un 0,1% m\u00e1s.<\/p>\n<p>Canarias y las Islas Baleares fueron las regiones que presentaron el mayor grado de ocupaci\u00f3n, con el 74,4% y el 71,8% de los apartamentos ofertados, respectivamente.<\/p>\n<p>En 2015 y por zonas tur\u00edsticas, Tenerife, con m\u00e1s 9,8 millones pernoctaciones, fue la principal, seguida de Gran Canaria, con 8,8 millones, y Lanzarote, con 7,3 millones. Fuerteventura fue la que alcanz\u00f3 la mayor ocupaci\u00f3n con una media del 8,7%. Los puntos con mayor n\u00famero de pernoctaciones son San Bartolom\u00e9 de Tirajana, Arona y T\u00edas.<\/p>\n<p>UN 6,7% M\u00c1S EN CAMPINGS.<\/p>\n<p>Por su lado, los campamentos tur\u00edsticos registraron un aumento del 6,7% en 2015, con un aumento del 6% de los viajeros residentes y del 7,6% de los no residentes. En diciembre, registraron un aumento del 7,9%.<\/p>\n<p>Los campings ofrecieron de media 492.409 plazas, un 0,9% m\u00e1s, de las cuales se ocuparon el 38,2%, lo que supone un aumento del 3,7%. El grado de ocupaci\u00f3n de fin de semana alcanz\u00f3 el 40,5%, con un aumento del 2,9% m\u00e1s que en 2014. El \u00cdndice de Precios de Campings se increment\u00f3 de media un 0,5% en 2015.<\/p>\n<p>En el conjunto del a\u00f1o, Catalu\u00f1a fue el destino preferido para acampar, con m\u00e1s de 15,2 millones de pernoctaciones, un 4,3% m\u00e1s. El mayor grado de ocupaci\u00f3n se alcanz\u00f3 en La Rioja, con el 62% de las parcelas ofertadas.<\/p>\n<p>Por zonas, Costa Brava fue la opci\u00f3n mayoritaria, con 6,6 millones de pernoctaciones, mientras que la Costa Blanca fue le destino con mayor ocupaci\u00f3n, con una media del 14,3%. Benidorm, Mont-Roig del Camp y Torreoella de Montgr\u00ed fueron los puntos tur\u00edsticos que concentraron mayores pernoctaciones.<\/p>\n<p>EN CASAS RURALES CRECIERON UN 12,9%.<\/p>\n<p>Las pernoctaciones en alojamientos de turismo rural aumentaron un 12,9% en 2015 y alcanzaron los 8,7 millones. El \u00edndice de precios de alojamientos de turismo rural aument\u00f3 un 0,9% el a\u00f1o pasado. En el \u00faltimo mes del a\u00f1o, las pernoctaciones realizadas en casas rurales crecieron un 12,4%.<\/p>\n<p>Los viajeros espa\u00f1oles, que representaron un 83,3% del total, realizaron el 75,7% del total de las pernoctaciones. Las pernoctaciones de no residentes crecieron un 13,8%, frente al 10% de las de residentes.<\/p>\n<p>Los alojamientos de turismo rural ofrecieron de media 142.994 plazas, un 1,1% m\u00e1s que en 2014. El grado de ocupaci\u00f3n en fin de semana se situ\u00f3 en el 29.5%, un 13,1% m\u00e1s.<\/p>\n<p>Castilla y Le\u00f3n fue el destino preferido en esta clase de alojamientos, con 1,4 millones de pernoctaciones, un 4,6% m\u00e1s, seguido de Catalu\u00f1a, con 1,1 millones de pernoctaciones. Baleares fue el principal destino elegido por los no residentes, acumulando el 51,6% del total.<\/p>\n<p>Por zonas tur\u00edsticas, Mallorca es el principal destino, en ocupaci\u00f3n con el 51,7% de las plazas ofertadas y 689.322 pernoctaciones.<\/p>\n<p>CATALU\u00d1A, LA FAVORITA EN ALBERGUES.<\/p>\n<p>Las pernoctaciones en albergues crecieron un 0,8% en 2015 y alcanzaron los 2,2 millones. Las de residentes bajaron un 1,9%, mientras que las de no residentes aumentaron un 6,9%.<\/p>\n<p>Los albergues ofrecieron, de media, 23.517 plazas, un 0,4% menos que en 2014. El grado de ocupaci\u00f3n medio en fin de semana baj\u00f3 un 1,6% y se situ\u00f3 en el 33,5%.<\/p>\n<p>Por comunidades, Catalu\u00f1a fue el destino preferido, con 891.731 pernoctaciones, un 0,9% m\u00e1s que el a\u00f1o anterior. Le sigui\u00f3 el Pa\u00eds Vasco con 257.039 pernoctaciones y tambi\u00e9n por grado de ocupaci\u00f3n en plazas con el 28,5%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la<\/p>\n","protected":false},"author":1,"featured_media":62718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-62717","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-02T15:12:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-02T15:12:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#article\",\"name\":\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias\",\"headline\":\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160129120204_800.jpg\",\"width\":800,\"height\":531},\"datePublished\":\"2016-02-02T16:12:53+01:00\",\"dateModified\":\"2016-02-02T16:12:53+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#listItem\",\"name\":\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#listItem\",\"position\":3,\"name\":\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/\",\"name\":\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias\",\"description\":\"Las pernoctaciones realizadas en alojamientos tur\\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\\u00f1o anterior, seg\\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\\u00edstica (INE). Esta tasa de variaci\\u00f3n es 1,2 puntos superior a la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160129120204_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#mainImage\",\"width\":800,\"height\":531},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\\\/#mainImage\"},\"datePublished\":\"2016-02-02T16:12:53+01:00\",\"dateModified\":\"2016-02-02T16:12:53+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias","description":"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#article","name":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias","headline":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg","width":800,"height":531},"datePublished":"2016-02-02T16:12:53+01:00","dateModified":"2016-02-02T16:12:53+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#listItem","name":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#listItem","position":3,"name":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/","name":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias","description":"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#mainImage","width":800,"height":531},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/#mainImage"},"datePublished":"2016-02-02T16:12:53+01:00","dateModified":"2016-02-02T16:12:53+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias","og:description":"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg","og:image:width":800,"og:image:height":531,"article:published_time":"2016-02-02T15:12:53+00:00","article:modified_time":"2016-02-02T15:12:53+00:00","twitter:card":"summary_large_image","twitter:title":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones | El Digital de Asturias","twitter:description":"Las pernoctaciones realizadas en alojamientos tur\u00edsticos extrahoteleros (apartamentos, campings y alojamientos de turismo rural) alcanzaron los 113,8 millones en 2015, lo que supone un aumento del 4,7% con respecto al a\u00f1o anterior, seg\u00fan los datos difundidos este viernes por el Instituto Nacional de Estad\u00edstica (INE). Esta tasa de variaci\u00f3n es 1,2 puntos superior a la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129120204_800.jpg"},"aioseo_meta_data":{"post_id":"62717","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:59:03","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 12:32:50","updated":"2026-05-22 23:59:03"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/\" title=\"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones\">Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Las pernoctaciones extrahoteleras suben un 4,7% en 2015, hasta 113,8 millones","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-pernoctaciones-extrahoteleras-suben-un-47-en-2015-hasta-1138-millones\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62717"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62718"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}