{"id":62699,"date":"2016-02-02T15:49:32","date_gmt":"2016-02-02T14:49:32","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62699"},"modified":"2016-02-02T15:49:32","modified_gmt":"2016-02-02T14:49:32","slug":"suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/","title":{"rendered":"Suances acoge la I Gala Nacional del Surf este fin de semana"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62700\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-173x300.jpg\" alt=\"fotonoticia_20160129104110_800\" width=\"173\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-173x300.jpg 173w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-368x640.jpg 368w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-768x1335.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-150x261.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-450x782.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-696x1210.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800-242x420.jpg 242w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg 800w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/>El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha.<\/p>\n<p>La programaci\u00f3n con motivo de la I Gala Nacional del Surf arrancar\u00e1 este viernes con el encuentro &#8216;Surf ayer y hoy&#8217; que reunir\u00e1 a los pioneros de este deporte en Espa\u00f1a. Esta misma jornada se entregar\u00e1n los premios de la Copa de Espa\u00f1a de SUP y habr\u00e1 una fiesta de recepci\u00f3n para los participantes, en la que adem\u00e1s habr\u00e1 stands de marcas.<\/p>\n<p>La jornada del s\u00e1bado 30 de enero estar\u00e1 protagonizada por las quedadas surferas. As\u00ed, habr\u00e1 una quedada de SUP en la playa de La Concha, en la que se intentar\u00e1 batir el R\u00e9cord Guiness de asistencia para promocionar la modalidad, y una Expression Session Pro en la playa de Los Locos.<\/p>\n<p>Por la tarde, habr\u00e1 un coloquio sobre el surf y una charla sobre &#8216;La Vaca XXL&#8217; en la que intervendr\u00e1n algunos de los participantes que surfearon en la reciente edici\u00f3n de esta competici\u00f3n de olas gigantes que se celebra en Santander.<\/p>\n<p>Finalmente, se celebrar\u00e1 la Gala Nacional del Surf 2016 en la que se entregar\u00e1n premios nacionales y se reconocer\u00e1 la trfayectoria varios deportistas.<\/p>\n<p>EL SURF EN SUANCES<\/p>\n<p>La historia del surf en Suances se remonta a principios de los a\u00f1os 70 cuando un peque\u00f1o grupo de surfistas suancinos, y otros venidos de Santander, empezaron a descubrir y disfrutar el gran potencial de las olas de la villa, sobre todo, de su joya: la Playa de Los Locos.<\/p>\n<p>Declarada &#8216;Reserva del Surf\u00bb y parada obligada para cualquier surfista que est\u00e9 rondando el norte peninsular. Fue a partir de los a\u00f1os 80 cuando se fund\u00f3 el Club de Surf Los Locos y se abri\u00f3 la primera tienda de Surf del municipio.<\/p>\n<p>A partir de ah\u00ed, el n\u00famero de surfistas ha crecido sin parar, as\u00ed como nuevas escuelas de surf, tiendas&#8230; Suances ha acogido, a lo largo de todos estos a\u00f1os, numerosas competiciones a nivel nacional.<\/p>\n<p>En los \u00faltimos a\u00f1os se est\u00e1 consolidando en la costa suancense nuevos deportes como el SUP (Stand Up Paddle o Surf de remo). Una disciplina que puede pracicarse en mar abierto, en puerto, en r\u00eda o en cualquier masa de agua en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":62700,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62699","post","type-post","status-publish","format-standard","has-post-thumbnail","category-la-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"la agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1391\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-02T14:49:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-02T14:49:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#article\",\"name\":\"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias\",\"headline\":\"Suances acoge la I Gala Nacional del Surf este fin de semana\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160129104110_800.jpg\",\"width\":800,\"height\":1391},\"datePublished\":\"2016-02-02T15:49:32+01:00\",\"dateModified\":\"2016-02-02T15:49:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#webpage\"},\"articleSection\":\"La Agenda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/la-agenda\\\/#listItem\",\"name\":\"La Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/la-agenda\\\/#listItem\",\"position\":2,\"name\":\"La Agenda\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/la-agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#listItem\",\"name\":\"Suances acoge la I Gala Nacional del Surf este fin de semana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#listItem\",\"position\":3,\"name\":\"Suances acoge la I Gala Nacional del Surf este fin de semana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/la-agenda\\\/#listItem\",\"name\":\"La Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/\",\"name\":\"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias\",\"description\":\"El municipio c\\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\\u00e1ntabra y espa\\u00f1ola en colaboraci\\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160129104110_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#mainImage\",\"width\":800,\"height\":1391},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\\\/#mainImage\"},\"datePublished\":\"2016-02-02T15:49:32+01:00\",\"dateModified\":\"2016-02-02T15:49:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias","description":"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/","robots":"max-image-preview:large","keywords":"la agenda","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#article","name":"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias","headline":"Suances acoge la I Gala Nacional del Surf este fin de semana","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg","width":800,"height":1391},"datePublished":"2016-02-02T15:49:32+01:00","dateModified":"2016-02-02T15:49:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#webpage"},"articleSection":"La Agenda"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/la-agenda\/#listItem","name":"La Agenda"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/la-agenda\/#listItem","position":2,"name":"La Agenda","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/la-agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#listItem","name":"Suances acoge la I Gala Nacional del Surf este fin de semana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#listItem","position":3,"name":"Suances acoge la I Gala Nacional del Surf este fin de semana","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/la-agenda\/#listItem","name":"La Agenda"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/","name":"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias","description":"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#mainImage","width":800,"height":1391},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/#mainImage"},"datePublished":"2016-02-02T15:49:32+01:00","dateModified":"2016-02-02T15:49:32+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias","og:description":"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg","og:image:width":800,"og:image:height":1391,"article:published_time":"2016-02-02T14:49:32+00:00","article:modified_time":"2016-02-02T14:49:32+00:00","twitter:card":"summary_large_image","twitter:title":"Suances acoge la I Gala Nacional del Surf este fin de semana | El Digital de Asturias","twitter:description":"El municipio c\u00e1ntabro de Suances acoge el 29 y 30 de enero la primera edici\u00f3n de la Gala Nacional del Surf que, organizada por las federaciones c\u00e1ntabra y espa\u00f1ola en colaboraci\u00f3n con el Ayuntamiento y el Gobierno regional, se desarrollar\u00e1 en el Hotel Azul y las playas de Los Locos y La Concha. La programaci\u00f3n","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129104110_800.jpg"},"aioseo_meta_data":{"post_id":"62699","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:57:33","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:33:33","updated":"2026-05-22 23:57:33"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/la-agenda\/\" title=\"La Agenda\">La Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/\" title=\"Suances acoge la I Gala Nacional del Surf este fin de semana\">Suances acoge la I Gala Nacional del Surf este fin de semana<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"La Agenda","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/la-agenda\/"},{"label":"Suances acoge la I Gala Nacional del Surf este fin de semana","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/suances-acoge-la-i-gala-nacional-del-surf-este-fin-de-semana\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62699"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62700"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}