{"id":62696,"date":"2016-02-02T15:48:25","date_gmt":"2016-02-02T14:48:25","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62696"},"modified":"2016-02-02T15:48:25","modified_gmt":"2016-02-02T14:48:25","slug":"londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/","title":{"rendered":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62697\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-360x203.jpg\" alt=\"fotonoticia_20160129102636_800\" width=\"360\" height=\"203\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-360x203.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-650x366.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-768x432.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-150x84.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-450x253.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-696x392.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-747x420.jpg 747w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-499x280.jpg 499w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800-510x289.jpg 510w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia.<\/p>\n<p>El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo establecida dentro del marco del &#8216;Programa de socios ejecutivos&#8217; de CLIA.<\/p>\n<p>El programa del Foro incluir\u00e1 conferencias de inter\u00e9s para las autoridades, agentes portuarios, operadores y organizaciones tur\u00edsticas y tratar\u00e1 asuntos de importancia para la Comunidad de Puertos y Destinos.<\/p>\n<p>El vicepresidente de operaciones estrat\u00e9gicas de CLIA, Bo Larsen, ha se\u00f1alado que los cruceros siguen siendo una industria \u00abdin\u00e1mica\u00bb que se encuentra \u00aben constante evoluci\u00f3n\u00bb y ha a\u00f1adido que a trav\u00e9s de esta reuni\u00f3n de los profesionales del sector se pretende \u00abdebatir sobre los retos y oportunidades comunes\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo<\/p>\n","protected":false},"author":1,"featured_media":62697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-62696","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-02T14:48:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-02T14:48:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#article\",\"name\":\"Londres acoger\\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias\",\"headline\":\"Londres acoger\\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160129102636_800.jpg\",\"width\":800,\"height\":450},\"datePublished\":\"2016-02-02T15:48:25+01:00\",\"dateModified\":\"2016-02-02T15:48:25+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#listItem\",\"name\":\"Londres acoger\\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#listItem\",\"position\":3,\"name\":\"Londres acoger\\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/\",\"name\":\"Londres acoger\\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias\",\"description\":\"La Asociaci\\u00f3n Internacional de L\\u00edneas de Cruceros (CLIA) organizar\\u00e1 su foro anual de Puertos y Destinos en Londres el pr\\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\\u00e1 a los socios ejecutivos de CLIA que tendr\\u00e1n la oportunidad de participar en una plataforma de di\\u00e1logo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160129102636_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#mainImage\",\"width\":800,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\\\/#mainImage\"},\"datePublished\":\"2016-02-02T15:48:25+01:00\",\"dateModified\":\"2016-02-02T15:48:25+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias","description":"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#article","name":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias","headline":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg","width":800,"height":450},"datePublished":"2016-02-02T15:48:25+01:00","dateModified":"2016-02-02T15:48:25+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#listItem","name":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#listItem","position":3,"name":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/","name":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias","description":"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#mainImage","width":800,"height":450},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/#mainImage"},"datePublished":"2016-02-02T15:48:25+01:00","dateModified":"2016-02-02T15:48:25+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias","og:description":"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg","og:image:width":800,"og:image:height":450,"article:published_time":"2016-02-02T14:48:25+00:00","article:modified_time":"2016-02-02T14:48:25+00:00","twitter:card":"summary_large_image","twitter:title":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero | El Digital de Asturias","twitter:description":"La Asociaci\u00f3n Internacional de L\u00edneas de Cruceros (CLIA) organizar\u00e1 su foro anual de Puertos y Destinos en Londres el pr\u00f3ximo 23 de febrero, para el que 18 directivos del sector ya han confirmado su asistencia. El evento reunir\u00e1 a los socios ejecutivos de CLIA que tendr\u00e1n la oportunidad de participar en una plataforma de di\u00e1logo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160129102636_800.jpg"},"aioseo_meta_data":{"post_id":"62696","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:57:31","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:33:33","updated":"2026-05-22 23:57:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/\" title=\"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero\">Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Londres acoger\u00e1 en febrero el foro anual de Puertos y Destinos de la industria del crucero","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/londres-acogera-en-febrero-el-foro-anual-de-puertos-y-destinos-de-la-industria-del-crucero\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62696"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62697"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}