{"id":62687,"date":"2016-02-02T15:44:32","date_gmt":"2016-02-02T14:44:32","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62687"},"modified":"2016-02-02T15:44:32","modified_gmt":"2016-02-02T14:44:32","slug":"heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/","title":{"rendered":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62688\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-360x240.jpg\" alt=\"fotonoticia_20160128194309_800\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-650x433.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-768x512.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-696x464.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-630x420.jpg 630w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800-101x66.jpg 101w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os &#8211;adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre&#8211; y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press el presidente, Ashish Kumar.<\/p>\n<p>La compa\u00f1\u00eda, que quiere situar spas especialmente en aeropuertos, pero tambi\u00e9n hoteles y cl\u00ednicas &#8211;con planes m\u00e1s avanzados en Barcelona y Madrid&#8211;, tambi\u00e9n desembarcar\u00e1 en paralelo en Par\u00eds, Londres, Copenhaguen, Lisboa y Amsterdam.<\/p>\n<p>A nivel global, la empresa registrar\u00e1 un beneficio de entre 300.000 y 500.000 euros para este a\u00f1o y prev\u00e9 que aumenten hasta un 20% durante el per\u00edodo 2017-2018.<\/p>\n<p>EXPANSI\u00d3N EN ESPA\u00d1A<\/p>\n<p>En diciembre la empresa ya anunci\u00f3 que abrir\u00eda 20 tiendas con una inversi\u00f3n de dos millones de euros en Espa\u00f1a en los pr\u00f3ximos tres a\u00f1os, una cifra que Kumar ve \u00abmuy posible\u00bb superar.<\/p>\n<p>Adem\u00e1s de aeropuertos, hoteles y cl\u00ednicas privadas, la empresa tambi\u00e9n busca lugares de mucho afluencia y circulaci\u00f3n de personas para instalar sus centros, que generan entre ocho y diez empleos cada uno.<\/p>\n<p>Heaven on Earth decidi\u00f3 empezar a implantarse en Espa\u00f1a el Aeropuerto de El Prat de Barcelona porque circulan casi 40 millones de pasajeros al a\u00f1o y porque registraba un crecimiento mayor que Madrid-Barajas.<\/p>\n<p>Los centros de Spa Express de Heaven On Earth ofrecen nueve tratamientos que duran entre 15 y 90 minutos y que incluyen reflexolog\u00eda podal, masaje de espalda superior, masaje de cabeza indio, terapia completa, manicura expr\u00e9s y masaje de manos.<\/p>\n<p>Heaven On Earth, creada en 2007, es una compa\u00f1\u00eda india especializada en masajes terap\u00e9uticos y de wellness con t\u00e9cnicas que combinan la reflexolog\u00eda china, los masajes suecos y el masaje capilar indio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os &#8211;adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre&#8211; y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press<\/p>\n","protected":false},"author":1,"featured_media":62688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-62687","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-02T14:44:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-02T14:44:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#article\",\"name\":\"Heaven on Earth abrir\\u00e1 spas en seis ciudades y facturar\\u00e1 hasta 2 millones en Espa\\u00f1a en 2016 | El Digital de Asturias\",\"headline\":\"Heaven on Earth abrir\\u00e1 spas en seis ciudades y facturar\\u00e1 hasta 2 millones en Espa\\u00f1a en 2016\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160128194309_800.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2016-02-02T15:44:32+01:00\",\"dateModified\":\"2016-02-02T15:44:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#listItem\",\"name\":\"Heaven on Earth abrir\\u00e1 spas en seis ciudades y facturar\\u00e1 hasta 2 millones en Espa\\u00f1a en 2016\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#listItem\",\"position\":3,\"name\":\"Heaven on Earth abrir\\u00e1 spas en seis ciudades y facturar\\u00e1 hasta 2 millones en Espa\\u00f1a en 2016\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/\",\"name\":\"Heaven on Earth abrir\\u00e1 spas en seis ciudades y facturar\\u00e1 hasta 2 millones en Espa\\u00f1a en 2016 | El Digital de Asturias\",\"description\":\"La empresa india de spas Heaven on Earth abrir\\u00e1 spas en Madrid, Sevilla, M\\u00e1laga, Mallorca, Ibiza y Alicante en los pr\\u00f3ximos a\\u00f1os --adem\\u00e1s de los tres que tiene en Barcelona donde desembarc\\u00f3 en diciembre-- y prev\\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\\u00f1a este a\\u00f1o, ha explicado este jueves a Europa Press\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160128194309_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\\\/#mainImage\"},\"datePublished\":\"2016-02-02T15:44:32+01:00\",\"dateModified\":\"2016-02-02T15:44:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias","description":"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#article","name":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias","headline":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg","width":800,"height":533},"datePublished":"2016-02-02T15:44:32+01:00","dateModified":"2016-02-02T15:44:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#listItem","name":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#listItem","position":3,"name":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/","name":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias","description":"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/#mainImage"},"datePublished":"2016-02-02T15:44:32+01:00","dateModified":"2016-02-02T15:44:32+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias","og:description":"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2016-02-02T14:44:32+00:00","article:modified_time":"2016-02-02T14:44:32+00:00","twitter:card":"summary_large_image","twitter:title":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016 | El Digital de Asturias","twitter:description":"La empresa india de spas Heaven on Earth abrir\u00e1 spas en Madrid, Sevilla, M\u00e1laga, Mallorca, Ibiza y Alicante en los pr\u00f3ximos a\u00f1os --adem\u00e1s de los tres que tiene en Barcelona donde desembarc\u00f3 en diciembre-- y prev\u00e9 facturar entre 1,5 y 2 millones de euros en Espa\u00f1a este a\u00f1o, ha explicado este jueves a Europa Press","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128194309_800.jpg"},"aioseo_meta_data":{"post_id":"62687","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:56:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 13:01:22","updated":"2026-05-22 23:56:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/\" title=\"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016\">Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Heaven on Earth abrir\u00e1 spas en seis ciudades y facturar\u00e1 hasta 2 millones en Espa\u00f1a en 2016","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/heaven-on-earth-abrira-spas-en-seis-ciudades-y-facturara-hasta-2-millones-en-espana-en-2016\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62687"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62688"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}