{"id":62594,"date":"2016-02-02T14:46:54","date_gmt":"2016-02-02T13:46:54","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62594"},"modified":"2016-02-02T14:46:54","modified_gmt":"2016-02-02T13:46:54","slug":"el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/","title":{"rendered":"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62595\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-360x212.jpg\" alt=\"fotonoticia_20160128120822_800\" width=\"360\" height=\"212\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-360x212.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-650x382.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-768x451.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-150x88.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-450x264.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-696x409.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-715x420.jpg 715w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800-172x100.jpg 172w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers&#8217; Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a.<\/p>\n<p>En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del &#8216;Top 25&#8217; ha conseguido situarse como el segundo mejor hotel espa\u00f1ol y el noveno europeo. Mientras que en el premio al Mejor Servicio tambi\u00e9n se ha situado en el segundo puesto a nivel nacional y el 14 a nivel europeo.<\/p>\n<p>El hotel cuenta con cuatro plantas, cada una dedicada a un barrio de la Ciudad Condal, y 30 habitaciones. En la parte superior del hotel, se encuentra la terraza The Rooftop con piscina con una capacidad para un m\u00e1ximo de 120 personas. Adem\u00e1s, tiene un bar &#8216;longue&#8217; abierto las 24 horas del d\u00eda.<\/p>\n<p>Tambi\u00e9n cuenta una oferta gastron\u00f3mica creada por el &#8216;chef&#8217; galardonado con una estrella Michelin, Marc Gascons. El men\u00fa est\u00e1 confeccionado a partir de productos locales y de temporada su restaurante tiene capacidad para 22 comensales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers&#8217; Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del &#8216;Top<\/p>\n","protected":false},"author":1,"featured_media":62595,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-62594","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers&#039; Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del &#039;Top\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers&#039; Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del &#039;Top\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-02T13:46:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-02T13:46:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers&#039; Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del &#039;Top\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#article\",\"name\":\"El hotel The Serras obtiene siete galardones en los premios Traverllers\\u2019 Choice 2016 | El Digital de Asturias\",\"headline\":\"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160128120822_800.jpg\",\"width\":800,\"height\":470},\"datePublished\":\"2016-02-02T14:46:54+01:00\",\"dateModified\":\"2016-02-02T14:46:54+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#listItem\",\"name\":\"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#listItem\",\"position\":3,\"name\":\"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/\",\"name\":\"El hotel The Serras obtiene siete galardones en los premios Traverllers\\u2019 Choice 2016 | El Digital de Asturias\",\"description\":\"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers' Choice, convirti\\u00e9ndose en el hotel m\\u00e1s galardonado de Espa\\u00f1a. En la categor\\u00eda de lujo ha sido el primer galardonado en Espa\\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del 'Top\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160128120822_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#mainImage\",\"width\":800,\"height\":470},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\\\/#mainImage\"},\"datePublished\":\"2016-02-02T14:46:54+01:00\",\"dateModified\":\"2016-02-02T14:46:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias","description":"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers' Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del 'Top","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#article","name":"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias","headline":"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg","width":800,"height":470},"datePublished":"2016-02-02T14:46:54+01:00","dateModified":"2016-02-02T14:46:54+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#listItem","name":"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#listItem","position":3,"name":"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/","name":"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias","description":"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers' Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del 'Top","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#mainImage","width":800,"height":470},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/#mainImage"},"datePublished":"2016-02-02T14:46:54+01:00","dateModified":"2016-02-02T14:46:54+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias","og:description":"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers' Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del 'Top","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg","og:image:width":800,"og:image:height":470,"article:published_time":"2016-02-02T13:46:54+00:00","article:modified_time":"2016-02-02T13:46:54+00:00","twitter:card":"summary_large_image","twitter:title":"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016 | El Digital de Asturias","twitter:description":"The Serras, el hotel boutique de cinco estrellas gran lujo de Barcelona, ha obtenido siete galardones en los premios Traverllers' Choice, convirti\u00e9ndose en el hotel m\u00e1s galardonado de Espa\u00f1a. En la categor\u00eda de lujo ha sido el primer galardonado en Espa\u00f1a, el segundo en Europa y el noveno en todo el mundo. Dentro del 'Top","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160128120822_800.jpg"},"aioseo_meta_data":{"post_id":"62594","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:44:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:34:40","updated":"2026-05-22 23:44:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/\" title=\"El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016\">El hotel The Serras obtiene siete galardones en los premios Traverllers\u2019 Choice 2016<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El hotel The Serras obtiene siete galardones en los premios Traverllers&#8217; Choice 2016","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-hotel-the-serras-obtiene-siete-galardones-en-los-premios-traverllers-choice-2016\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62594"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62595"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}