{"id":62517,"date":"2016-02-01T03:13:01","date_gmt":"2016-02-01T02:13:01","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62517"},"modified":"2016-02-01T03:13:01","modified_gmt":"2016-02-01T02:13:01","slug":"el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/","title":{"rendered":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62518\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-360x241.jpg\" alt=\"fotonoticia_20160127184508_800\" width=\"360\" height=\"241\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-360x241.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-650x435.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-768x514.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-450x301.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-696x465.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800-628x420.jpg 628w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la XIV Cumbre Internacional de la Gastronom\u00eda Madrid Fusi\u00f3n.<\/p>\n<p>Un sector al que \u00c1lvaro Guti\u00e9rrez ha mostrado su apoyo y el de la instituci\u00f3n que preside no solo visitando este mediod\u00eda Enofusi\u00f3n sino tambi\u00e9n promocionando la participaci\u00f3n de 19 bodegas y cooperativas de la provincia de Toledo en esta feria, as\u00ed como la celebraci\u00f3n de una cata de vinos toledanos maridada con productos gastron\u00f3micos representativos de la provincia como son caza, quesos, chorizos y mazapanes, ha informado la Diputaci\u00f3n en un comunicado.<\/p>\n<p>\u00c1lvaro Guti\u00e9rrez y la vicepresidenta delegada del \u00c1rea de Educaci\u00f3n, Cultura, Turismo y Deportes, Mar\u00eda \u00c1ngeles Garc\u00eda, han presidido esta cata de vinos que ha sido dirigida por t\u00e9cnicos de las respectivas bodegas participantes y que ha contado con una gran aceptaci\u00f3n por parte de los asistentes que llenaron la sala donde se ha celebrado.<\/p>\n<p>Los seis vinos seleccionados por Enofusi\u00f3n para participar en esta cata han sido Loco 2013, un blanco de Bodegas Canopy. DO M\u00e9ntrida; Pingorote 2010 Crianza de Bodegas Lat\u00fae de la DO La Mancha; Pa\u00f1o Fino 2013 de Bodegas Barreda de vinos de la tierra de Castilla; Pinuaga, 200 Cepas 2013 de Bodegas Pinuaga de vinos de la Tierra de Castilla, y Em\u00e9ritus 2010 de la DO Pago Dominio de Valdepusa y Otfen.<\/p>\n<p>Una cata en la que tambi\u00e9n han participado el director general de Industrias Agroalimentarias de Castilla-La Mancha, Agapito Portillo; el director de Enofusi\u00f3n, Vicente S\u00e1nchez Migall\u00f3n; el alcalde de M\u00e9ntrida, Alfonso Arriero, y el marqu\u00e9s de Gri\u00f1\u00f3n, Carlos Falc\u00f3.<\/p>\n<p>El presidente de la Diputaci\u00f3n ha resaltado el hecho de que por primera vez la Instituci\u00f3n provincial haya promovido la participaci\u00f3n de vinos toledanos en esta important\u00edsima cita enol\u00f3gica, un encuentro muy importante para el sector que re\u00fane en un mismo marco a bodegueros, hosteleros, distribuidores, en\u00f3logos, sumilleres, periodistas y aficionados a la cultura del vino de todo el mundo.<\/p>\n<p>Guti\u00e9rrez ha resaltado la importancia que este a\u00f1o tiene para el mundo de la gastronom\u00eda con eventos tan destacados como la Capitalidad Espa\u00f1ola que va a tener Toledo y que la Diputaci\u00f3n apoya de forma decida, y que tanta repercusi\u00f3n va a tener en el \u00e1mbito tur\u00edstico de la capital y de la provincia de Toledo.<\/p>\n<p>Previamente a la cata, ha tenido ocasi\u00f3n de probar los vinos toledanos presentes en Enofusi\u00f3n, que son Castillo de Consuegra, San Antonio Abad, Bodega Campos de Dulcinea, Bodega Romaila, Bodegas Alcerdet, Bodegas Camino Alto, Bodegas Canapy, Bodegas Gonzalo Valverde, Bodegas Kiries, Bodegas M\u00e1s que Vinos, Bodegas Vihucas, Bodegas y Vi\u00f1edos Mu\u00f1oz, Bodegas y Vi\u00f1edos Pinuaga, Capilla del Fraile, Condes de Fuensalida S. COOP. de CLM, Finca Loranque, Hacienda Villarta, Jim\u00e9nez Landi y Pagos de Familia Marqu\u00e9s de Gri\u00f1\u00f3n S.A.<\/p>\n<p>Adem\u00e1s, Guti\u00e9rrez ha visitado el stand de Toledo Capital Gastron\u00f3mica presente en Madrid Fusi\u00f3n donde ha intercambiado impresiones con los productores que mostraban sus productos, como cerveza Domus, de Toledo capital, y queso Majazul de Bargas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la<\/p>\n","protected":false},"author":1,"featured_media":62518,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-62517","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-01T02:13:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-01T02:13:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#article\",\"name\":\"El presidente de la Diputaci\\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\\u00f3n | El Digital de Asturias\",\"headline\":\"El presidente de la Diputaci\\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160127184508_800.jpg\",\"width\":800,\"height\":535},\"datePublished\":\"2016-02-01T03:13:01+01:00\",\"dateModified\":\"2016-02-01T03:13:01+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#listItem\",\"name\":\"El presidente de la Diputaci\\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#listItem\",\"position\":3,\"name\":\"El presidente de la Diputaci\\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/\",\"name\":\"El presidente de la Diputaci\\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\\u00f3n | El Digital de Asturias\",\"description\":\"El presidente de la Diputaci\\u00f3n Provincial de Toledo, \\u00c1lvaro Guti\\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\\u00e9rcoles en Enofusi\\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160127184508_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#mainImage\",\"width\":800,\"height\":535},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\\\/#mainImage\"},\"datePublished\":\"2016-02-01T03:13:01+01:00\",\"dateModified\":\"2016-02-01T03:13:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias","description":"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#article","name":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias","headline":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg","width":800,"height":535},"datePublished":"2016-02-01T03:13:01+01:00","dateModified":"2016-02-01T03:13:01+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#listItem","name":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#listItem","position":3,"name":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/","name":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias","description":"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#mainImage","width":800,"height":535},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/#mainImage"},"datePublished":"2016-02-01T03:13:01+01:00","dateModified":"2016-02-01T03:13:01+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias","og:description":"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg","og:image:width":800,"og:image:height":535,"article:published_time":"2016-02-01T02:13:01+00:00","article:modified_time":"2016-02-01T02:13:01+00:00","twitter:card":"summary_large_image","twitter:title":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n | El Digital de Asturias","twitter:description":"El presidente de la Diputaci\u00f3n Provincial de Toledo, \u00c1lvaro Guti\u00e9rrez, ha destacado la calidad, la variedad y la competitividad de los vinos de la provincia toledana que han participado desde el lunes y hasta este mi\u00e9rcoles en Enofusi\u00f3n, la feria nacional e internacional dedicada a los vinos que se celebra en Madrid dentro de la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127184508_800.jpg"},"aioseo_meta_data":{"post_id":"62517","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:30:59","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:35:47","updated":"2026-05-22 23:30:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/\" title=\"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n\">El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El presidente de la Diputaci\u00f3n resalta la calidad y competitividad de los vinos toledanos presentes en Enofusi\u00f3n","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-presidente-de-la-diputacion-resalta-la-calidad-y-competitividad-de-los-vinos-toledanos-presentes-en-enofusion\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62517"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62518"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}