{"id":62430,"date":"2016-02-01T02:11:45","date_gmt":"2016-02-01T01:11:45","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62430"},"modified":"2016-02-01T02:11:45","modified_gmt":"2016-02-01T01:11:45","slug":"los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/","title":{"rendered":"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62431\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-360x239.jpg\" alt=\"fotonoticia_20160127153551_800\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-768x511.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-696x463.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-632x420.jpg 632w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-121x79.jpg 121w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800-101x66.jpg 101w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria &#8217;10 Men\u00fas 1 Navidad&#8217; (&#8216;www.10menus1navidad.com&#8217;) en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena.<\/p>\n<p>A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa por cada 10 men\u00fas contratados por sus clientes durante la campa\u00f1a navide\u00f1a. As\u00ed, durante los 25 d\u00edas laborables que dure el reparto, en las cocinas del hotel Catalonia Barcelona Plaza se elaborar\u00e1n un total de 1.250 men\u00fas solidarios con propuestas suaves y equilibradas como sopas, cremas, aves y pescados.<\/p>\n<p>De este modo, estar\u00e1 cubierto el servicio de cenas para las aproximadamente 50 personas que diariamente frecuentan el comedor social que la Fundaci\u00f3 Arrels posee en el barrio barcelon\u00e9s del Raval. Los usuarios que quieran sumarse a esta iniciativa pueden contactar con los organizadores mediante el correo electr\u00f3nico 10menus1navidad@hoteles-catalonia.es.<\/p>\n<p>Esta iniciativa solidaria tambi\u00e9n cuenta con el apoyo log\u00edstico de Rotary Club de Barcelona, una organizaci\u00f3n que se encarga de la distribuci\u00f3n de los men\u00fas mediante veh\u00edculos adaptados para el transporte de alimentos.<\/p>\n<p>La cadena hotelera completa esta campa\u00f1a puntual con la participaci\u00f3n peri\u00f3dica en el proyecto ALPAN, una iniciativa que distribuye gratuitamente men\u00fas elaborados por hoteles y restaurantes en distintos comedores sociales de la Ciudad Condal.<\/p>\n<p>Actualmente los hoteles Catalonia Ramblas, Catalonia Eixample 1864, Catalonia Barcelona 505, Catalonia Diagonal Centro y Catalonia Park G\u00fcell colaboran en el proyecto ALPAN confeccionando 50 men\u00fas semanales, saldando la participaci\u00f3n anual de la cadena con un total de 13.000 men\u00fas donados durante el 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria &#8217;10 Men\u00fas 1 Navidad&#8217; (&#8216;www.10menus1navidad.com&#8217;) en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa<\/p>\n","protected":false},"author":1,"featured_media":62431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-62430","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria &#039;10 Men\u00fas 1 Navidad&#039; (&#039;www.10menus1navidad.com&#039;) en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria &#039;10 Men\u00fas 1 Navidad&#039; (&#039;www.10menus1navidad.com&#039;) en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-01T01:11:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-01T01:11:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria &#039;10 Men\u00fas 1 Navidad&#039; (&#039;www.10menus1navidad.com&#039;) en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#article\",\"name\":\"Los clientes de Catalonia Hotels & Resorts donan 1.250 men\\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias\",\"headline\":\"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\\u00fas solidarios a un comedor social de Barcelona\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160127153551_800.jpg\",\"width\":800,\"height\":532},\"datePublished\":\"2016-02-01T02:11:45+01:00\",\"dateModified\":\"2016-02-01T02:11:45+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#listItem\",\"name\":\"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\\u00fas solidarios a un comedor social de Barcelona\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#listItem\",\"position\":3,\"name\":\"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\\u00fas solidarios a un comedor social de Barcelona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/\",\"name\":\"Los clientes de Catalonia Hotels & Resorts donan 1.250 men\\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias\",\"description\":\"Los clientes de Catalonia Hotels & Resorts han donado 1.250 men\\u00fas solidario a un comedor social de Barcelona, gracias a la campa\\u00f1a solidaria '10 Men\\u00fas 1 Navidad' ('www.10menus1navidad.com') en la que han participado m\\u00e1s de 12.500 personas, seg\\u00fan informa la cadena. A trav\\u00e9s de esta acci\\u00f3n solidaria, la cadena se compromet\\u00eda a donar un men\\u00fa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/fotonoticia_20160127153551_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#mainImage\",\"width\":800,\"height\":532},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\\\/#mainImage\"},\"datePublished\":\"2016-02-01T02:11:45+01:00\",\"dateModified\":\"2016-02-01T02:11:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los clientes de Catalonia Hotels & Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias","description":"Los clientes de Catalonia Hotels & Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria '10 Men\u00fas 1 Navidad' ('www.10menus1navidad.com') en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#article","name":"Los clientes de Catalonia Hotels & Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias","headline":"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg","width":800,"height":532},"datePublished":"2016-02-01T02:11:45+01:00","dateModified":"2016-02-01T02:11:45+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#listItem","name":"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#listItem","position":3,"name":"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/","name":"Los clientes de Catalonia Hotels & Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias","description":"Los clientes de Catalonia Hotels & Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria '10 Men\u00fas 1 Navidad' ('www.10menus1navidad.com') en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#mainImage","width":800,"height":532},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/#mainImage"},"datePublished":"2016-02-01T02:11:45+01:00","dateModified":"2016-02-01T02:11:45+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias","og:description":"Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria '10 Men\u00fas 1 Navidad' ('www.10menus1navidad.com') en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg","og:image:width":800,"og:image:height":532,"article:published_time":"2016-02-01T01:11:45+00:00","article:modified_time":"2016-02-01T01:11:45+00:00","twitter:card":"summary_large_image","twitter:title":"Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona | El Digital de Asturias","twitter:description":"Los clientes de Catalonia Hotels &amp; Resorts han donado 1.250 men\u00fas solidario a un comedor social de Barcelona, gracias a la campa\u00f1a solidaria '10 Men\u00fas 1 Navidad' ('www.10menus1navidad.com') en la que han participado m\u00e1s de 12.500 personas, seg\u00fan informa la cadena. A trav\u00e9s de esta acci\u00f3n solidaria, la cadena se compromet\u00eda a donar un men\u00fa","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/02\/fotonoticia_20160127153551_800.jpg"},"aioseo_meta_data":{"post_id":"62430","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 23:22:47","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:36:39","updated":"2026-05-22 23:22:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/\" title=\"Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona\">Los clientes de Catalonia Hotels &amp; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Los clientes de Catalonia Hotels &#038; Resorts donan 1.250 men\u00fas solidarios a un comedor social de Barcelona","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-clientes-de-catalonia-hotels-resorts-donan-1-250-menus-solidarios-a-un-comedor-social-de-barcelona\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62430"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62431"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}