{"id":62190,"date":"2016-01-30T02:37:29","date_gmt":"2016-01-30T01:37:29","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62190"},"modified":"2016-01-30T02:37:29","modified_gmt":"2016-01-30T01:37:29","slug":"el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/","title":{"rendered":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62191\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-360x288.jpg\" alt=\"fotonoticia_20160126140028_800\" width=\"360\" height=\"288\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-360x288.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-650x520.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-768x614.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-150x120.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-450x360.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-696x557.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800-525x420.jpg 525w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas.<\/p>\n<p>Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales atractivos culturales de C\u00e1diz y que \u00abcada a\u00f1o se consolida m\u00e1s como foco de atracci\u00f3n para los turistas que llegan a la provincia\u00bb.<\/p>\n<p>El dato de 151.624 visitantes en 2015 supera en casi 900 turistas las cifras de 2014, que ya se hab\u00edan considerado como las mejores en la vida del conjunto, con 14.000 visitantes m\u00e1s que en 2013.<\/p>\n<p>Seg\u00fan las estad\u00edsticas, la llegada a Baelo Claudia de turistas ha batido r\u00e9cords mensuales en cinco ocasiones (enero, abril, mayo, septiembre y diciembre), \u00ablo que da idea de que la oferta de la provincia est\u00e1 dando pasos de gigante para desestacionalizarse\u00bb, ha dicho L\u00f3pez Gil. Adem\u00e1s, los meses de julio y agosto sumaron cerca de 49.000 visitantes, lo que supone el 32 por ciento del total anual.<\/p>\n<p>El delegado ha se\u00f1alado como causas del ascenso generalizado de visitantes durante todo el a\u00f1o factores como la consolidaci\u00f3n de las actividades que desarrollamos desde el \u00e1rea de difusi\u00f3n, el notable aumento de la recuperaci\u00f3n tur\u00edstica de la zona donde se enmarca el yacimiento, la mejora del conocimiento que se tiene de esta ciudad hispanorromana y al afianzamiento de Baelo Claudia dentro de los circuitos tur\u00edsticos y culturales de car\u00e1cter nacional e internacional, e incluso la climatolog\u00eda, que ha sido \u00abmuy favorable a lo largo de 2015\u00bb.<\/p>\n<p>PROCEDENCIA DE LOS VISITANTES<\/p>\n<p>L\u00f3pez Gil ha explicado que a lo largo de 2015 ha sido especialmente destacable el repunte de los visitantes procedentes del resto de Espa\u00f1a, que son los que han representado el principal aumento en cifras y han contribuido de manera m\u00e1s significativa a volver a batir el r\u00e9cord del conjunto, mientras que el resto de segmentos han experimentado ligeros descensos.<\/p>\n<p>En cifras totales, el principal grupo de visitantes lo conforman los andaluces de fuera de C\u00e1diz que con un total de 70.747 visitantes que suponen el 47 por ciento del total. Le siguen los visitantes nacionales &#8211;un total de 46.078 (30% del total)&#8211;.<\/p>\n<p>Respecto a las cifras de visitantes extranjeros, se han mantenido en niveles similares a 2014. En este caso, los meses entre enero y junio de 2015 han registrado cifras r\u00e9cord en este segmento de turistas extranjeros, as\u00ed como el mes de octubre que es en el que se documenta un mayor n\u00famero de estos extranjeros llegados de fuera del pa\u00eds.<\/p>\n<p>Por \u00faltimo, ha apuntado que se mantienen en cifras similares a 2014 (con ligeros descensos) los visitantes locales y los escolares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales<\/p>\n","protected":false},"author":1,"featured_media":62191,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-62190","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-30T01:37:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-30T01:37:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#article\",\"name\":\"El conjunto arqueol\\u00f3gico de Baelo Claudia logra r\\u00e9cord hist\\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias\",\"headline\":\"El conjunto arqueol\\u00f3gico de Baelo Claudia logra r\\u00e9cord hist\\u00f3rico con 151.600 visitantes en 2015\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160126140028_800.jpg\",\"width\":800,\"height\":640},\"datePublished\":\"2016-01-30T02:37:29+01:00\",\"dateModified\":\"2016-01-30T02:37:29+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#listItem\",\"name\":\"El conjunto arqueol\\u00f3gico de Baelo Claudia logra r\\u00e9cord hist\\u00f3rico con 151.600 visitantes en 2015\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#listItem\",\"position\":3,\"name\":\"El conjunto arqueol\\u00f3gico de Baelo Claudia logra r\\u00e9cord hist\\u00f3rico con 151.600 visitantes en 2015\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/\",\"name\":\"El conjunto arqueol\\u00f3gico de Baelo Claudia logra r\\u00e9cord hist\\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias\",\"description\":\"El delegado de la Junta en C\\u00e1diz, Fernando L\\u00f3pez Gil, ha visitado este martes el conjunto arqueol\\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\\u00e9cord hist\\u00f3rico de visitas con un total de 151.624 personas. Seg\\u00fan ha explicado la Junta en una nota, L\\u00f3pez Gil ha manifestado que dicho enclave es uno de principales\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160126140028_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#mainImage\",\"width\":800,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\\\/#mainImage\"},\"datePublished\":\"2016-01-30T02:37:29+01:00\",\"dateModified\":\"2016-01-30T02:37:29+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias","description":"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#article","name":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias","headline":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg","width":800,"height":640},"datePublished":"2016-01-30T02:37:29+01:00","dateModified":"2016-01-30T02:37:29+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#listItem","name":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#listItem","position":3,"name":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/","name":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias","description":"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#mainImage","width":800,"height":640},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/#mainImage"},"datePublished":"2016-01-30T02:37:29+01:00","dateModified":"2016-01-30T02:37:29+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias","og:description":"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg","og:image:width":800,"og:image:height":640,"article:published_time":"2016-01-30T01:37:29+00:00","article:modified_time":"2016-01-30T01:37:29+00:00","twitter:card":"summary_large_image","twitter:title":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015 | El Digital de Asturias","twitter:description":"El delegado de la Junta en C\u00e1diz, Fernando L\u00f3pez Gil, ha visitado este martes el conjunto arqueol\u00f3gico de Baelo Claudia, que en 2015 ha alcanzado su r\u00e9cord hist\u00f3rico de visitas con un total de 151.624 personas. Seg\u00fan ha explicado la Junta en una nota, L\u00f3pez Gil ha manifestado que dicho enclave es uno de principales","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160126140028_800.jpg"},"aioseo_meta_data":{"post_id":"62190","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 22:44:38","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:39:43","updated":"2026-05-22 22:44:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/\" title=\"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015\">El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El conjunto arqueol\u00f3gico de Baelo Claudia logra r\u00e9cord hist\u00f3rico con 151.600 visitantes en 2015","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-conjunto-arqueologico-de-baelo-claudia-logra-record-historico-con-151-600-visitantes-en-2015\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62190"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62191"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}