{"id":62068,"date":"2016-01-25T23:53:55","date_gmt":"2016-01-25T22:53:55","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62068"},"modified":"2016-01-25T23:53:55","modified_gmt":"2016-01-25T22:53:55","slug":"canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/","title":{"rendered":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62069\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-360x270.jpg\" alt=\"fotonoticia_20160125155555_800\" width=\"360\" height=\"270\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-360x270.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-650x488.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-768x576.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-150x113.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-450x338.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-80x60.jpg 80w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-265x198.jpg 265w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-696x522.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-560x420.jpg 560w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-90x67.jpg 90w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-164x124.jpg 164w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800-100x75.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo pr\u00f3ximamente en Cretas (Teruel), la red cuenta ya con 25 establecimientos distribuidos por toda la Comunidad.<\/p>\n<p>La consejera ha visitado la localidad altoaragonesa acompa\u00f1ada por el director gerente del Instituto Aragon\u00e9s de la Juventud, Adri\u00e1n Gimeno. Tras firmar en el libro de honor del Ayuntamiento, se ha dirigido al albergue, donde ha firmado el convenio con el alcalde de Canfranc y ha visitado todas sus instalaciones, ha informado el Ejecutivo auton\u00f3mico en una nota de prensa.<\/p>\n<p>Mar\u00eda Victoria Broto ha destacado los \u00abbeneficios\u00bb que este acuerdo aporta a la localidad de Canfranc, ya que la red publicitar\u00e1 estas instalaciones, tanto en el \u00e1mbito auton\u00f3mico, como en el nacional y el internacional. Asimismo, ha a\u00f1adido que \u00abesta firma quiere decir que este albergue cumple con todas las condiciones que se exigen desde el Instituto Aragon\u00e9s de la Juventud para poder formar parte de la red\u00bb.<\/p>\n<p>Broto ha incidido, adem\u00e1s, la amplia colaboraci\u00f3n que existe entre el Ayuntamiento de Canfranc y el Gobierno de Arag\u00f3n en diferentes cuestiones.<\/p>\n<p>RED DE ALBERGUES<\/p>\n<p>La Red Aragonesa de Albergues Juveniles forma parte de la Red Espa\u00f1ola, de la Federaci\u00f3n Europea y de la Federaci\u00f3n Internacional de Albergues Juveniles, que tienen como objetivo la promoci\u00f3n de la presencia de estos establecimientos.<\/p>\n<p>En Espa\u00f1a, existen un total de 280, mientras que suman 4.000 los repartidos en 90 pa\u00edses de todo el mundo, que registran 2,5 millones de pernoctaciones al a\u00f1o.<\/p>\n<p>La red cuenta con un programa de actividades amplio que incluyen desde el intercambio de j\u00f3venes entre albergues internacionales, vacaciones solidarias, proyecto MOVIC (actividades que se realizan con los j\u00f3venes en los albergues) y concursos.<\/p>\n<p>Para pernoctar en estos establecimientos, es necesario el carn\u00e9 de alberguista, un requisito que aporta m\u00faltiples ventajas al usuario y que le aporta promociones y descuentos en su vida cotidiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo<\/p>\n","protected":false},"author":1,"featured_media":62069,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-62068","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-25T22:53:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-25T22:53:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#article\",\"name\":\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias\",\"headline\":\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160125155555_800.jpg\",\"width\":800,\"height\":600},\"datePublished\":\"2016-01-25T23:53:55+01:00\",\"dateModified\":\"2016-01-25T23:53:55+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#listItem\",\"name\":\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#listItem\",\"position\":3,\"name\":\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/\",\"name\":\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias\",\"description\":\"La consejera de Ciudadan\\u00eda y Derechos Sociales del Gobierno de Arag\\u00f3n, Mar\\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\\u00e1 a cabo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160125155555_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\\\/#mainImage\"},\"datePublished\":\"2016-01-25T23:53:55+01:00\",\"dateModified\":\"2016-01-25T23:53:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias","description":"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#article","name":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias","headline":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg","width":800,"height":600},"datePublished":"2016-01-25T23:53:55+01:00","dateModified":"2016-01-25T23:53:55+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#listItem","name":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#listItem","position":3,"name":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/","name":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias","description":"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/#mainImage"},"datePublished":"2016-01-25T23:53:55+01:00","dateModified":"2016-01-25T23:53:55+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias","og:description":"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg","og:image:width":800,"og:image:height":600,"article:published_time":"2016-01-25T22:53:55+00:00","article:modified_time":"2016-01-25T22:53:55+00:00","twitter:card":"summary_large_image","twitter:title":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos | El Digital de Asturias","twitter:description":"La consejera de Ciudadan\u00eda y Derechos Sociales del Gobierno de Arag\u00f3n, Mar\u00eda Victoria Broto, y el alcalde de Canfranc, Fernando S\u00e1nchez, han firmado un convenio por el cual el albergue de esta localidad pasa a formar parte de la Red Aragonesa de Albergues Juveniles. Con esta firma, y con la que se llevar\u00e1 a cabo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125155555_800.jpg"},"aioseo_meta_data":{"post_id":"62068","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 22:30:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:41:41","updated":"2026-05-22 22:30:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/\" title=\"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos\">Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Canfranc se une a la Red Aragonesa de Albergues Juveniles, que ya cuenta con 25 establecimientos","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/canfranc-se-une-a-la-red-aragonesa-de-albergues-juveniles-que-ya-cuenta-con-25-establecimientos\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62068"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62069"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}