{"id":62040,"date":"2016-01-25T23:45:54","date_gmt":"2016-01-25T22:45:54","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=62040"},"modified":"2016-01-25T23:45:54","modified_gmt":"2016-01-25T22:45:54","slug":"badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/","title":{"rendered":"Badajoz fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-62041\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-360x270.jpg\" alt=\"fotonoticia_20160125145838_800\" width=\"360\" height=\"270\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-360x270.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-650x488.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-768x576.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-150x113.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-450x338.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-80x60.jpg 80w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-265x198.jpg 265w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-696x522.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-560x420.jpg 560w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-90x67.jpg 90w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-164x124.jpg 164w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800-100x75.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo.<\/p>\n<p>El programa de estas fiestas ha sido presentado en rueda de prensa por el concejal de Ferias y Fiestas, Miguel \u00c1ngel Rodr\u00edguez de la Calle, quien ha explicado que, frente a otros a\u00f1os, estas actuaciones de murgas ser\u00e1n, en lugar de en escenarios, a \u00abpie de calle\u00bb en lugares habilitados en la Plaza L\u00f3pez de Ayala, en la esquina de la confiter\u00eda La Cubana, en la Plaza de la Soledad y en la Plaza Alta que contar\u00e1n con un &#8216;display&#8217; y una moqueta.<\/p>\n<p>Al respecto, ha agregado que se trata de una propuesta de la Comisi\u00f3n de Murgas que han \u00abaceptado\u00bb con el objetivo de \u00abrellenar huecos\u00bb en la programaci\u00f3n del Carnaval, facilitar que las murgas act\u00faen en la ciudad y dotar a esta fiesta de \u00abm\u00e1s atractivo\u00bb.<\/p>\n<p>Al mismo tiempo, ha puntualizado que estas actuaciones tendr\u00e1n lugar el s\u00e1bado d\u00eda 6 y el lunes d\u00eda 8 entre las 14,00 y las 1,00 horas interviniendo en primer lugar las infantiles y las juveniles, seguidas de las de adultos inscritas en el concurso de murgas y las que no se han apuntado como Ad Libitum o Jarana.<\/p>\n<p>CONCURSO DE MURGAS<\/p>\n<p>El concurso de murgas es uno de los atractivos del Carnaval de Badajoz y comienza este lunes, d\u00eda 25, con las preliminares que tendr\u00e1n lugar en el Teatro L\u00f3pez de Ayala del 25 al 29 de enero, mientras que las semifinales ser\u00e1n del 1 al 3 de febrero y la final el 5 de febrero, ha informado el concejal, que ha matizado que este a\u00f1o, en concreto el d\u00eda 4 de febrero, se sortear\u00e1 el orden de la actuaci\u00f3n en la final y que, en el caso de las semifinales, ser\u00e1 en funci\u00f3n del puesto en el que hayan actuado en la primera fase.<\/p>\n<p>De igual modo, ha se\u00f1alado la existencia de nuevos galardones a las murgas y que, en concreto, la Asociaci\u00f3n de la Prensa de Badajoz otorgar\u00e1 el premio &#8216;A la s\u00e1tira del Carnaval&#8217; para reconocer a la murga que presente el mejor repertorio sobre la actualidad a trav\u00e9s de la cr\u00edtica, la parodia y el ingenio en sus letras.<\/p>\n<p>Asimismo, el Almac\u00e9n de bebidas Carballo conceder\u00e1 premios al mejor bombo, caja y guitarra, los tres dotados de 300 euros, Di\u00f3n Eventos al mejor figurante con 150 euros y Come y Calla Catering al mejor estribillo con 150 euros en el marco de este concurso cuya final se retransmitir\u00e1 en unas pantallas situadas en San Francisco y en el que el p\u00fablico del L\u00f3pez de Ayala podr\u00e1 votar a la mejor murga convirti\u00e9ndose en jurado popular.<\/p>\n<p>Otra de las novedades del Carnaval 2016 es el concurso de murgas de los m\u00e1s peque\u00f1os, en el que se separan las infantiles de las juveniles debido al aumento de participantes, de manera que el primero se desarrolla el jueves d\u00eda 4 a las 11,00 horas en el L\u00f3pez de Ayala con nueves murgas y el segundo el mismo d\u00eda a las 18,00 horas con seis.<\/p>\n<p>PROGRAMA DE ACTOS<\/p>\n<p>En su intervenci\u00f3n, Rodr\u00edguez de la Calle ha recordado que la pregonera de este a\u00f1o es Mary Pepa Orantos, que ofrecer\u00e1 el preg\u00f3n en la Plaza de Espa\u00f1a a las 20.30 horas del viernes 5, cuando tambi\u00e9n se celebra a partir de las 18,00 horas el desfile oficial de comparsas infantiles entre la Avenida de Europa y la Plaza de Espa\u00f1a con 1.154 participantes.<\/p>\n<p>El s\u00e1bado d\u00eda 6 se celebrar\u00e1 a las 13,00 horas en el Teatro L\u00f3pez de Ayala el concurso de disfraz individual de comparsa infantil y popular infantil y de 16,00 a 21,00 horas una concentraci\u00f3n de disfraces populares en el Paseo de San Francisco, donde se conceder\u00e1n premios al mejor disfraz por pareja, individual y maquillaje, todos ellos dotados con 300 euros cada uno, y se podr\u00e1 disfrutar de una actuaci\u00f3n de un DJ.<\/p>\n<p>El domingo d\u00eda 7 ser\u00e1 el turno a las 12,00 horas del gran desfile de comparsas, grupos menores y artefactos entre la avenida de Santa Marina y la Plaza Dragones y en el que participan 5.347 personas, tras el cual se celebrar\u00e1 de 16,00 a 21,00 horas un baile con DJ en San Francisco en el que se dar\u00e1 a conocer el fallo del concurso de disfraces infantiles de comparsas y popular y el del desfile de comparsas, grupos menores y artefactos.<\/p>\n<p>Por \u00faltimo, el martes d\u00eda 9 culminar\u00e1 el Carnaval con el Entierro de la Sardina, que dar\u00e1 comienzo a partir de las 08,30 horas en la Barriada de San Roque, y a las 19,00 horas con la entrega de premios a los ganadores de los distintos concursos y la actuaci\u00f3n de las tres primeras murgas en San Francisco.<\/p>\n<p>Finalmente, Miguel \u00c1ngel Rodr\u00edguez de la Calle ha informado que el Carnaval 2016 de Badajoz tiene un presupuesto de 387.757 euros, un 4 por ciento superior al del a\u00f1o anterior dado el aumento de grupos, de colaboradores o de jurados y que cuenta con la colaboraci\u00f3n de Renfe, Aqualia y Cablex, adem\u00e1s de haber sido promocionado tanto en la Feria Internacional de Turismo Fitur con 12 miembros de comparsas que han repartido material promocional disfrazados, como en ciudades como Sevilla, C\u00e1diz o C\u00f3rdoba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El<\/p>\n","protected":false},"author":1,"featured_media":62041,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-62040","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el &#039;Carnaval de calle&#039; con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el &#039;Carnaval de calle&#039; con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-25T22:45:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-25T22:45:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el &#039;Carnaval de calle&#039; con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#article\",\"name\":\"Badajoz fomentar\\u00e1 el \\u2018Carnaval de calle\\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias\",\"headline\":\"Badajoz fomentar\\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160125145838_800.jpg\",\"width\":800,\"height\":600},\"datePublished\":\"2016-01-25T23:45:54+01:00\",\"dateModified\":\"2016-01-25T23:45:54+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#listItem\",\"name\":\"Badajoz fomentar\\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#listItem\",\"position\":3,\"name\":\"Badajoz fomentar\\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/\",\"name\":\"Badajoz fomentar\\u00e1 el \\u2018Carnaval de calle\\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias\",\"description\":\"La ciudad de Badajoz celebrar\\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\\u00e9s Tur\\u00edstico Nacional que este a\\u00f1o fomentar\\u00e1 el 'Carnaval de calle' con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160125145838_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\\\/#mainImage\"},\"datePublished\":\"2016-01-25T23:45:54+01:00\",\"dateModified\":\"2016-01-25T23:45:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias","description":"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el 'Carnaval de calle' con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#article","name":"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias","headline":"Badajoz fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg","width":800,"height":600},"datePublished":"2016-01-25T23:45:54+01:00","dateModified":"2016-01-25T23:45:54+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#listItem","name":"Badajoz fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#listItem","position":3,"name":"Badajoz fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/","name":"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias","description":"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el 'Carnaval de calle' con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/#mainImage"},"datePublished":"2016-01-25T23:45:54+01:00","dateModified":"2016-01-25T23:45:54+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias","og:description":"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el 'Carnaval de calle' con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg","og:image:width":800,"og:image:height":600,"article:published_time":"2016-01-25T22:45:54+00:00","article:modified_time":"2016-01-25T22:45:54+00:00","twitter:card":"summary_large_image","twitter:title":"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo | El Digital de Asturias","twitter:description":"La ciudad de Badajoz celebrar\u00e1 del 5 al 9 de febrero el Carnaval, Fiesta de Inter\u00e9s Tur\u00edstico Nacional que este a\u00f1o fomentar\u00e1 el 'Carnaval de calle' con actuaciones de murgas infantiles, juveniles y de adultos, tanto inscritas como no en el concurso oficial de este tipo de agrupaciones, en distintos puntos del Casco Antiguo. El","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160125145838_800.jpg"},"aioseo_meta_data":{"post_id":"62040","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 22:26:36","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:41:41","updated":"2026-05-22 22:26:36"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/\" title=\"Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo\">Badajoz fomentar\u00e1 el \u2018Carnaval de calle\u2019 con actuaciones de murgas en el Casco Antiguo<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Badajoz fomentar\u00e1 el &#8216;Carnaval de calle&#8217; con actuaciones de murgas en el Casco Antiguo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/badajoz-fomentara-el-carnaval-de-calle-con-actuaciones-de-murgas-en-el-casco-antiguo\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=62040"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/62040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/62041"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=62040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=62040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=62040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}