{"id":61843,"date":"2016-01-23T13:58:16","date_gmt":"2016-01-23T12:58:16","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61843"},"modified":"2016-01-23T13:58:16","modified_gmt":"2016-01-23T12:58:16","slug":"los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/","title":{"rendered":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61844\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-360x270.jpg\" alt=\"fotonoticia_20160122152454_800\" width=\"360\" height=\"270\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-360x270.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-650x488.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-768x576.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-150x113.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-450x338.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-80x60.jpg 80w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-265x198.jpg 265w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-696x522.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-560x420.jpg 560w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-90x67.jpg 90w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-164x124.jpg 164w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800-100x75.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el cinco por ciento de media.<\/p>\n<p>En una nota, la CECA ha expresado el \u00aboptimismo\u00bb del sector \u00abfruto de la mejora de la llegada de turistas a la regi\u00f3n, con 26 millones de visitantes en 2015, que generaron en determinadas zonas tur\u00edsticas hasta el cinco y el 10 por ciento del consumo global en el sector\u00bb.<\/p>\n<p>Con motivo de la inauguraci\u00f3n de la Feria Internacional de Turismo (Fitur) en Madrid, el presidente de la Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA), Manuel Garc\u00eda-Izquierdo Parralo, ha valorado \u00abel potencial que tiene el binomio turismo y comercio para la econom\u00eda andaluza\u00bb.<\/p>\n<p>A su juicio, \u00abel mejor ejemplo de ello son los datos de recepci\u00f3n de turistas que ha cosechado Andaluc\u00eda en 2015, con 26 millones de visitantes, que han llegado a generar en determinadas zonas tur\u00edsticas hasta el cinco y el diez por ciento del consumo global en el sector\u00bb, unas cifras que \u00abpermiten al comercio afrontar 2016 con cierto optimismo, previendo una mejora del gasto medio que realizan los turistas en el comercio que podr\u00eda oscilar entre el tres y hasta el cinco por ciento de media\u00bb.<\/p>\n<p>\u00abNuestros comerciantes vienen haciendo grandes esfuerzos en los \u00faltimos a\u00f1os por ofrecer al turista el mejor servicio y atenci\u00f3n especializadas, pero debemos incidir que \u00e9sta es una tarea de todos, en la que debemos caminar de la mano con la Junta de Andaluc\u00eda, corporaciones locales y diputaciones as\u00ed como todos los sectores econ\u00f3micos implicados, para posicionar nuestras ciudades como lugares de especial atractivo de compras\u00bb, argumenta Garc\u00eda-Izquierdo.<\/p>\n<p>Seg\u00fan las estimaciones de CECA, el gasto realizado por turistas en el comercio en aquellas \u00e1reas con mayor desarrollo tur\u00edstico \u00abpodr\u00eda ser incluso mayor si tenemos en cuenta adem\u00e1s el turismo residencial, profesional o de congresos, y el patrimonial\u00bb.<\/p>\n<p>El turismo de compras representa \u00abun gran potencial econ\u00f3mico sobre el que se debe seguir trabajando\u00bb. A su juicio, en Andaluc\u00eda, \u00abimplicar a los centros comerciales abiertos (CCA) es garant\u00eda de \u00e9xito en la promoci\u00f3n de actividades e iniciativas atractivas para los visitantes, pues ha demostrado ser un modelo de gesti\u00f3n p\u00fablico-privada eficaz, ofreciendo incluso en algunos casos rutas tur\u00edstico-comerciales de gran inter\u00e9s\u00bb.<\/p>\n<p>No obstante, el presidente de CECA ha recordado la importancia de que, \u00abtanto desde la Junta de Andaluc\u00eda como desde el Gobierno central, se*realicen acciones de promoci\u00f3n e informaci\u00f3n de las caracter\u00edsticas del comercio y las posibilidades que ofrece en origen\u00bb, puesto que \u00abla oferta comercial debe ser el punto de partida que seduzca al potencial viajero, ofreciendo informaci\u00f3n segmentada por territorios y subsectores comerciales y no s\u00f3lo atendiendo al atractivo cultural, gastron\u00f3mico o estilo de vida de la ciudad en cuesti\u00f3n\u00bb, conclu\u00eda Garc\u00eda-Izquierdo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el<\/p>\n","protected":false},"author":1,"featured_media":61844,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-61843","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-23T12:58:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-23T12:58:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#article\",\"name\":\"Los comerciantes andaluces prev\\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias\",\"headline\":\"Los comerciantes andaluces prev\\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160122152454_800.jpg\",\"width\":800,\"height\":600},\"datePublished\":\"2016-01-23T13:58:16+01:00\",\"dateModified\":\"2016-01-23T13:58:16+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#listItem\",\"name\":\"Los comerciantes andaluces prev\\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#listItem\",\"position\":3,\"name\":\"Los comerciantes andaluces prev\\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/\",\"name\":\"Los comerciantes andaluces prev\\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias\",\"description\":\"La Confederaci\\u00f3n Empresarial de Comercio de Andaluc\\u00eda (CECA) se ha mostrado optimista ante la previsi\\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\\u00e9n para este a\\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\\u00eda experimentar una mejorara de entre el tres y hasta el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160122152454_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\\\/#mainImage\"},\"datePublished\":\"2016-01-23T13:58:16+01:00\",\"dateModified\":\"2016-01-23T13:58:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias","description":"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#article","name":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias","headline":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg","width":800,"height":600},"datePublished":"2016-01-23T13:58:16+01:00","dateModified":"2016-01-23T13:58:16+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#listItem","name":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#listItem","position":3,"name":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/","name":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias","description":"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/#mainImage"},"datePublished":"2016-01-23T13:58:16+01:00","dateModified":"2016-01-23T13:58:16+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias","og:description":"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg","og:image:width":800,"og:image:height":600,"article:published_time":"2016-01-23T12:58:16+00:00","article:modified_time":"2016-01-23T12:58:16+00:00","twitter:card":"summary_large_image","twitter:title":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz | El Digital de Asturias","twitter:description":"La Confederaci\u00f3n Empresarial de Comercio de Andaluc\u00eda (CECA) se ha mostrado optimista ante la previsi\u00f3n de incremento del gasto de los turistas en el comercio andaluz y prev\u00e9n para este a\u00f1o un incremento del gasto medio que realizan los turistas en el comercio, que podr\u00eda experimentar una mejorara de entre el tres y hasta el","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160122152454_800.jpg"},"aioseo_meta_data":{"post_id":"61843","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 22:01:53","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:44:59","updated":"2026-05-22 22:01:53"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/\" title=\"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz\">Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Los comerciantes andaluces prev\u00e9n un incremento del 3% al 5% del gasto de los turistas en el comercio andaluz","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-comerciantes-andaluces-preven-un-incremento-del-3-al-5-del-gasto-de-los-turistas-en-el-comercio-andaluz\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61843"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/61844"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}