{"id":61732,"date":"2016-01-23T12:54:53","date_gmt":"2016-01-23T11:54:53","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61732"},"modified":"2016-01-23T12:54:53","modified_gmt":"2016-01-23T11:54:53","slug":"la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/","title":{"rendered":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61733\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-360x240.jpg\" alt=\"fotonoticia_20160121203013_800\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-650x433.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-768x512.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-696x464.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-630x420.jpg 630w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800-101x66.jpg 101w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por \u00abimpulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n\u00bb con el objetivo de \u00abdesestacionalizar e incrementar la rentabilidad del turismo\u00bb en la regi\u00f3n, y as\u00ed \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb.<\/p>\n<p>As\u00ed se ha pronunciado el secretario auton\u00f3mico de Turismo, Francesc Colomer, este jueves en la segunda jornada de Fitur, que ha contado con la presencia del &#8216;president&#8217; de la Generalitat, Ximo Puig, ha informado la Generalitat a trav\u00e9s de un comunicado.<\/p>\n<p>La Agencia Valenciana de Turismo ha participado en la 36\u00aa edici\u00f3n del certamen apoyando a la iniciativa &#8216;Yo soy noticia&#8217; del periodista valenciano Pedro Morata, adem\u00e1s de la presentaci\u00f3n de D\u00e9nia (Alicante) Ciudad Creativa Gastron\u00f3mica de la Unesco, el Congreso Nacional &#8216;Euro-Toques&#8217; y en la entrega de los certificados I+D+i de Asociaci\u00f3n Espa\u00f1ola de Normalizaci\u00f3n y Certificaci\u00f3n (Aenor) al Instituto Valenciano de Tecnolog\u00edas Tur\u00edsticas (Invat.tur).<\/p>\n<p>Durante su intervenci\u00f3n, Colomer ha asegurado que la Generalitat \u00abha venido a explicarle al mundo que es hora de volver a construir un encuentro donde la \u00e9tica y la est\u00e9tica se unen\u00bb. \u00abEstamos aqu\u00ed para recordar a los mercados que es hora de volver a lo genuino, a lo aut\u00e9ntico, a la cultura, a las playas, a la luz, al Mediterr\u00e1neo\u00bb, ha manifestado.<\/p>\n<p>En la presentaci\u00f3n de D\u00e9nia Ciudad Creativa Gastron\u00f3mica, el responsable de Turismo ha querido \u00abdar la enhorabuena\u00bb al sector local, y a quienes \u00abse dedican a custodiar lo mejor del pasado y a conjugarlo con la creatividad y la vanguardia\u00bb. Para \u00e9l, la elecci\u00f3n del municipio alicantino por la Unesco \u00abes un importante colof\u00f3n a los buenos resultados de 2015\u00bb, que \u00abha sido un gran a\u00f1o en cifras y debe inspirarnos para hacer las cosas mejor\u00bb.<\/p>\n<p>Asimismo, Colomer ha resaltado que se trata de un reconocimiento que \u00abno s\u00f3lo beneficia a Denia, sino que se abre a toda la comarca y por extensi\u00f3n a toda la Comunitat Valenciana\u00bb.<\/p>\n<p>LA COCINA VALENCIANA, EN SU \u00abEDAD DE ORO\u00bb<\/p>\n<p>Posteriormente se ha celebrado el acto de presentaci\u00f3n del Congreso &#8216;Euro-Toques&#8217;, una asamblea nacional que acoger\u00e1 Elche (Alicante) el pr\u00f3ximo mes de mayo y que reunir\u00e1 a cerca de 300 cocineros de todo el mundo. Este acto ha contado con la presencia de la \u00abembajadora de la gastronom\u00eda de la Comunitat\u00bb, la chef valenciana Susi D\u00edaz.<\/p>\n<p>En su discurso, el secretario auton\u00f3mico ha reconocido el trabajo diario de la Red de Centros de Turismo de la Comunitat y ha reivindicado el \u00abprestigio social\u00bb de los chefs. \u00abOjal\u00e1 fu\u00e9ramos capaces de abrir el angular y potenciar el reconocimiento de otros profesionales del sector\u00bb, ha aseverado.<\/p>\n<p>En esta l\u00ednea, ha se\u00f1alado que la gastronom\u00eda valenciana \u00abest\u00e1 viviendo una edad de oro y debemos aprovecharla\u00bb, para as\u00ed \u00abproteger la cultura culinaria y la sabidur\u00eda ancestral de los fogones\u00bb. Para \u00e9l, &#8216;Euro-Toques&#8217; \u00abes un reflejo de la cultura del esfuerzo\u00bb, y ha indicado que \u00abcomenzar un proyecto requiere coraje pero acabarlo requiere constancia\u00bb.<\/p>\n<p>\u00abRECONCILIAR\u00bb TURISMO Y DEPORTE<\/p>\n<p>Finalmente, en la presentaci\u00f3n de la iniciativa &#8216;Yo soy noticia&#8217;, que combina deporte, turismo y nuevas tecnolog\u00edas, y, seg\u00fan Francesc Colomer, \u00abbusca reconciliar dos \u00e1mbitos fundamentales de nuestra forma de ser como valencianos, de nuestra forma de entender y aprovechar el tiempo libre\u00bb.<\/p>\n<p>\u00abEl deporte vertebra el territorio y constituye un aut\u00e9ntico producto tur\u00edstico\u00bb, ha manifestado, por lo que \u00abideas como las de Pedro Morata son hitos de m\u00e1xima jerarqu\u00eda en nuestra vida social y pueden dar muchas alegr\u00edas al turismo\u00bb.<\/p>\n<p>LA \u00abPUNTA DE LANZA\u00bb DEL TURISMO<\/p>\n<p>Por otro lado, los establecimientos que han recibido este jueves en Fitur certificados de gesti\u00f3n de I+D+i de Aenor han sido las agencias de viaje, CV Incoming, \u00danico Viajes e Idealtours, el Hotel Balneario de Cofrentes (Valencia), el Balneario de Montanejos (Castell\u00f3n) y el Camping Mariola de Bocairent (Valencia).<\/p>\n<p>Para el responsable de Turismo, estos certificados \u00abdistinguen al sector empresarial tur\u00edstico valenciano como la punta de lanza en este \u00e1mbito\u00bb. \u00abSu competitividad pasa por contar con los mejores profesionales y con aquellos que saben transformar sus ideas en proyectos, compartiendo conocimiento entre empresas, servicios y destinos tur\u00edsticos\u00bb, ha a\u00f1adido.<\/p>\n<p>En este sentido, Colomer ha se\u00f1alado que desde la Generalitat \u00abse trabaja por hacer del turismo de la Comunitat un sector din\u00e1mico en base a la aplicaci\u00f3n de la innovaci\u00f3n y la tecnolog\u00eda\u00bb, con el objetivo de \u00abasociar su imagen de marca a valores como la anticipaci\u00f3n, la investigaci\u00f3n aplicada y el emprendimiento\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por \u00abimpulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n\u00bb con el objetivo de \u00abdesestacionalizar e incrementar la rentabilidad del turismo\u00bb en la regi\u00f3n, y as\u00ed \u00abvolver a lo genuino, lo<\/p>\n","protected":false},"author":1,"featured_media":61733,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":{"0":"post-61732","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad-turismo"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por &quot;impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n&quot; con el objetivo de &quot;desestacionalizar e incrementar la rentabilidad del turismo&quot; en la regi\u00f3n, y as\u00ed &quot;volver a lo genuino, lo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por &quot;impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n&quot; con el objetivo de &quot;desestacionalizar e incrementar la rentabilidad del turismo&quot; en la regi\u00f3n, y as\u00ed &quot;volver a lo genuino, lo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-23T11:54:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-23T11:54:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por &quot;impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n&quot; con el objetivo de &quot;desestacionalizar e incrementar la rentabilidad del turismo&quot; en la regi\u00f3n, y as\u00ed &quot;volver a lo genuino, lo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#article\",\"name\":\"La Generalitat Valenciana apuesta por \\u00abvolver a lo genuino, lo aut\\u00e9ntico y a la esencia del Mediterr\\u00e1neo\\u00bb | El Digital de Asturias\",\"headline\":\"La Generalitat Valenciana apuesta por \\u00abvolver a lo genuino, lo aut\\u00e9ntico y a la esencia del Mediterr\\u00e1neo\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160121203013_800.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2016-01-23T12:54:53+01:00\",\"dateModified\":\"2016-01-23T12:54:53+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#listItem\",\"name\":\"La Generalitat Valenciana apuesta por \\u00abvolver a lo genuino, lo aut\\u00e9ntico y a la esencia del Mediterr\\u00e1neo\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#listItem\",\"position\":3,\"name\":\"La Generalitat Valenciana apuesta por \\u00abvolver a lo genuino, lo aut\\u00e9ntico y a la esencia del Mediterr\\u00e1neo\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/\",\"name\":\"La Generalitat Valenciana apuesta por \\u00abvolver a lo genuino, lo aut\\u00e9ntico y a la esencia del Mediterr\\u00e1neo\\u00bb | El Digital de Asturias\",\"description\":\"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por \\\"impulsar nuevos productos tur\\u00edsticos que fomenten el deporte, la gastronom\\u00eda y la innovaci\\u00f3n\\\" con el objetivo de \\\"desestacionalizar e incrementar la rentabilidad del turismo\\\" en la regi\\u00f3n, y as\\u00ed \\\"volver a lo genuino, lo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160121203013_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\\\/#mainImage\"},\"datePublished\":\"2016-01-23T12:54:53+01:00\",\"dateModified\":\"2016-01-23T12:54:53+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias","description":"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por \"impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n\" con el objetivo de \"desestacionalizar e incrementar la rentabilidad del turismo\" en la regi\u00f3n, y as\u00ed \"volver a lo genuino, lo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#article","name":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias","headline":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg","width":800,"height":533},"datePublished":"2016-01-23T12:54:53+01:00","dateModified":"2016-01-23T12:54:53+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#listItem","name":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#listItem","position":3,"name":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/","name":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias","description":"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por \"impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n\" con el objetivo de \"desestacionalizar e incrementar la rentabilidad del turismo\" en la regi\u00f3n, y as\u00ed \"volver a lo genuino, lo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/#mainImage"},"datePublished":"2016-01-23T12:54:53+01:00","dateModified":"2016-01-23T12:54:53+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias","og:description":"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por &quot;impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n&quot; con el objetivo de &quot;desestacionalizar e incrementar la rentabilidad del turismo&quot; en la regi\u00f3n, y as\u00ed &quot;volver a lo genuino, lo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2016-01-23T11:54:53+00:00","article:modified_time":"2016-01-23T11:54:53+00:00","twitter:card":"summary_large_image","twitter:title":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb | El Digital de Asturias","twitter:description":"La Generalitat Valenciana ha presentado en la jornada de la Comunitat en la Feria Internacional de Turismo (Fitur) su apuesta por &quot;impulsar nuevos productos tur\u00edsticos que fomenten el deporte, la gastronom\u00eda y la innovaci\u00f3n&quot; con el objetivo de &quot;desestacionalizar e incrementar la rentabilidad del turismo&quot; en la regi\u00f3n, y as\u00ed &quot;volver a lo genuino, lo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121203013_800.jpg"},"aioseo_meta_data":{"post_id":"61732","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-25 09:35:58","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:45:45","updated":"2025-09-25 09:35:58"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/\" title=\"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb\">La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"La Generalitat Valenciana apuesta por \u00abvolver a lo genuino, lo aut\u00e9ntico y a la esencia del Mediterr\u00e1neo\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-generalitat-valenciana-apuesta-por-volver-a-lo-genuino-lo-autentico-y-a-la-esencia-del-mediterraneo\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61732"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/61733"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}