{"id":61712,"date":"2016-01-23T12:36:52","date_gmt":"2016-01-23T11:36:52","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61712"},"modified":"2016-01-23T12:36:52","modified_gmt":"2016-01-23T11:36:52","slug":"united-continental-gano-7-340-millones-a-cierre-de-2015","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/","title":{"rendered":"United Continental gan\u00f3 7.340 millones a cierre de 2015"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61713\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-360x240.jpg\" alt=\"fotonoticia_20160121194253_800\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-650x433.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-768x512.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-696x464.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-630x420.jpg 630w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800-101x66.jpg 101w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el &#8216;holding&#8217;.<\/p>\n<p>La facturaci\u00f3n del grupo se redujo un 2,7%, hasta los 37.864 millones de d\u00f3lares (34.916 millones de euros), mientras que los costes disminuyeron un 10,5%, hasta los 36.528 millones de d\u00f3lares (33.684 millones de euros). La partida del combustible cay\u00f3 un 35,6%.<\/p>\n<p>El consejero delegado actual de UAL, Brett J. Hatt, destac\u00f3 que la compa\u00f1\u00eda mejor\u00f3 su rendimiento operativo, continu\u00f3 invirtiendo en sus productos y servicios y registr\u00f3 una actuaci\u00f3n financiera r\u00e9cord.<\/p>\n<p>Con respecto a las cuentas del cuarto y \u00faltimo trimestre de 2015, UAL gan\u00f3 823 millones de d\u00f3lares (759 millones de euros) frente a los 28 millones de d\u00f3lares (26 millones de euros) registrados en el mismo periodo del a\u00f1o anterior.<\/p>\n<p>Por otro lado, destaca la ca\u00edda del 9,3% de los pasajeros transportados en vuelos regionales a cierre de 2015 de la compa\u00f1\u00eda y el descenso del 3,1% del transporte de carga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el &#8216;holding&#8217;. La facturaci\u00f3n del grupo se redujo<\/p>\n","protected":false},"author":1,"featured_media":61713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-61712","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el &#039;holding&#039;. La facturaci\u00f3n del grupo se redujo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el &#039;holding&#039;. La facturaci\u00f3n del grupo se redujo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-23T11:36:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-23T11:36:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el &#039;holding&#039;. La facturaci\u00f3n del grupo se redujo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#article\",\"name\":\"United Continental gan\\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias\",\"headline\":\"United Continental gan\\u00f3 7.340 millones a cierre de 2015\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160121194253_800.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2016-01-23T12:36:52+01:00\",\"dateModified\":\"2016-01-23T12:36:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#listItem\",\"name\":\"United Continental gan\\u00f3 7.340 millones a cierre de 2015\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#listItem\",\"position\":3,\"name\":\"United Continental gan\\u00f3 7.340 millones a cierre de 2015\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/\",\"name\":\"United Continental gan\\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias\",\"description\":\"United Continental (UAL) registr\\u00f3 un beneficio de 7.340 millones de d\\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\\u00e1s que las ganancias de 1.132 millones de d\\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\\u00edda del precio del petr\\u00f3leo, inform\\u00f3 el 'holding'. La facturaci\\u00f3n del grupo se redujo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160121194253_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/united-continental-gano-7-340-millones-a-cierre-de-2015\\\/#mainImage\"},\"datePublished\":\"2016-01-23T12:36:52+01:00\",\"dateModified\":\"2016-01-23T12:36:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias","description":"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el 'holding'. La facturaci\u00f3n del grupo se redujo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#article","name":"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias","headline":"United Continental gan\u00f3 7.340 millones a cierre de 2015","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg","width":800,"height":533},"datePublished":"2016-01-23T12:36:52+01:00","dateModified":"2016-01-23T12:36:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#listItem","name":"United Continental gan\u00f3 7.340 millones a cierre de 2015"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#listItem","position":3,"name":"United Continental gan\u00f3 7.340 millones a cierre de 2015","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/","name":"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias","description":"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el 'holding'. La facturaci\u00f3n del grupo se redujo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/#mainImage"},"datePublished":"2016-01-23T12:36:52+01:00","dateModified":"2016-01-23T12:36:52+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias","og:description":"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el 'holding'. La facturaci\u00f3n del grupo se redujo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2016-01-23T11:36:52+00:00","article:modified_time":"2016-01-23T11:36:52+00:00","twitter:card":"summary_large_image","twitter:title":"United Continental gan\u00f3 7.340 millones a cierre de 2015 | El Digital de Asturias","twitter:description":"United Continental (UAL) registr\u00f3 un beneficio de 7.340 millones de d\u00f3lares (6.769 millones de euros) a cierre de 2015, casi siete veces m\u00e1s que las ganancias de 1.132 millones de d\u00f3lares (1.044 millones de euros) obtenidas en 2014, gracias a la ca\u00edda del precio del petr\u00f3leo, inform\u00f3 el 'holding'. La facturaci\u00f3n del grupo se redujo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121194253_800.jpg"},"aioseo_meta_data":{"post_id":"61712","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 21:42:03","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:45:45","updated":"2026-05-22 21:42:03"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/\" title=\"United Continental gan\u00f3 7.340 millones a cierre de 2015\">United Continental gan\u00f3 7.340 millones a cierre de 2015<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"United Continental gan\u00f3 7.340 millones a cierre de 2015","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/united-continental-gano-7-340-millones-a-cierre-de-2015\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61712"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/61713"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}