{"id":61688,"date":"2016-01-23T12:21:08","date_gmt":"2016-01-23T11:21:08","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61688"},"modified":"2016-01-23T12:21:08","modified_gmt":"2016-01-23T11:21:08","slug":"barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/","title":{"rendered":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61689\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-360x270.jpg\" alt=\"fotonoticia_20160121190822_800\" width=\"360\" height=\"270\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-360x270.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-650x488.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-768x576.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-150x113.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-450x338.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-80x60.jpg 80w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-265x198.jpg 265w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-696x522.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-560x420.jpg 560w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-90x67.jpg 90w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-164x124.jpg 164w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800-100x75.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur.<\/p>\n<p>Colom ha abogado por \u00abavanzar de forma sistem\u00e1tica hacia la adopci\u00f3n de modelos de desarrollo sostenibles a favor del medio ambiente, la diversidad cultural y la responsabilidad social\u00bb, ha informado el Ayuntamiento en un comunicado.<\/p>\n<p>Barcelona fue el primer destino urbano en recibir la certificaci\u00f3n Biosphere World Class Destination en 2011, certificaci\u00f3n que renov\u00f3 en 2014, y la ciudad tambi\u00e9n es miembro del Global Sustainable Tourism Council, una alianza p\u00fablico-privada que defiende que el turismo aporte riqueza econ\u00f3mica y social, con empleo de calidad y conservaci\u00f3n de la naturaleza y la cultura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por \u00abavanzar de forma sistem\u00e1tica hacia la<\/p>\n","protected":false},"author":1,"featured_media":61689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":{"0":"post-61688","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad-turismo"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por &quot;avanzar de forma sistem\u00e1tica hacia la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por &quot;avanzar de forma sistem\u00e1tica hacia la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-23T11:21:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-23T11:21:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por &quot;avanzar de forma sistem\u00e1tica hacia la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#article\",\"name\":\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias\",\"headline\":\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160121190822_800.jpg\",\"width\":800,\"height\":600},\"datePublished\":\"2016-01-23T12:21:08+01:00\",\"dateModified\":\"2016-01-23T12:21:08+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#listItem\",\"name\":\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#listItem\",\"position\":3,\"name\":\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/\",\"name\":\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias\",\"description\":\"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\\u00f3n de Euskadi en Fitur. Colom ha abogado por \\\"avanzar de forma sistem\\u00e1tica hacia la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160121190822_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\\\/#mainImage\"},\"datePublished\":\"2016-01-23T12:21:08+01:00\",\"dateModified\":\"2016-01-23T12:21:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias","description":"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por \"avanzar de forma sistem\u00e1tica hacia la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#article","name":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias","headline":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg","width":800,"height":600},"datePublished":"2016-01-23T12:21:08+01:00","dateModified":"2016-01-23T12:21:08+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#listItem","name":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#listItem","position":3,"name":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/","name":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias","description":"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por \"avanzar de forma sistem\u00e1tica hacia la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/#mainImage"},"datePublished":"2016-01-23T12:21:08+01:00","dateModified":"2016-01-23T12:21:08+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias","og:description":"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por &quot;avanzar de forma sistem\u00e1tica hacia la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg","og:image:width":800,"og:image:height":600,"article:published_time":"2016-01-23T11:21:08+00:00","article:modified_time":"2016-01-23T11:21:08+00:00","twitter:card":"summary_large_image","twitter:title":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20 | El Digital de Asturias","twitter:description":"El concejal de Empleo, Empresa y Turismo del Ayuntamiento de Barcelona, Agust\u00ed Colom, ha apoyado este jueves la Carta Mundial de Turismo Sostenible +20 participando en su entrega a la Organizaci\u00f3n Mundial del Turismo (OMT) en un acto en el pabell\u00f3n de Euskadi en Fitur. Colom ha abogado por &quot;avanzar de forma sistem\u00e1tica hacia la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160121190822_800.jpg"},"aioseo_meta_data":{"post_id":"61688","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-25 09:30:02","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:46:43","updated":"2025-09-25 09:30:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/\" title=\"Barcelona apoya la Carta Mundial de Turismo Sostenible +20\">Barcelona apoya la Carta Mundial de Turismo Sostenible +20<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Barcelona apoya la Carta Mundial de Turismo Sostenible +20","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/barcelona-apoya-la-carta-mundial-de-turismo-sostenible-20\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61688"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/61689"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}