{"id":61519,"date":"2016-01-22T18:28:57","date_gmt":"2016-01-22T17:28:57","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61519"},"modified":"2016-01-22T18:28:57","modified_gmt":"2016-01-22T17:28:57","slug":"la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/","title":{"rendered":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61520\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-248x300.jpg\" alt=\"fotonoticia_20160120202506_800\" width=\"248\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-248x300.jpg 248w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-529x640.jpg 529w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-768x929.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-150x182.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-450x545.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-696x842.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800-347x420.jpg 347w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg 800w\" sizes=\"(max-width: 248px) 100vw, 248px\" \/>La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas\u00bb a un precio muy competitivo y con una amplia oferta\u00bb.<\/p>\n<p>\u00abCon la firma de este convenio y el apoyo a esta iniciativa se ofrece al viajero una mayor integraci\u00f3n de oferta y demanda aprovechando la excelente conectividad de nuestra regi\u00f3n y las infraestructuras de transporte m\u00e1s vanguardistas y competitivas del momento, de las que Espa\u00f1a es l\u00edder y referente mundial\u00bb, ha subrayado Fern\u00e1ndez de C\u00f3rdova.<\/p>\n<p>El convenio, que se ha firmado con la Asociaci\u00f3n Red Ciudades AVE e incluye a las comunidades aut\u00f3nomas de Castila y Le\u00f3n, Catalu\u00f1a, Valencia y Madrid, sienta las bases de cooperaci\u00f3n entre las instituciones p\u00fablicas, las privadas, administraciones regionales y municipales, y supone el apoyo del Gobierno regional con medidas como la formaci\u00f3n de personal y el apoyo financiero.<\/p>\n<p>Fern\u00e1ndez de C\u00f3rdova ha destacado que con esta iniciativa de Avexperience supone una nueva apuesta del Gobierno regional para atraer turistas a la regi\u00f3n y ha a\u00f1adido que los datos publicados esta semana sobre la afluencia tur\u00edstica a la Comunidad \u00abofrecen una perspectiva muy positiva: desde enero a noviembre de 2015 nos han visitado 10,3 millones de turistas\u00bb.<\/p>\n<p>En este sentido, ha indicado que con toda probabilidad se superar\u00e1n los once millones de visitantes en las estad\u00edsticas del \u00faltimo mes. \u00abLa interpretaci\u00f3n de estas cifras nos revela que hemos experimentado un incremento del 9,13 por ciento, muy por encima de la media espa\u00f1ola, y las perspectivas auguran que el sector seguir\u00e1 creciendo en 2016\u00bb, ha agregado la directora de la Oficina.<\/p>\n<p>MARCA MADRID<\/p>\n<p>Fern\u00e1ndez de C\u00f3rdova ha recordado que el Gobierno regional est\u00e1 trabajando en la creaci\u00f3n de la marca Madrid que dar\u00e1 cumplimiento a una exigencia del sector tur\u00edstico y de las administraciones p\u00fablicas: posicionar a la regi\u00f3n en el nivel de los grandes destinos tur\u00edsticos del mundo, reforzando su atractivo con todo su Patrimonio art\u00edstico, natural, cultural y gastron\u00f3mico, entre otros.<\/p>\n<p>\u00abContamos con tres ciudades Patrimonio de la Humanidad -San Lorenzo de El Escorial, Alcal\u00e1 de Henares y Aranjuez- y el Parque Nacional de Guadarrama, Reserva de la Bioesfera. Sin duda, la firma de este convenio colaborar\u00e1 para dar a conocer esta importante oferta a los visitantes de nuestra regi\u00f3n\u00bb, ha concluido la directora de la Oficina de Cultura y Turismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas\u00bb a un precio muy competitivo y con una<\/p>\n","protected":false},"author":1,"featured_media":61520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-61519","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas&quot; a un precio muy competitivo y con una\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas&quot; a un precio muy competitivo y con una\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"968\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-22T17:28:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-22T17:28:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas&quot; a un precio muy competitivo y con una\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#article\",\"name\":\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\\u00f3n en AVE | El Digital de Asturias\",\"headline\":\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\\u00f3n en AVE\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160120202506_800.jpg\",\"width\":800,\"height\":968},\"datePublished\":\"2016-01-22T18:28:57+01:00\",\"dateModified\":\"2016-01-22T18:28:57+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#listItem\",\"name\":\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\\u00f3n en AVE\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#listItem\",\"position\":3,\"name\":\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\\u00f3n en AVE\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/\",\"name\":\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\\u00f3n en AVE | El Digital de Asturias\",\"description\":\"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\\u00e1ndez de C\\u00f3rdova, ha firmado h un convenio para la promoci\\u00f3n de Avexperience, un nuevo producto tur\\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\\u00f3nomas\\\" a un precio muy competitivo y con una\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160120202506_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#mainImage\",\"width\":800,\"height\":968},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\\\/#mainImage\"},\"datePublished\":\"2016-01-22T18:28:57+01:00\",\"dateModified\":\"2016-01-22T18:28:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias","description":"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas\" a un precio muy competitivo y con una","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#article","name":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias","headline":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg","width":800,"height":968},"datePublished":"2016-01-22T18:28:57+01:00","dateModified":"2016-01-22T18:28:57+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#listItem","name":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#listItem","position":3,"name":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/","name":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias","description":"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas\" a un precio muy competitivo y con una","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#mainImage","width":800,"height":968},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/#mainImage"},"datePublished":"2016-01-22T18:28:57+01:00","dateModified":"2016-01-22T18:28:57+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias","og:description":"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas&quot; a un precio muy competitivo y con una","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg","og:image:width":800,"og:image:height":968,"article:published_time":"2016-01-22T17:28:57+00:00","article:modified_time":"2016-01-22T17:28:57+00:00","twitter:card":"summary_large_image","twitter:title":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE | El Digital de Asturias","twitter:description":"La directora de la Oficina de Cultura y Turismo, Anunciada Fern\u00e1ndez de C\u00f3rdova, ha firmado h un convenio para la promoci\u00f3n de Avexperience, un nuevo producto tur\u00edstico con el que se obtiene un paquete de viajes en AVE y hoteles en 21 ciudades y cuatro comunidades aut\u00f3nomas&quot; a un precio muy competitivo y con una","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120202506_800.jpg"},"aioseo_meta_data":{"post_id":"61519","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 21:13:27","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:48:43","updated":"2026-05-22 21:13:27"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/\" title=\"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE\">La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"La Comunidad de Madrid firma un convenio para fomentar viajes personalizados a la regi\u00f3n en AVE","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-comunidad-de-madrid-firma-un-convenio-para-fomentar-viajes-personalizados-a-la-region-en-ave\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61519"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/61520"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}