{"id":61464,"date":"2016-01-22T18:09:45","date_gmt":"2016-01-22T17:09:45","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61464"},"modified":"2016-01-22T18:09:45","modified_gmt":"2016-01-22T17:09:45","slug":"penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/","title":{"rendered":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la &#8216;Gu\u00eda Verde Michelin&#8217;"},"content":{"rendered":"<p>El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n &#8216;La Gu\u00eda Verde&#8217; de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas.<\/p>\n<p>   Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en Espa\u00f1a como en Portugal, entrar\u00e1 en vigor a partir del 1 de abril.<\/p>\n<p>   En este sentido, la rectora comercial de Michelin Travel Partner Espa\u00f1a y Portugal, Mayte Carre\u00f1o, ha afirmado que han buscado \u00abun aliado de referencia\u00bb para \u00abconsolidar una fuerte apuesta por el mercado de publicaciones tur\u00edsticas\u00bb.<\/p>\n<p>   Por su parte, el director comercial de Penguin Random House Grupo Editorial, Patxi Beascoa, ha se\u00f1alado que \u00aba trav\u00e9s de este acuerdo con Michelin Travel Partner\u00bb refueran \u00absu cat\u00e1logo y presencia en el sector de turismo y viajes\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n &#8216;La Gu\u00eda Verde&#8217; de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en<\/p>\n","protected":false},"author":1,"featured_media":38653,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-61464","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n &#039;La Gu\u00eda Verde&#039; de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n &#039;La Gu\u00eda Verde&#039; de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-22T17:09:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-22T17:09:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n &#039;La Gu\u00eda Verde&#039; de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#article\",\"name\":\"Penguin Random House desarrollar\\u00e1 a partir de febrero la edici\\u00f3n de la \\u2018Gu\\u00eda Verde Michelin\\u2019 | El Digital de Asturias\",\"headline\":\"Penguin Random House desarrollar\\u00e1 a partir de febrero la edici\\u00f3n de la &#8216;Gu\\u00eda Verde Michelin&#8217;\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/rural.jpg\",\"width\":800,\"height\":527},\"datePublished\":\"2016-01-22T18:09:45+01:00\",\"dateModified\":\"2016-01-22T18:09:45+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#listItem\",\"name\":\"Penguin Random House desarrollar\\u00e1 a partir de febrero la edici\\u00f3n de la &#8216;Gu\\u00eda Verde Michelin&#8217;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#listItem\",\"position\":3,\"name\":\"Penguin Random House desarrollar\\u00e1 a partir de febrero la edici\\u00f3n de la &#8216;Gu\\u00eda Verde Michelin&#8217;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/\",\"name\":\"Penguin Random House desarrollar\\u00e1 a partir de febrero la edici\\u00f3n de la \\u2018Gu\\u00eda Verde Michelin\\u2019 | El Digital de Asturias\",\"description\":\"El grupo editorial Penguin Random House desarrollar\\u00e1 a partir de febrero la edici\\u00f3n, comercializaci\\u00f3n y distribuci\\u00f3n de la colecci\\u00f3n 'La Gu\\u00eda Verde' de las gu\\u00edas tur\\u00edsticas Michelin para los mercados de lengua espa\\u00f1ola, seg\\u00fan informan ambas compa\\u00f1\\u00edas. Asimismo, el contrato para la distribuci\\u00f3n y comercializaci\\u00f3n del resto del cat\\u00e1logo de publicaciones de Michelin, tanto en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/rural.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#mainImage\",\"width\":800,\"height\":527},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\\\/#mainImage\"},\"datePublished\":\"2016-01-22T18:09:45+01:00\",\"dateModified\":\"2016-01-22T18:09:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias","description":"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n 'La Gu\u00eda Verde' de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#article","name":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias","headline":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la &#8216;Gu\u00eda Verde Michelin&#8217;","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg","width":800,"height":527},"datePublished":"2016-01-22T18:09:45+01:00","dateModified":"2016-01-22T18:09:45+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#listItem","name":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la &#8216;Gu\u00eda Verde Michelin&#8217;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#listItem","position":3,"name":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la &#8216;Gu\u00eda Verde Michelin&#8217;","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/","name":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias","description":"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n 'La Gu\u00eda Verde' de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#mainImage","width":800,"height":527},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/#mainImage"},"datePublished":"2016-01-22T18:09:45+01:00","dateModified":"2016-01-22T18:09:45+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias","og:description":"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n 'La Gu\u00eda Verde' de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg","og:image:width":800,"og:image:height":527,"article:published_time":"2016-01-22T17:09:45+00:00","article:modified_time":"2016-01-22T17:09:45+00:00","twitter:card":"summary_large_image","twitter:title":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019 | El Digital de Asturias","twitter:description":"El grupo editorial Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n, comercializaci\u00f3n y distribuci\u00f3n de la colecci\u00f3n 'La Gu\u00eda Verde' de las gu\u00edas tur\u00edsticas Michelin para los mercados de lengua espa\u00f1ola, seg\u00fan informan ambas compa\u00f1\u00edas. Asimismo, el contrato para la distribuci\u00f3n y comercializaci\u00f3n del resto del cat\u00e1logo de publicaciones de Michelin, tanto en","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/rural.jpg"},"aioseo_meta_data":{"post_id":"61464","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 21:04:05","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:48:44","updated":"2026-05-22 21:04:05"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/\" title=\"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019\">Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la \u2018Gu\u00eda Verde Michelin\u2019<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Penguin Random House desarrollar\u00e1 a partir de febrero la edici\u00f3n de la &#8216;Gu\u00eda Verde Michelin&#8217;","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/penguin-random-house-desarrollara-a-partir-de-febrero-la-edicion-de-la-guia-verde-michelin\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61464"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/38653"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}