{"id":61398,"date":"2016-01-22T17:48:24","date_gmt":"2016-01-22T16:48:24","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=61398"},"modified":"2016-01-22T17:48:24","modified_gmt":"2016-01-22T16:48:24","slug":"la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/","title":{"rendered":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61399\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-360x270.jpg\" alt=\"fotonoticia_20160120155733_800\" width=\"360\" height=\"270\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-360x270.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-650x488.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-768x576.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-150x113.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-450x338.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-80x60.jpg 80w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-265x198.jpg 265w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-696x522.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-560x420.jpg 560w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-90x67.jpg 90w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-164x124.jpg 164w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800-100x75.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 \u00abla colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba\u00bb, y para que \u00abel incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo\u00bb.<\/p>\n<p>Cresp\u00edn, quien ha asistido junto con la presidenta de la Junta de Andaluc\u00eda, Susana D\u00edaz, a los actos de promoci\u00f3n de C\u00f3rdoba como destino tur\u00edstico en Fitur, ha destacado la consolidaci\u00f3n de la Feria Internacional del Turismo, as\u00ed como \u00ablas oportunidades de negocio que ha generado en todos estos a\u00f1os en torno a un sector en alza, que en el caso de Andaluc\u00eda y de C\u00f3rdoba es fundamental para el desarrollo econ\u00f3mico y la creaci\u00f3n de riqueza y empleo\u00bb.<\/p>\n<p>La Junta de Andaluc\u00eda, seg\u00fan ha se\u00f1alado, \u00abapuesta por que la inversi\u00f3n que hace la Junta en este evento retorne a Andaluc\u00eda y C\u00f3rdoba en forma de contratos, en turistas, en pernoctaciones, en negocios y en creaci\u00f3n de riqueza y de empleo\u00bb.<\/p>\n<p>En opini\u00f3n de Cresp\u00edn, \u00abdebemos seguir consolidando los buenos resultados que hemos obtenido en 2015, mejorar nuestro liderazgo tur\u00edstico en el conjunto del pa\u00eds y que toda la rentabilidad tur\u00edstica que ya se ha producido en 2015, y que esperamos siga produci\u00e9ndose en 2016, se traduzca en generaci\u00f3n de empleo de calidad\u00bb.<\/p>\n<p>La delegada ha puesto de relieve el respaldo institucional que la Junta de Andaluc\u00eda presta a Fitur, como escaparate internacional para potenciar el turismo, \u00abdonde mostrar la calidad, innovaci\u00f3n y la diversificaci\u00f3n de la oferta que nuestra provincia aporta\u00bb.<\/p>\n<p>Cresp\u00edn ha indicado que \u00abC\u00f3rdoba cuenta con recursos suficientes para seguir siendo destino tur\u00edstico nacional e internacional y para que el sector tur\u00edstico siga siendo b\u00e1sico en la creaci\u00f3n de riqueza y empleo de calidad en la provincia\u00bb.<\/p>\n<p>A este respecto, Cresp\u00edn ha destacado la profesionalidad del sector, al que ha mostrado su respeto por el trabajo que est\u00e1 realizando para conseguir unos est\u00e1ndares de calidad cada vez mayores, de cara a incrementar el n\u00famero de viajeros, pernoctaciones y puestos de trabajo.<\/p>\n<p>UN MILL\u00d3N DE TURISTAS EN C\u00d3RDOBA<\/p>\n<p>De hecho, seg\u00fan ha recordado, C\u00f3rdoba recibi\u00f3 entre enero y noviembre del pasado a\u00f1o m\u00e1s de un mill\u00f3n de turistas, el 57% procedentes de Espa\u00f1a, en concreto 587.185, y el 43% restante, es decir 450.260 visitantes, procedentes de otros pa\u00edses. Estas cifras suponen un incremento interanual del 2,2%.<\/p>\n<p>La provincia ha tenido en torno a 1.692.000 pernoctaciones en establecimientos hoteleros y un grado de ocupaci\u00f3n hotelera media del 46,9% de las m\u00e1s de 11.000 plazas hoteleras disponibles. El sector hotelero ha dado trabajo de media a 1.259 personas en la provincia durante este periodo, un 1,5% m\u00e1s que durante el mismo periodo de 2014.<\/p>\n<p>En estos momentos, seg\u00fan ha indicado Cresp\u00edn, \u00abC\u00f3rdoba est\u00e1 realizando un importante esfuerzo por poner en valor su oferta tur\u00edstica, gracias a sus recursos en cultura, gastronom\u00eda, historia, en combinaci\u00f3n con una capital y una provincia moderna, atractiva y bien comunicada\u00bb.<\/p>\n<p>Entre otros, cabe se\u00f1alar las actividades de los museos de Bellas Artes y Arqueol\u00f3gico, gestionados por la Administraci\u00f3n auton\u00f3mica o los esfuerzos por convertir a Medina Azahara en reclamo tur\u00edstico importante. A este respecto, la delegada ha recordado que recientemente se present\u00f3 un congreso internacional que contar\u00e1 con expertos de prestigio y el respaldo de representantes e investigadores de ciudades isl\u00e1micas que ya son Patrimonio Mundial. Todo ello en el camino a la candidatura de la ciudad califal para ser declarada por la Unesco Patrimonio Mundial.<\/p>\n<p>Por \u00faltimo, Cresp\u00edn ha destacado el incremento de visitas a la Sinagoga, con un aumento de visitantes a lo largo del pasado a\u00f1o hasta llegar a los 582.325. A ello hay que a\u00f1adir el apoyo de la Junta a la mejora de la oferta y la difusi\u00f3n de las diferentes comarcas de la provincia.<\/p>\n<p>Para la delegada, el objetivo es que \u00ablos n\u00fameros e indicadores tur\u00edsticos se reflejen en empleo estable y cualificado y, para ello, abordamos Fitur de manera muy consensuada con todos los operadores tur\u00edsticos, adem\u00e1s de con los patronatos provinciales de Turismo de las diputaciones andaluzas\u00bb.<\/p>\n<p>Cresp\u00edn conf\u00eda en que \u00abel resultado para Andaluc\u00eda en Fitur 2016 arroje un buen volumen de negocio y contratos\u00bb, insistiendo en que \u00abla inversi\u00f3n y el esfuerzo econ\u00f3mico que para el Gobierno supone la presencia de Andaluc\u00eda en Fitur solo tiene un resultado l\u00f3gico, y es que esa inversi\u00f3n vuelva en contratos, en turistas, en pernoctaciones, en negocios y en creaci\u00f3n de riqueza y de empleo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 \u00abla colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba\u00bb, y para que \u00abel incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo\u00bb. Cresp\u00edn,<\/p>\n","protected":false},"author":1,"featured_media":61399,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-61398","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 &quot;la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba&quot;, y para que &quot;el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo&quot;. Cresp\u00edn,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 &quot;la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba&quot;, y para que &quot;el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo&quot;. Cresp\u00edn,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-22T16:48:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-22T16:48:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 &quot;la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba&quot;, y para que &quot;el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo&quot;. Cresp\u00edn,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#article\",\"name\":\"La Junta aboga por la colaboraci\\u00f3n institucional para la promoci\\u00f3n de C\\u00f3rdoba | El Digital de Asturias\",\"headline\":\"La Junta aboga por la colaboraci\\u00f3n institucional para la promoci\\u00f3n de C\\u00f3rdoba\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160120155733_800.jpg\",\"width\":800,\"height\":600},\"datePublished\":\"2016-01-22T17:48:24+01:00\",\"dateModified\":\"2016-01-22T17:48:24+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#listItem\",\"name\":\"La Junta aboga por la colaboraci\\u00f3n institucional para la promoci\\u00f3n de C\\u00f3rdoba\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#listItem\",\"position\":3,\"name\":\"La Junta aboga por la colaboraci\\u00f3n institucional para la promoci\\u00f3n de C\\u00f3rdoba\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/\",\"name\":\"La Junta aboga por la colaboraci\\u00f3n institucional para la promoci\\u00f3n de C\\u00f3rdoba | El Digital de Asturias\",\"description\":\"La delegada del Gobierno andaluz en C\\u00f3rdoba, Rafi Cresp\\u00edn, ha defendido este mi\\u00e9rcoles en Fitur 2016 \\\"la colaboraci\\u00f3n entre las administraciones, los agentes sociales y econ\\u00f3micos y las empresas para la promoci\\u00f3n del sector tur\\u00edstico en C\\u00f3rdoba\\\", y para que \\\"el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo\\\". Cresp\\u00edn,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/fotonoticia_20160120155733_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\\\/#mainImage\"},\"datePublished\":\"2016-01-22T17:48:24+01:00\",\"dateModified\":\"2016-01-22T17:48:24+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias","description":"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 \"la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba\", y para que \"el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo\". Cresp\u00edn,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#article","name":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias","headline":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg","width":800,"height":600},"datePublished":"2016-01-22T17:48:24+01:00","dateModified":"2016-01-22T17:48:24+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#listItem","name":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#listItem","position":3,"name":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/","name":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias","description":"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 \"la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba\", y para que \"el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo\". Cresp\u00edn,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/#mainImage"},"datePublished":"2016-01-22T17:48:24+01:00","dateModified":"2016-01-22T17:48:24+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias","og:description":"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 &quot;la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba&quot;, y para que &quot;el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo&quot;. Cresp\u00edn,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg","og:image:width":800,"og:image:height":600,"article:published_time":"2016-01-22T16:48:24+00:00","article:modified_time":"2016-01-22T16:48:24+00:00","twitter:card":"summary_large_image","twitter:title":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba | El Digital de Asturias","twitter:description":"La delegada del Gobierno andaluz en C\u00f3rdoba, Rafi Cresp\u00edn, ha defendido este mi\u00e9rcoles en Fitur 2016 &quot;la colaboraci\u00f3n entre las administraciones, los agentes sociales y econ\u00f3micos y las empresas para la promoci\u00f3n del sector tur\u00edstico en C\u00f3rdoba&quot;, y para que &quot;el incremento de la actividad repercuta positivamente en el aumento de puestos de trabajo&quot;. Cresp\u00edn,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2016\/01\/fotonoticia_20160120155733_800.jpg"},"aioseo_meta_data":{"post_id":"61398","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 20:54:46","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-08 21:50:00","updated":"2026-05-22 20:54:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/\" title=\"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba\">La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"La Junta aboga por la colaboraci\u00f3n institucional para la promoci\u00f3n de C\u00f3rdoba","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-junta-aboga-por-la-colaboracion-institucional-para-la-promocion-de-cordoba\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=61398"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/61398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/61399"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=61398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=61398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=61398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}