{"id":4894,"date":"2014-02-22T15:53:10","date_gmt":"2014-02-22T16:53:10","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=4894"},"modified":"2014-02-22T15:53:10","modified_gmt":"2014-02-22T16:53:10","slug":"estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/","title":{"rendered":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4895\" alt=\"5971354w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-253x300.jpg\" width=\"253\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-253x300.jpg 253w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-540x640.jpg 540w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-150x178.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-450x534.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-696x825.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w-354x420.jpg 354w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg 700w\" sizes=\"(max-width: 253px) 100vw, 253px\" \/>Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA).<\/p>\n<p>El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and Environment y en Journal of Plant Physiology, abre una v\u00eda para mejorar el rendimiento comercial del cultivo del pimiento.<\/p>\n<p>En las pruebas llevadas a cabo hasta el momento por los investigadores, las plantas obtenidas con los patrones seleccionados permitieron un ahorro de hasta el 25 por ciento de agua, manteniendo los rendimientos.<\/p>\n<p>La clave reside en injertar las variedades deseadas sobre genotipos resistentes a estas situaciones de estr\u00e9s, seg\u00fan ha asegurado a EFE Salvador L\u00f3pez Galarza, investigador del Centro Valenciano de Estudios sobre el Riego de la UPV.<\/p>\n<p>Seg\u00fan L\u00f3pez, la salinidad y la escasez de agua son algunos de los mayores problemas a los que se enfrentan los cultivos, situaciones de estr\u00e9s que inciden \u00abdirectamente en la calidad del producto final, as\u00ed como en el rendimiento comercial de las explotaciones\u00bb.<\/p>\n<p>En el estudio se han identificado los patrones de pimiento que, en un futuro, podr\u00edan ayudar a obtener plantas que sobrevivan en estas situaciones de estr\u00e9s con un rendimiento y calidad aceptable, ha apuntado el investigador.<\/p>\n<p>Los investigadores de la UPV y el IVIA evaluaron 40 genotipos de pimiento (Capsicum spp) tanto comerciales como silvestres, seleccionados del Banco de Germoplasma del COMAV de la Universidad Polit\u00e9cnica de Val\u00e8ncia.<\/p>\n<p>El estudio de selecci\u00f3n se realiz\u00f3 durante las fases vegetativa y reproductiva bajo condiciones, por un lado, de d\u00e9ficit h\u00eddrico y, por otro, de alta salinidad.<\/p>\n<p>De los 40 genotipos, se seleccionaron los m\u00e1s aptos por su tasa fotosint\u00e9tica, evaluando posteriormente, en condiciones de campo, el rendimiento de las plantas injertadas sobre estos patrones en estas situaciones de estr\u00e9s.<\/p>\n<p>\u00abLa fotos\u00edntesis es uno de los primeros procesos que se ve afectado tanto por la escasez de agua como por la salinidad, de ah\u00ed que lo utiliz\u00e1ramos como par\u00e1metro de referencia para el cribado de los genotipos\u00bb, ha apuntado \u00c1ngeles Calatayud, investigadora del Centro de Citricultura y Producci\u00f3n Vegetal del IVIA.<\/p>\n<p>Los genotipos seleccionados y utilizados como patrones por los investigadores mejoraron la tolerancia a la salinidad de las variedades comerciales, tanto en rendimiento comercial como en la calidad de fruto.<\/p>\n<p>Las pruebas las llevaron a cabo en unos invernaderos de la cooperativa de El Perell\u00f3, zona que se caracteriza por un elevado contenido salino tanto en el suelo como en el agua de riego.<\/p>\n<p>Los ensayos con plantas sometidas a estr\u00e9s h\u00eddrico se realizaron en la cooperativa de Surinver de Pilar de la Horadada y en una finca de Anecoop en Museros.<\/p>\n<p>Los investigadores de la UPV y el IVIA est\u00e1n trabajando tambi\u00e9n en el desarrollo de nuevos h\u00edbridos a partir de los genotipos tolerantes que permitan obtener patrones que conjuguen las propiedades beneficiosas de cada uno de ellos y presenten mejor afinidad con las variedades comerciales.<\/p>\n<p>En estos momentos se ha testado en condiciones de campo la primera generaci\u00f3n de h\u00edbridos y algunos de ellos han mostrado un comportamiento excelente.<\/p>\n<p>Asimismo, tambi\u00e9n se eval\u00faa su resistencia a las enfermedades m\u00e1s comunes para poder cultivar pimientos en suelos afectados por las patolog\u00edas m\u00e1s frecuentes sin necesidad de realizar desinfecci\u00f3n del suelo, por lo que esta t\u00e9cnica puede resultar tambi\u00e9n interesante para un manejo m\u00e1s sostenible del cultivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and<\/p>\n","protected":false},"author":1,"featured_media":4895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-4894","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-22T16:53:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-22T16:53:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#article\",\"name\":\"Estudian c\\u00f3mo obtener plantas de pimientos resistentes a sequ\\u00eda y salinidad | El Digital de Asturias\",\"headline\":\"Estudian c\\u00f3mo obtener plantas de pimientos resistentes a sequ\\u00eda y salinidad\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5971354w.jpg\",\"width\":700,\"height\":830},\"datePublished\":\"2014-02-22T15:53:10+01:00\",\"dateModified\":\"2014-02-22T15:53:10+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#listItem\",\"name\":\"Estudian c\\u00f3mo obtener plantas de pimientos resistentes a sequ\\u00eda y salinidad\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#listItem\",\"position\":3,\"name\":\"Estudian c\\u00f3mo obtener plantas de pimientos resistentes a sequ\\u00eda y salinidad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/\",\"name\":\"Estudian c\\u00f3mo obtener plantas de pimientos resistentes a sequ\\u00eda y salinidad | El Digital de Asturias\",\"description\":\"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\\u00e1s resistentes a la sequ\\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\\u00e9cnica de Val\\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5971354w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#mainImage\",\"width\":700,\"height\":830},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\\\/#mainImage\"},\"datePublished\":\"2014-02-22T15:53:10+01:00\",\"dateModified\":\"2014-02-22T15:53:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias","description":"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#article","name":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias","headline":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg","width":700,"height":830},"datePublished":"2014-02-22T15:53:10+01:00","dateModified":"2014-02-22T15:53:10+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#listItem","name":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#listItem","position":3,"name":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/","name":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias","description":"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#mainImage","width":700,"height":830},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/#mainImage"},"datePublished":"2014-02-22T15:53:10+01:00","dateModified":"2014-02-22T15:53:10+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias","og:description":"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg","og:image:width":700,"og:image:height":830,"article:published_time":"2014-02-22T16:53:10+00:00","article:modified_time":"2014-02-22T16:53:10+00:00","twitter:card":"summary_large_image","twitter:title":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad | El Digital de Asturias","twitter:description":"Valencia, 22 feb (EFE).- Obtener plantas de pimiento m\u00e1s resistentes a la sequ\u00eda y la salinidad es el objetivo de un estudio desarrollado por investigadores de la Universidad Polit\u00e9cnica de Val\u00e8ncia (UPV) y el Instituto Valenciano de Investigaciones Agrarias (IVIA). El estudio, cuyos resultados han sido publicados recientemente en el Journal of Food, Agriculture and","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5971354w.jpg"},"aioseo_meta_data":{"post_id":"4894","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-16 15:51:56","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:58:57","updated":"2025-09-16 15:51:56"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/\" title=\"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad\">Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Estudian c\u00f3mo obtener plantas de pimientos resistentes a sequ\u00eda y salinidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/estudian-como-obtener-plantas-de-pimientos-resistentes-a-sequia-y-salinidad\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=4894"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/4895"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=4894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=4894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=4894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}