{"id":48564,"date":"2015-09-11T17:07:24","date_gmt":"2015-09-11T15:07:24","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=48564"},"modified":"2015-09-11T17:07:24","modified_gmt":"2015-09-11T15:07:24","slug":"vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/","title":{"rendered":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-48565\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-360x251.jpg\" alt=\"fotonoticia_20150910115244_800\" width=\"360\" height=\"251\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-360x251.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-650x453.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-768x535.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-150x104.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-450x313.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-100x70.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-696x485.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800-603x420.jpg 603w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado.<\/p>\n<p>Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de ingl\u00e9s; un test psicot\u00e9cnico; entrevista personal, y prueba en simulador, m\u00e1s un curso posterior para los elegidos.<\/p>\n<p>Vueling opera actualmente 366 rutas en m\u00e1s de 160 destinos de Europa, Oriente Pr\u00f3ximo y \u00c1frica con una flota de m\u00e1s de 100 aviones basados en 22 aeropuertos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de<\/p>\n","protected":false},"author":1,"featured_media":48565,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":{"0":"post-48564","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad-turismo"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-11T15:07:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-09-11T15:07:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#article\",\"name\":\"Vueling contratar\\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias\",\"headline\":\"Vueling contratar\\u00e1 hasta 200 copilotos para su crecimiento en 2016\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/fotonoticia_20150910115244_800.jpg\",\"width\":800,\"height\":557},\"datePublished\":\"2015-09-11T17:07:24+02:00\",\"dateModified\":\"2015-09-11T17:07:24+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#listItem\",\"name\":\"Vueling contratar\\u00e1 hasta 200 copilotos para su crecimiento en 2016\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#listItem\",\"position\":3,\"name\":\"Vueling contratar\\u00e1 hasta 200 copilotos para su crecimiento en 2016\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/\",\"name\":\"Vueling contratar\\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias\",\"description\":\"Vueling contratar\\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\\u00e1n a integrarse en la plantilla a partir de la pr\\u00f3xima temporada de verano 2016, ha informado este jueves la compa\\u00f1\\u00eda en un comunicado. Las pruebas de selecci\\u00f3n consistir\\u00e1n en una evaluaci\\u00f3n de los conocimientos generales operacionales y del avi\\u00f3n; una prueba de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/fotonoticia_20150910115244_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#mainImage\",\"width\":800,\"height\":557},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\\\/#mainImage\"},\"datePublished\":\"2015-09-11T17:07:24+02:00\",\"dateModified\":\"2015-09-11T17:07:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias","description":"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#article","name":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias","headline":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg","width":800,"height":557},"datePublished":"2015-09-11T17:07:24+02:00","dateModified":"2015-09-11T17:07:24+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#listItem","name":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#listItem","position":3,"name":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/","name":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias","description":"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#mainImage","width":800,"height":557},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/#mainImage"},"datePublished":"2015-09-11T17:07:24+02:00","dateModified":"2015-09-11T17:07:24+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias","og:description":"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg","og:image:width":800,"og:image:height":557,"article:published_time":"2015-09-11T15:07:24+00:00","article:modified_time":"2015-09-11T15:07:24+00:00","twitter:card":"summary_large_image","twitter:title":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016 | El Digital de Asturias","twitter:description":"Vueling contratar\u00e1 hasta 200 nuevos copilotos de perfil medio y alto que pasar\u00e1n a integrarse en la plantilla a partir de la pr\u00f3xima temporada de verano 2016, ha informado este jueves la compa\u00f1\u00eda en un comunicado. Las pruebas de selecci\u00f3n consistir\u00e1n en una evaluaci\u00f3n de los conocimientos generales operacionales y del avi\u00f3n; una prueba de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910115244_800.jpg"},"aioseo_meta_data":{"post_id":"48564","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-20 06:33:44","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 00:38:47","updated":"2025-09-20 06:33:44"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/\" title=\"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016\">Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Vueling contratar\u00e1 hasta 200 copilotos para su crecimiento en 2016","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/vueling-contratara-hasta-200-copilotos-para-su-crecimiento-en-2016\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/48564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=48564"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/48564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/48565"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=48564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=48564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=48564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}