{"id":48539,"date":"2015-09-11T16:48:36","date_gmt":"2015-09-11T14:48:36","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=48539"},"modified":"2015-09-11T16:48:36","modified_gmt":"2015-09-11T14:48:36","slug":"thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/","title":{"rendered":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-48540\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-360x240.jpg\" alt=\"fotonoticia_20150910094950_800\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-650x433.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-768x512.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-696x464.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-630x420.jpg 630w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes.<\/p>\n<p>As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los \u00faltimos tres a\u00f1os, Thomas Cook ha apoyado a sus socios hoteleros en Baleares con 28 millones de euros para renovar sus propiedades.<\/p>\n<p>De estos 28 millones, alrededor de 25 millones de euros se destin\u00f3 a hoteles de Mallorca. Adem\u00e1s, este a\u00f1o otros 20 millones de euros se han invertido en hoteles en propiedad, arrendados y gestionados en Espa\u00f1a. La mitad de esta cantidad se utiliz\u00f3 para actualizar, renovar y poner en practica las marcas propias. Estos hoteles arrendados se encuentran en Mallorca y Menorca, y est\u00e1n operando bajo la marca Sentido, SmartLine, Sunprime y SunConnect.<\/p>\n<p>El grupo ha explicado que invierte en nuevas ofertas en Espa\u00f1a, sobre todo en sus propias marcas. As\u00ed, este verano el touroperador ofreci\u00f3 209 hoteles bajo la marca Sentido, smartline, Sunwing, Sunprime y SunConnect Brand en el mundo.<\/p>\n<p>Un 25 por ciento de todas las propias marcas de hoteles est\u00e1n en Espa\u00f1a, en total son 51. De estos, 32 hoteles y resorts est\u00e1n ubicados en Baleares, de los cuales 25 en Mallorca, destino principal de Espa\u00f1a.<\/p>\n<p>El presidente de la junta de Thomas Cook Group, Frank Meysman, ha indicado que para la junta directiva es importante tener una impresi\u00f3n de primera mano de su negocio principal y el producto. Por ello, ha a\u00f1adido que \u00abno hay mejor lugar para experimentar esto que en Mallorca donde comenz\u00f3 el turismo en todo el Mediterr\u00e1neo y donde se puede explorar todo tipo de experiencias de vacaciones\u00bb.<\/p>\n<p>\u00abAqu\u00ed se puede ver c\u00f3mo funciona el negocio de los viajes: Gran oferta de vacaciones y cumplir las expectativas de nuestros clientes, Somos un negocio de consumo y como nos ocupamos de nuestros clientes para determinar nuestro \u00e9xito futuro\u00bb, ha declarado.<\/p>\n<p>BIEN POSICIONADOS.<\/p>\n<p>Por su parte, el consejero delegado de Thomas Cook Group, Peter Fankhauser, ha se\u00f1alado que Espa\u00f1a \u00aby sobre todo Mallorca\u00bb son muy importantes para su negocio porque \u00abel turismo es importante para la econom\u00eda local\u00bb.<\/p>\n<p>Por este motivo, ha explicado que han ampliado su oferta hotelera de forma masiva en los \u00faltimos anos. \u00abAhora nos sentimos muy bien posicionados y nuestro objetivo es mejorar a\u00fan m\u00e1s la calidad de nuestro producto. Todos estamos interesados en la creaci\u00f3n de un entorno favorable para las inversiones y la facilitaci\u00f3n de un turismo de calidad. En este sentido, se han tomado muchas medidas como por ejemplo, normas estrictas sobre la Playa de Palma o dar a conocer el centro de la ciudad de Palma\u00bb, ha concluido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los<\/p>\n","protected":false},"author":1,"featured_media":48540,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":{"0":"post-48539","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad-turismo"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-11T14:48:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-09-11T14:48:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#article\",\"name\":\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\\u00edses europeos en 2014 | El Digital de Asturias\",\"headline\":\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\\u00edses europeos en 2014\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/fotonoticia_20150910094950_800.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2015-09-11T16:48:36+02:00\",\"dateModified\":\"2015-09-11T16:48:36+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#listItem\",\"name\":\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\\u00edses europeos en 2014\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#listItem\",\"position\":3,\"name\":\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\\u00edses europeos en 2014\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/\",\"name\":\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\\u00edses europeos en 2014 | El Digital de Asturias\",\"description\":\"El grupo Thomas Cook llev\\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\\u00e1s importantes. As\\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\\u00e9rcoles, donde tambi\\u00e9n han se\\u00f1alado que, en los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/fotonoticia_20150910094950_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\\\/#mainImage\"},\"datePublished\":\"2015-09-11T16:48:36+02:00\",\"dateModified\":\"2015-09-11T16:48:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias","description":"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#article","name":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias","headline":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg","width":800,"height":533},"datePublished":"2015-09-11T16:48:36+02:00","dateModified":"2015-09-11T16:48:36+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#listItem","name":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#listItem","position":3,"name":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/","name":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias","description":"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/#mainImage"},"datePublished":"2015-09-11T16:48:36+02:00","dateModified":"2015-09-11T16:48:36+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias","og:description":"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2015-09-11T14:48:36+00:00","article:modified_time":"2015-09-11T14:48:36+00:00","twitter:card":"summary_large_image","twitter:title":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014 | El Digital de Asturias","twitter:description":"El grupo Thomas Cook llev\u00f3 a Baleares alrededor de 2,1 millones de turistas de 15 pa\u00edses emisores de Europa ya que para esta empresa Mallorca es uno de los tres destinos vacacionales m\u00e1s importantes. As\u00ed ha informado el grupo durante una rueda de prensa en Palma este mi\u00e9rcoles, donde tambi\u00e9n han se\u00f1alado que, en los","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150910094950_800.jpg"},"aioseo_meta_data":{"post_id":"48539","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-20 06:30:23","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 00:39:56","updated":"2025-09-20 06:30:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/\" title=\"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014\">Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Thomas Cook trajo a Baleares 2,1 millones de turistas de 15 pa\u00edses europeos en 2014","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/thomas-cook-trajo-a-baleares-21-millones-de-turistas-de-15-paises-europeos-en-2014\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/48539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=48539"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/48539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/48540"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=48539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=48539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=48539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}