{"id":48428,"date":"2015-09-10T05:16:27","date_gmt":"2015-09-10T03:16:27","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=48428"},"modified":"2015-09-10T05:16:27","modified_gmt":"2015-09-10T03:16:27","slug":"ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/","title":{"rendered":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-48429\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-300x300.jpg\" alt=\"fotonoticia_20150909100433_800\" width=\"300\" height=\"300\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-300x300.jpg 300w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-640x640.jpg 640w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-768x768.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-150x150.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-450x450.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-696x696.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-420x420.jpg 420w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800-50x50.jpg 50w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles.<\/p>\n<p>La &#8216;low cost&#8217; revisa al alza la previsi\u00f3n de crecimiento de tr\u00e1fico de pasajeros, que se sit\u00faa en un aumento del 13% durante su primer semestre fiscal, frente al 10% inicial.<\/p>\n<p>El incremento del resultado se debe tambi\u00e9n a un aumento de las tasas del 2% en sus seis primeros meses fiscales, frente al crecimiento plano fijado en sus anteriores estimaciones.<\/p>\n<p>Durante su tercer trimestre fiscal, la empresa a\u00e9rea calcula un aumento del 15% frente al 13% previsto, mientras que las tasas se espera que se mantengan frente a las ca\u00eddas del 4% y 8% fijadas en principio.<\/p>\n<p>El ejercicio 2015\/2016 registrar\u00e1 un tr\u00e1fico de 104 millones de pasajeros frente a los 103 millones estimados. Los precios de fuel influyen tambi\u00e9n en esta revisi\u00f3n que aumenta el resultado neto de la compa\u00f1\u00eda, ya que se esperan ca\u00eddas del coste destinado a combustible.<\/p>\n<p>Ryanair ha afirmado haber recuperado todos los fondos, que fueron de menos de cinco millones de d\u00f3lares (4,47 millones de euros) que un &#8216;hackeo&#8217; sustray\u00f3 de su transferencia a un banco chino el pasado mes de abril. \u00abSe han tomado medidas para garantizar que no vuelva a suceder\u00bb, ha asegurado la compa\u00f1\u00eda.<\/p>\n<p>FAVORECIDOS POR LAS CIRCUNSTANCIAS<\/p>\n<p>El presidente y consejero delegado del grupo, Michael O&#8217;Leary, ha mostrado su sorpresa por la fortaleza de las reservas y tasas de la temporada de verano. La empresa registr\u00f3 cifras &#8216;r\u00e9cord&#8217; en ocupaci\u00f3n del 95% en julio y agosto, as\u00ed como un 2% m\u00e1s de precios de billete, cuando en principio cre\u00edan que se mantendr\u00eda.<\/p>\n<p>O&#8217;Leary recalca que esta mejora no se debe s\u00f3lo al modelo o gesti\u00f3n de su empresa, sino tambi\u00e9n por las tendencias en la industria de aviaci\u00f3n en la \u00e9poca estival. Ejemplo de ello es el mal tiempo en el norte de Europa, el incentivo a familias brit\u00e1nicas a viajar, la oferta plana de las empresas europeas y los bajos precios de fuel. Todo ello ha influido en esta previsi\u00f3n alcista.<\/p>\n<p>La aerol\u00ednea de bajo coste asegura que espera menos presiones en las tasas esta temporada de inverno, as\u00ed como fuertes crecimientos en los principales mercados europeos como es el alem\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La &#8216;low cost&#8217; revisa al alza la previsi\u00f3n de crecimiento de<\/p>\n","protected":false},"author":1,"featured_media":48429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":{"0":"post-48428","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad-turismo"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La &#039;low cost&#039; revisa al alza la previsi\u00f3n de crecimiento de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La &#039;low cost&#039; revisa al alza la previsi\u00f3n de crecimiento de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-10T03:16:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-09-10T03:16:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La &#039;low cost&#039; revisa al alza la previsi\u00f3n de crecimiento de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#article\",\"name\":\"Ryanair prev\\u00e9 un 25% m\\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias\",\"headline\":\"Ryanair prev\\u00e9 un 25% m\\u00e1s de ganancias en su ejercicio fiscal\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/fotonoticia_20150909100433_800.jpg\",\"width\":800,\"height\":800},\"datePublished\":\"2015-09-10T05:16:27+02:00\",\"dateModified\":\"2015-09-10T05:16:27+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#listItem\",\"name\":\"Ryanair prev\\u00e9 un 25% m\\u00e1s de ganancias en su ejercicio fiscal\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#listItem\",\"position\":3,\"name\":\"Ryanair prev\\u00e9 un 25% m\\u00e1s de ganancias en su ejercicio fiscal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/\",\"name\":\"Ryanair prev\\u00e9 un 25% m\\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias\",\"description\":\"Ryanair sit\\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\\\/2016, un 25% m\\u00e1s respecto al a\\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\\u00fan ha informado la aerol\\u00ednea irlandesa este mi\\u00e9rcoles. La 'low cost' revisa al alza la previsi\\u00f3n de crecimiento de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/fotonoticia_20150909100433_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#mainImage\",\"width\":800,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\\\/#mainImage\"},\"datePublished\":\"2015-09-10T05:16:27+02:00\",\"dateModified\":\"2015-09-10T05:16:27+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias","description":"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La 'low cost' revisa al alza la previsi\u00f3n de crecimiento de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#article","name":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias","headline":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg","width":800,"height":800},"datePublished":"2015-09-10T05:16:27+02:00","dateModified":"2015-09-10T05:16:27+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#listItem","name":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#listItem","position":3,"name":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/","name":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias","description":"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La 'low cost' revisa al alza la previsi\u00f3n de crecimiento de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#mainImage","width":800,"height":800},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/#mainImage"},"datePublished":"2015-09-10T05:16:27+02:00","dateModified":"2015-09-10T05:16:27+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias","og:description":"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La 'low cost' revisa al alza la previsi\u00f3n de crecimiento de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg","og:image:width":800,"og:image:height":800,"article:published_time":"2015-09-10T03:16:27+00:00","article:modified_time":"2015-09-10T03:16:27+00:00","twitter:card":"summary_large_image","twitter:title":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal | El Digital de Asturias","twitter:description":"Ryanair sit\u00faa sus ganancias entre 1.175 y 1.225 millones de euros a cierre del ejercicio fiscal 2015\/2016, un 25% m\u00e1s respecto al a\u00f1o fiscal precedente y por encima de los 970 millones de euros previstos antes, seg\u00fan ha informado la aerol\u00ednea irlandesa este mi\u00e9rcoles. La 'low cost' revisa al alza la previsi\u00f3n de crecimiento de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/09\/fotonoticia_20150909100433_800.jpg"},"aioseo_meta_data":{"post_id":"48428","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-20 06:18:28","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 00:40:41","updated":"2025-09-20 06:18:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/\" title=\"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal\">Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Ryanair prev\u00e9 un 25% m\u00e1s de ganancias en su ejercicio fiscal","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ryanair-preve-un-25-mas-de-ganancias-en-su-ejercicio-fiscal\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/48428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=48428"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/48428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/48429"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=48428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=48428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=48428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}