{"id":4741,"date":"2014-02-21T09:18:43","date_gmt":"2014-02-21T10:18:43","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=4741"},"modified":"2014-02-21T09:18:43","modified_gmt":"2014-02-21T10:18:43","slug":"las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/","title":{"rendered":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4742\" alt=\"Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380-360x263.jpg\" width=\"360\" height=\"263\" \/>SINC &#8211; Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas.<\/p>\n<p>Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo de la migra\u00f1a y otras cefaleas es muy elevado, igual o superior al 30% durante un m\u00ednimo de tres meses, seg\u00fan muestran los ensayos cl\u00ednicos\u201d.<\/p>\n<p>\u201cEs decir, a corto plazo, muchas terapias puedan ser entendidas por los pacientes como eficaces cuando intr\u00ednsecamente no lo son\u201d, explica David Ezpeleta, coordinador del grupo de estudio de cefaleas de la SEN.<\/p>\n<p>Por ello, los expertos han analizado los estudios sobre la eficacia de diversos tratamientos no farmacol\u00f3gicos para determinar qu\u00e9 terapias han demostrado ser superiores al placebo y suponen un beneficio real para los pacientes.<\/p>\n<p>La bibliograf\u00eda sobre homeopat\u00eda es muy amplia y de momento no se ha demostrado de forma consistente que su eficacia sea superior a la del placebo<\/p>\n<p>\u201cLos pretendidos efectos beneficiosos en algunos pacientes y los resultados positivos obtenidos en algunos ensayos se pueden explican por varias razones: metodolog\u00eda empleada, efecto placebo, efecto terap\u00e9utico de las propias consultas, otras medidas asociadas como la dieta, el ejercicio o las t\u00e9cnicas de relajaci\u00f3n, tratamientos convencionales simult\u00e1neos y la capacidad de recuperaci\u00f3n del organismo\u201d, detalla Francisco Jos\u00e9 Molina, vocal del mismo grupo de la SEN.<\/p>\n<p>\u201cTambi\u00e9n nos preocupa el proceso de evaluaci\u00f3n y regulaci\u00f3n de los productos homeop\u00e1ticos recientemente abierto por la Administraci\u00f3n y su equiparaci\u00f3n conceptual con los medicamentos al uso\u201d, afirma el experto.<\/p>\n<p>En este sentido, \u201cel grupo de estudio de cefaleas de la SEN apoya a plataformas como #NoSinEvidencia, que solicita que no se apruebe ning\u00fan tratamiento que no hayan demostrado \u2013mediante ensayos cl\u00ednicos reproducibles\u2013 unas condiciones de eficacia y seguridad superiores al placebo\u201d, sostiene Ezpeleta.<\/p>\n<p>Los datos epidemiol\u00f3gicos indican que el 85-90% de la poblaci\u00f3n ha tenido alg\u00fan episodio de cefalea en el \u00faltimo a\u00f1o. En el caso de la migra\u00f1a, su prevalencia en Espa\u00f1a alcanza el 12-13% de la poblaci\u00f3n general y el 17-18% de las mujeres.<\/p>\n<p>Terapia a terapia<\/p>\n<p>Respecto a las terapias herbales, solo se dispone de estudios controlados con dos principios activos de posible efecto preventivo en la migra\u00f1a epis\u00f3dica: la petasina (de la planta Petasites hybridus) y el parten\u00f3lido (de la planta Tanacetum parthenium). \u201cEn Espa\u00f1a, no se dispone de preparados herbales fiables para el tratamiento de la migra\u00f1a\u201d, apunta Molina.<\/p>\n<p>En relaci\u00f3n con las terapias diet\u00e9ticas, \u201ces un hecho sobradamente conocido que, en algunos pacientes, determinados alimentos y condimentos pueden desencadenar sus crisis de migra\u00f1a; sin embargo, pensamos que la relaci\u00f3n entre migra\u00f1a y alimentaci\u00f3n est\u00e1 sobreestimada, pues los estudios epidemiol\u00f3gicos nos hablan de que esto sucede de forma habitual y consistente en torno al 10% de los pacientes\u201d, comenta Ezpeleta.<\/p>\n<p>\u201cLos neur\u00f3logos no aconsejamos dietas especiales ni restrictivas a los pacientes con migra\u00f1a ya que, a fecha de hoy, ninguna intolerancia alimentaria ni su correlato diet\u00e9tico han demostrado con rigor su eficacia ni en la migra\u00f1a epis\u00f3dica ni en la migra\u00f1a cr\u00f3nica\u201d, se\u00f1ala Molina.<\/p>\n<p>\u201cEs m\u00e1s, la supresi\u00f3n de ciertos alimentos puede ser peligrosa por producir d\u00e9ficits de vitaminas y oligoelementos, siendo una pr\u00e1ctica altamente desaconsejable durante el embarazo\u201d, matiza Jes\u00fas Porta-Etessam, miembro del grupo de la SEN. \u201cM\u00e1s que de alimentos concretos \u2013determinadas bebidas alcoh\u00f3licas aparte\u2013, los pacientes hablan de retraso u omisi\u00f3n de comidas principales y otros tipos de ayuno, falta de hidrataci\u00f3n y comidas copiosas como posibles factores desencadenantes de sus crisis\u201d, apostilla.<\/p>\n<p>Acerca de los suplementos alimenticios eficaces en la prevenci\u00f3n de la migra\u00f1a, se dispone de evidencias cient\u00edficas para la vitamina B2 (riboflavina) y el magnesio.<\/p>\n<p>\u201cLa vitamina B2 a dosis altas (400 mg\/d\u00eda) y el magnesio a dosis medias (300 mg\/d\u00eda) pueden ser eficaces, pero al igual que en las terapias herbales, solo hay datos favorables en la migra\u00f1a epis\u00f3dica. Sin embargo, la eficacia de estos tratamientos es limitada y menor que la de los f\u00e1rmacos antimigra\u00f1osos habituales\u201d, a\u00f1ade Molina. \u201cEn cuanto al suplemento oral de la enzima DAO, a fecha de hoy no existen publicaciones que sustenten su eficacia\u201d, declara.<\/p>\n<p>La revisi\u00f3n realizada por la SEN tambi\u00e9n incluye terapias relacionadas con el trabajo del cuerpo, la medicina oriental y las terapias mentales en pacientes con cefaleas. \u201cEn relaci\u00f3n con la acupuntura, hemos comprobado que existen evidencias a favor de su uso y estudios en contra. Es un tratamiento que podr\u00eda valorarse en algunos pacientes con migra\u00f1a\u201d, se\u00f1ala Porta-Etessam.<\/p>\n<p>\u201cLa medicina conductual, las terapias de relajaci\u00f3n, el biofeedback y la terapia cognitivo-conductual para el estr\u00e9s son recursos que se han mostrado \u00fatiles tanto en la migra\u00f1a como en la cefalea de tipo tensi\u00f3n; en consecuencia, deber\u00edamos considerarlos en nuestros pacientes, especialmente si el estr\u00e9s es un desencadenante o agravante de sus crisis\u201d, contin\u00faa.<\/p>\n<p>Finalmente, el tratamiento del dolor perif\u00e9rico regional con bloqueos de nervios craneales, los diferentes abordajes terap\u00e9uticos de los puntos miofasciales y las diferentes t\u00e9cnicas de fisioterapia, quiropr\u00e1ctica y otras disciplinas \u201cpueden ser \u00fatiles en muchos casos, pero se necesitan ensayos cl\u00ednicos que confirmen su eficacia y permitan ampliar el abanico de pacientes que puedan beneficiarse de estas terapias\u201d, concluye Porta-Etessam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SINC &#8211; Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo<\/p>\n","protected":false},"author":1,"featured_media":4742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-4741","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"519\" \/>\n\t\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-21T10:18:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-21T10:18:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#article\",\"name\":\"Las terapias homeop\\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias\",\"headline\":\"Las terapias homeop\\u00e1ticas para el dolor de cabeza no son superiores al placebo\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg\",\"width\":519,\"height\":380},\"datePublished\":\"2014-02-21T09:18:43+01:00\",\"dateModified\":\"2014-02-21T09:18:43+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#listItem\",\"name\":\"Las terapias homeop\\u00e1ticas para el dolor de cabeza no son superiores al placebo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#listItem\",\"position\":3,\"name\":\"Las terapias homeop\\u00e1ticas para el dolor de cabeza no son superiores al placebo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/\",\"name\":\"Las terapias homeop\\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias\",\"description\":\"SINC - Herbolog\\u00eda, homeopat\\u00eda, terapias diet\\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\\u00f3n\\u2026 Con mucha frecuencia, los pacientes que padecen migra\\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\\u00f3gicas. Seg\\u00fan un comunicado emitido hoy por la Sociedad Espa\\u00f1ola de Neurolog\\u00eda (SEN) tras una revisi\\u00f3n de la evidencia cient\\u00edfica existente, \\u201cel efecto placebo del tratamiento preventivo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#mainImage\",\"width\":519,\"height\":380},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\\\/#mainImage\"},\"datePublished\":\"2014-02-21T09:18:43+01:00\",\"dateModified\":\"2014-02-21T09:18:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias","description":"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#article","name":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias","headline":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg","width":519,"height":380},"datePublished":"2014-02-21T09:18:43+01:00","dateModified":"2014-02-21T09:18:43+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#listItem","name":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#listItem","position":3,"name":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/","name":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias","description":"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#mainImage","width":519,"height":380},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/#mainImage"},"datePublished":"2014-02-21T09:18:43+01:00","dateModified":"2014-02-21T09:18:43+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias","og:description":"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg","og:image:width":519,"og:image:height":380,"article:published_time":"2014-02-21T10:18:43+00:00","article:modified_time":"2014-02-21T10:18:43+00:00","twitter:card":"summary_large_image","twitter:title":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo | El Digital de Asturias","twitter:description":"SINC - Herbolog\u00eda, homeopat\u00eda, terapias diet\u00e9ticas, acupuntura, medicina conductual, terapias de relajaci\u00f3n\u2026 Con mucha frecuencia, los pacientes que padecen migra\u00f1a y otras cefaleas recurren a diversas terapias no farmacol\u00f3gicas. Seg\u00fan un comunicado emitido hoy por la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN) tras una revisi\u00f3n de la evidencia cient\u00edfica existente, \u201cel efecto placebo del tratamiento preventivo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/Las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo_image_380.jpg"},"aioseo_meta_data":{"post_id":"4741","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-16 15:32:00","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:57:34","updated":"2025-09-16 15:32:00"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/\" title=\"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo\">Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Las terapias homeop\u00e1ticas para el dolor de cabeza no son superiores al placebo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-terapias-homeopaticas-para-el-dolor-de-cabeza-no-son-superiores-al-placebo\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=4741"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/4742"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=4741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=4741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=4741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}