{"id":4679,"date":"2014-02-21T06:06:29","date_gmt":"2014-02-21T07:06:29","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=4679"},"modified":"2014-02-21T06:06:29","modified_gmt":"2014-02-21T07:06:29","slug":"air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/","title":{"rendered":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4680\" alt=\"5964762w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w-360x147.jpg\" width=\"360\" height=\"147\" \/>Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo.<\/p>\n<p>As\u00ed lo ha manifestado hoy en Madrid el director general de la compa\u00f1\u00eda para Espa\u00f1a, Paul Verhagen, tras resaltar que Air Berl\u00edn conecta m\u00e1s de 25 aeropuertos de Espa\u00f1a y Portugal con instalaciones de Alemania, Austria y Suiza, por lo que es \u00abl\u00edder en estas rutas\u00bb en las que transporta 10 de los 31 millones de viajeros que contabiliza anualmente.<\/p>\n<p>Air Berl\u00edn, tambi\u00e9n l\u00edder en Palma de Mallorca y en las rutas entre Alemania, Austria y Suiza y las Islas Canarias tiene previsto operar en la temporada de verano unos 800 vuelos a la semana con Espa\u00f1a de los que 511 tendr\u00e1n origen o destino en Baleares y 81 en Canarias.<\/p>\n<p>Respecto a la programaci\u00f3n en Madrid, desde el 10 de marzo unir\u00e1 la capital con Viena cuatro veces a la semana y se prev\u00e9 que esta conexi\u00f3n aumente a cinco frecuencias semanales a partir de abril.<\/p>\n<p>La conexi\u00f3n con D\u00fcsseldorf se abrir\u00e1 el 31 de marzo con una ruta diaria (excepto los s\u00e1bados) y a partir de mayo operar\u00e1 14 conexiones semanales con Berl\u00edn, en lugar de las 12 actuales.<\/p>\n<p>La compa\u00f1\u00eda ha explicado que la apertura de estas rutas con los \u00abhubs\u00bb de Viena y D\u00fcsseldorf abrir\u00e1 a los pasajeros en Espa\u00f1a la posibilidad de conectar con otras rutas de Air Berl\u00edn al norte y este de Europa o al resto del mundo gracias al acuerdo de colaboraci\u00f3n estrat\u00e9gica con Etihad Airways y por su participaci\u00f3n en la alianza Oneworld.<\/p>\n<p>Verhagen ha explicado que la compa\u00f1\u00eda ha decidido potenciar para la temporada de verano en Espa\u00f1a las rutas claves con la incorporaci\u00f3n de m\u00e1s frecuencias y por ello conectar\u00e1 Palma de Mallorca con Berl\u00edn siete veces al d\u00eda y 8 con D\u00fcsseldorf.<\/p>\n<p>Seg\u00fan las previsiones, Air Berl\u00edn volar\u00e1 desde 25 aeropuertos de Alemania, Austria y Suiza a Palma hasta 442 veces a la semana.<\/p>\n<p>Las frecuencias con las Islas Canarias aumentan un 12% y habr\u00e1 13 vuelos semanales a Lanzarote, 16 a Gran Canaria, 25 a tenerife Sur y 18 a Fuerteventura.<\/p>\n<p>El responsable de la compa\u00f1\u00eda alemana para Espa\u00f1a ha dado la bienvenida a la pol\u00edtica de bonificaci\u00f3n dise\u00f1ada por Aena, aunque ha manifestado que sus beneficios se ver\u00e1n a \u00abmedio y largo plazo y no tendr\u00e1n repercusi\u00f3n en la temporada de verano porque su anuncio lleg\u00f3 demasiado tarde\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la<\/p>\n","protected":false},"author":1,"featured_media":4680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-4679","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"328\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-21T07:06:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-21T07:06:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#article\",\"name\":\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias\",\"headline\":\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5964762w.jpg\",\"width\":800,\"height\":328},\"datePublished\":\"2014-02-21T06:06:29+01:00\",\"dateModified\":\"2014-02-21T06:06:29+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#listItem\",\"name\":\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#listItem\",\"position\":3,\"name\":\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/\",\"name\":\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias\",\"description\":\"Madrid, 20 feb (EFE).- La compa\\u00f1\\u00eda Air Berl\\u00edn abrir\\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\\u00fcsseldorf el pr\\u00f3ximo mes de marzo y ampliar\\u00e1 el n\\u00famero de frecuencias semanales que opera entre Madrid y Berl\\u00edn a partir de mayo. As\\u00ed lo ha manifestado hoy en Madrid el director general de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5964762w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#mainImage\",\"width\":800,\"height\":328},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\\\/#mainImage\"},\"datePublished\":\"2014-02-21T06:06:29+01:00\",\"dateModified\":\"2014-02-21T06:06:29+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias","description":"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#article","name":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias","headline":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg","width":800,"height":328},"datePublished":"2014-02-21T06:06:29+01:00","dateModified":"2014-02-21T06:06:29+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#listItem","name":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#listItem","position":3,"name":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/","name":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias","description":"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#mainImage","width":800,"height":328},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/#mainImage"},"datePublished":"2014-02-21T06:06:29+01:00","dateModified":"2014-02-21T06:06:29+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias","og:description":"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg","og:image:width":800,"og:image:height":328,"article:published_time":"2014-02-21T07:06:29+00:00","article:modified_time":"2014-02-21T07:06:29+00:00","twitter:card":"summary_large_image","twitter:title":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf | El Digital de Asturias","twitter:description":"Madrid, 20 feb (EFE).- La compa\u00f1\u00eda Air Berl\u00edn abrir\u00e1 dos nuevas rutas desde Barajas a los aeropuertos de Viena y D\u00fcsseldorf el pr\u00f3ximo mes de marzo y ampliar\u00e1 el n\u00famero de frecuencias semanales que opera entre Madrid y Berl\u00edn a partir de mayo. As\u00ed lo ha manifestado hoy en Madrid el director general de la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964762w.jpg"},"aioseo_meta_data":{"post_id":"4679","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-16 15:25:14","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:57:31","updated":"2025-09-16 15:25:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/\" title=\"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf\">Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Air Berlin abre dos nuevas rutas desde Madrid a Viena y Dusseldorf","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/air-berlin-abre-dos-nuevas-rutas-desde-madrid-a-viena-y-dusseldorf\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=4679"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/4680"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=4679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=4679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=4679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}