{"id":4664,"date":"2014-02-21T06:01:07","date_gmt":"2014-02-21T07:01:07","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=4664"},"modified":"2014-02-21T06:01:07","modified_gmt":"2014-02-21T07:01:07","slug":"la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/","title":{"rendered":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4665\" alt=\"5964399w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w-360x218.jpg\" width=\"360\" height=\"218\" \/>Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior afeada.<\/p>\n<p>El edificio de 40.000 metros cuadrados dise\u00f1ado por Santiago Calatrava como una de las estrellas de su blanca Ciudad de las Artes y las Ciencias ofrece desde el mes pasado una ins\u00f3lita cara, dominada por el acero gris, las gr\u00faas y las vallas del per\u00edmetro de seguridad ante posibles desprendimientos.<\/p>\n<p>El vistoso recubrimiento de blanco \u00abtrencad\u00eds\u00bb de su inmensa cubierta ha ido siendo retirado -sobre todo a mano por parte de escaladores- hasta dejarlo en una suerte de casco semidesnudo, provisional y en obras.<\/p>\n<p>El fuerte viento navide\u00f1o termin\u00f3 por descubrir las deficiencias t\u00e9cnicas de estos 8.000 metros cuadrados de revestimiento cer\u00e1mico brillante, ante las cuales el despacho de Calatrava y las empresas que se hab\u00edan encargado de su montaje (Acciona y Dragados) tuvieron que asumir el coste de una soluci\u00f3n de emergencia encargada por la Generalitat.<\/p>\n<p>Esta intervenci\u00f3n, valorada en tres millones de euros, no evit\u00f3 suspender, el 1 de febrero, el estreno de \u00abManon Lescaut\u00bb, de Puccini -que ha logrado ser reprogramada para el pr\u00f3ximo oto\u00f1o bajo la direcci\u00f3n de Pl\u00e1cido Domingo-, ni ofrecer a diario una imagen casi apocal\u00edptica (y dolorosa para muchos) del inmenso edificio de Calatrava.<\/p>\n<p>La casualidad quiso tambi\u00e9n que esos trabajos compartieran protagonismo con el mism\u00edsimo George Clooney durante los d\u00edas de rodaje de \u00abTomorrowland\u00bb, la pel\u00edcula futurista de Disney que alter\u00f3, tambi\u00e9n, la vida normal de la Ciudad de las Artes y las Ciencias durante la segunda quincena de enero.<\/p>\n<p>La retirada t\u00e9cnica de ese \u00abtrencad\u00eds\u00bb de la fachada, cuya soluci\u00f3n est\u00e9tica definitiva a\u00fan se desconoce, se ha completado esta semana y as\u00ed, \u00abL&#8217;italiana in Algeri\u00bb, de Gioachino Rossini, podr\u00e1 cumplir los plazos y ser la \u00f3pera con la que el coliseo vuelva a abrir musicalmente sus puertas para la temporada 2013-2014.<\/p>\n<p>El centro de artes valenciano programa por segunda ocasi\u00f3n en su historia este &#8216;dramma giocoso&#8217; en dos actos, con libreto de Angelo Anelli y direcci\u00f3n de Ottavio Dantone, titular de la Accademia Bizantina de R\u00e1vena.<\/p>\n<p>Joan Font, del grupo teatral Comediants, debuta en la \u00f3pera valenciana con este colorido montaje, con escenograf\u00eda y vestuario de Joan Guill\u00e9n, iluminaci\u00f3n de Albert Faura y coreograf\u00eda de Xevi Dorca.<\/p>\n<p>El Palau de les Arts ha reunido un reparto que combina int\u00e9rpretes consolidados del repertorio rossiniano con nuevos valores del panorama l\u00edrico, entre los que figuran tambi\u00e9n artistas del Centre de Perfeccionament Pl\u00e1cido Domingo.<\/p>\n<p>Se han programado seis funciones de esta obra: los d\u00edas 23 y 26 de febrero, as\u00ed como el 1, 11, 13 y 15 de marzo, a la que seguir\u00e1n posteriormente los estrenos de \u00abSimon Boccanegra\u00bb, de Verdi, y \u00abMaror\u00bb, de Manuel Palau.<\/p>\n<p>Por su parte, Zubin Mehta dirigir\u00e1 \u00abLa forza del destino\u00bb, de Verdi, y \u00abTurandot\u00bb, de Puccini, en la s\u00e9ptima edici\u00f3n del Festival del Mediterrani que acoger\u00e1 el Palau de les Arts del 31 de mayo al 15 de junio pr\u00f3ximos.<\/p>\n<p>Precisamente, el Palau est\u00e1 a la espera de que el director de orquesta indio responda a su propuesta de convertirse en el pr\u00f3ximo director musical del teatro oper\u00edstico valenciano, ya que este a\u00f1o finaliza su vinculaci\u00f3n con el actual, Omar Meir Wellber.<\/p>\n<p>Una posibilidad art\u00edstica que, tambi\u00e9n, tiene a Pl\u00e1cido Domingo en sus particulares quinielas, aunque el tenor madrile\u00f1o ha reconocido ya que mientras siga cantando no podr\u00eda aceptar el cargo por requerir una gran dedicaci\u00f3n.<\/p>\n<p>La Orquestra de la Comunitat Valenciana, la formaci\u00f3n titular del Palau de les Arts, ha sufrido tambi\u00e9n los recortes presupuestarios pero sus 54 miembros supervivientes han logrado, en enero y tambi\u00e9n bajo la batuta temporal de Mehta, el reconocimiento del p\u00fablico en una exitosa gira por China.<\/p>\n<p>&nbsp;<\/p>\n<p>Por Carlos Bazarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior<\/p>\n","protected":false},"author":1,"featured_media":4665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-4664","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-21T07:01:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-21T07:01:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#article\",\"name\":\"La \\u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias\",\"headline\":\"La \\u00f3pera regresa a un Palau de les Arts afeado y sin director musical\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5964399w.jpg\",\"width\":800,\"height\":486},\"datePublished\":\"2014-02-21T06:01:07+01:00\",\"dateModified\":\"2014-02-21T06:01:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#listItem\",\"name\":\"La \\u00f3pera regresa a un Palau de les Arts afeado y sin director musical\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#listItem\",\"position\":3,\"name\":\"La \\u00f3pera regresa a un Palau de les Arts afeado y sin director musical\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/\",\"name\":\"La \\u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias\",\"description\":\"Valencia, 20 feb (EFE).- Poco m\\u00e1s de ocho a\\u00f1os despu\\u00e9s de su solemne inauguraci\\u00f3n como una de las \\u00f3peras m\\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\\u00e9n, sin director musical y con una imagen exterior\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5964399w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#mainImage\",\"width\":800,\"height\":486},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\\\/#mainImage\"},\"datePublished\":\"2014-02-21T06:01:07+01:00\",\"dateModified\":\"2014-02-21T06:01:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias","description":"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#article","name":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias","headline":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg","width":800,"height":486},"datePublished":"2014-02-21T06:01:07+01:00","dateModified":"2014-02-21T06:01:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#listItem","name":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#listItem","position":3,"name":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/","name":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias","description":"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#mainImage","width":800,"height":486},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/#mainImage"},"datePublished":"2014-02-21T06:01:07+01:00","dateModified":"2014-02-21T06:01:07+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias","og:description":"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg","og:image:width":800,"og:image:height":486,"article:published_time":"2014-02-21T07:01:07+00:00","article:modified_time":"2014-02-21T07:01:07+00:00","twitter:card":"summary_large_image","twitter:title":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical | El Digital de Asturias","twitter:description":"Valencia, 20 feb (EFE).- Poco m\u00e1s de ocho a\u00f1os despu\u00e9s de su solemne inauguraci\u00f3n como una de las \u00f3peras m\u00e1s futuristas y ambiciosas del mundo, el Palau de les Arts Reina Sof\u00eda de Valencia abre este domingo su nueva temporada con un estreno de Rossini pero, tambi\u00e9n, sin director musical y con una imagen exterior","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5964399w.jpg"},"aioseo_meta_data":{"post_id":"4664","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-16 15:24:00","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:57:30","updated":"2025-09-16 15:24:00"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/\" title=\"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical\">La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"La \u00f3pera regresa a un Palau de les Arts afeado y sin director musical","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-opera-regresa-a-un-palau-de-les-arts-afeado-y-sin-director-musical\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=4664"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/4665"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=4664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=4664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=4664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}