{"id":4277,"date":"2014-02-15T21:46:54","date_gmt":"2014-02-15T22:46:54","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=4277"},"modified":"2014-02-15T21:46:54","modified_gmt":"2014-02-15T22:46:54","slug":"los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/","title":{"rendered":"Los creadores juegan con los estampados y los patrones setenteros en Madrid"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4278\" alt=\"5948564w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas.<\/p>\n<p>Con la mirada en la \u00e9poca dorada y la \u00abjet set\u00bb que arropaba al escritor Truman Capone, la dise\u00f1adora Teresa Helbig ha presentado una colecci\u00f3n que recrea una sociedad en la que aparec\u00edan fabulosas se\u00f1oras vestidas de ensue\u00f1o.<\/p>\n<p>\u00abEran mujeres estupendas, aut\u00e9nticos cisnes como les llamaba Capote\u00bb, ha contado la creadora, que ha subido a la pasarela de la segunda jornada de la Mercedes-Benz Fashion Week, una de las propuestas m\u00e1s completa y atractiva.<\/p>\n<p>Los patrones de los a\u00f1os 60 y 70 y la atm\u00f3sfera de la m\u00edtica discoteca neoyorquina Studio 54 se han trasladado a las creaciones de Helbig, quien viste a la mujer con maravillosos vestidos con efecto caleidosc\u00f3pico y geom\u00e9trico.<\/p>\n<p>\u00abEs una colecci\u00f3n muy laboriosa, he confeccionado a mano los estampados\u00bb, ha desvelado la creadora que ha echado mano de 35.000 tachuelas de color oro que ofrec\u00edan un apunte roquero.<\/p>\n<p>Sobre la pasarela se ha visto una costura minuciosa y mimada con la lana como protagonista. Vestidos cortos y largos, coquetos \u00abshorts\u00bb, abrigos cortos, pantalones rectos ligeramente acampanados y americanas adornadas con botones dorados.<\/p>\n<p>Ha llamado la atenci\u00f3n un fabuloso mono beige de manga larga y pata ancha, adornado con mangas de piel de mapache y un cintur\u00f3n de cadera dorado, una oda al buen gusto.<\/p>\n<p>En esta ocasi\u00f3n, deja a un lado los colores blanco y negro y se recrea con el coral, el crudo, el c\u00e1mel y el amarillo curry, tonos con los que construye una sinfon\u00eda de vestidos de noches.<\/p>\n<p>M\u00e1s ligera y desestructura que en otras ocasiones ha sido la propuesta de \u00c1ngel Schlesser, que ha puesto en escena un ejercicio de sobriedad y feminidad.<\/p>\n<p>\u00abSon prendas m\u00e1s ligeras de lo habitual, piezas que miran a los a\u00f1os setenta\u00bb, ha contado el creador c\u00e1ntabro que ha presentado dos estampados. Uno con lunares peque\u00f1os y sutiles y el otro con grandes pinceladas.<\/p>\n<p>La propuesta de Schlesser es concreta, va destina a una mujer atemporal, urbana y pr\u00e1ctica que busca el confort en vestidos, blusas, pantalones y jers\u00e9is de punto ingl\u00e9s para su d\u00eda a d\u00eda.<\/p>\n<p>\u00abEl dise\u00f1o que sintetiza el esp\u00edritu de la colecci\u00f3n es un vestido en blanco roto, de talle bajo, manga larga, cuello a la caja y vuelo en el bajo\u00bb, ha apuntado el creador.<\/p>\n<p>Su paleta de colores se ha movido entre el azul marino, el granate y el verde oliva, con un apunte de naranja destinado a la noche, que como no pod\u00eda ser de otra manera se viste de largo.<\/p>\n<p>Schlesser tampoco se ha resistido a incorporar la piel en sus propuestas. Piel vuelta y zorro, trabajado en abrigo y en estola, han acompa\u00f1ado sus propuestas.<\/p>\n<p>Los patrones de la d\u00e9cada de los 60 y la sastrer\u00eda masculina vertebran el trabajo de Roberto Torretta, que ha exhibido prendas con una silueta en forma de \u00abA\u00bb may\u00fascula con la intenci\u00f3n de hacer piezas lo m\u00e1s femeninas posibles.<\/p>\n<p>\u00abEl negro en distintas texturas es el hilo conductor de la colecci\u00f3n\u00bb, ha dicho el argentino que ha coqueteado con tejidos masculinos como el cheviot o la raya diplom\u00e1tica hasta conseguir vestidos y trajes de chaqueta hiperfemenios.<\/p>\n<p>Como es habitual en sus colecciones, Torreta ha utilizado la piel para construir serios vestidos de apariencia sencilla, aunque muy trabajados.<\/p>\n<p>El rojo chile, el rosa palo y el burdeos ba\u00f1an las cl\u00e1sicas prendas con una aire actual, cosmopolita y m\u00e1s moderno. Pocos accesorios, salvo un divertido y abrigado cuello de piel que ha instalado en muchas de sus propuestas. \u00abMi intenci\u00f3n ha sido hacer una pasarela alegre con momentos de optimismo\u00bb, ha se\u00f1alado antes de comenzar su desfile.<\/p>\n<p>Bajo el t\u00edtulo N.E.O, Juana Mart\u00edn ha puesto en escena una colecci\u00f3n con sutiles volantes y l\u00edneas m\u00e1s depuradas sin olvidar sus ra\u00edces andaluzas que en esta ocasi\u00f3n ha plasmado con sutiles ondas.<\/p>\n<p>Esta cordobesa, que reivindica el trabajo artesanal del oficio, ha vestido a la mujer con una serie de prendas en blanco y negro muy sencillas, casi, casi minimalistas.<\/p>\n<p>Por la ma\u00f1ana, unos por exclusividad y otros con la idea de rentabilizar su negocio, los dise\u00f1adores Martin Lamothe, Ailanto y Montesinos han experimentado con los tejidos hasta crear estampados con luz propia y cierta personalidad. Mar\u00eda Barros ha preferido la ausencia de estampados para confeccionar una colecci\u00f3n inspirada en el cine surrealista de Bu\u00f1uel, Cocteau y Germaine Dulac.<\/p>\n<p>Carmen Mart\u00edn y Celia Sierra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la \u00abjet set\u00bb que<\/p>\n","protected":false},"author":1,"featured_media":4278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-4277","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la &quot;jet set&quot; que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la &quot;jet set&quot; que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-15T22:46:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-15T22:46:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la &quot;jet set&quot; que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#article\",\"name\":\"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias\",\"headline\":\"Los creadores juegan con los estampados y los patrones setenteros en Madrid\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5948564w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-02-15T21:46:54+01:00\",\"dateModified\":\"2014-02-15T21:46:54+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#listItem\",\"name\":\"Los creadores juegan con los estampados y los patrones setenteros en Madrid\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#listItem\",\"position\":3,\"name\":\"Los creadores juegan con los estampados y los patrones setenteros en Madrid\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/\",\"name\":\"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias\",\"description\":\"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\\u00f1ana los dise\\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \\u00e9poca dorada y la \\\"jet set\\\" que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5948564w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\\\/#mainImage\"},\"datePublished\":\"2014-02-15T21:46:54+01:00\",\"dateModified\":\"2014-02-15T21:46:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias","description":"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la \"jet set\" que","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#article","name":"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias","headline":"Los creadores juegan con los estampados y los patrones setenteros en Madrid","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg","width":800,"height":533},"datePublished":"2014-02-15T21:46:54+01:00","dateModified":"2014-02-15T21:46:54+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#listItem","name":"Los creadores juegan con los estampados y los patrones setenteros en Madrid"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#listItem","position":3,"name":"Los creadores juegan con los estampados y los patrones setenteros en Madrid","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/","name":"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias","description":"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la \"jet set\" que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/#mainImage"},"datePublished":"2014-02-15T21:46:54+01:00","dateModified":"2014-02-15T21:46:54+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias","og:description":"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la &quot;jet set&quot; que","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-02-15T22:46:54+00:00","article:modified_time":"2014-02-15T22:46:54+00:00","twitter:card":"summary_large_image","twitter:title":"Los creadores juegan con los estampados y los patrones setenteros en Madrid | El Digital de Asturias","twitter:description":"Madrid, 15 feb (EFE).- Mientras hoy que por la ma\u00f1ana los dise\u00f1adores mimaban y creaban sus propios estampados, por la tarde los creadores se centraban en los patrones de los a\u00f1o 60 y 70 para confeccionar prendas funcionales, de apariencia sencilla, pero trabajadas. Con la mirada en la \u00e9poca dorada y la &quot;jet set&quot; que","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5948564w.jpg"},"aioseo_meta_data":{"post_id":"4277","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:58:53","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:53:49","updated":"2026-05-15 11:58:53"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/\" title=\"Los creadores juegan con los estampados y los patrones setenteros en Madrid\">Los creadores juegan con los estampados y los patrones setenteros en Madrid<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Los creadores juegan con los estampados y los patrones setenteros en Madrid","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-creadores-juegan-con-los-estampados-y-los-patrones-setenteros-en-madrid\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=4277"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/4278"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=4277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=4277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=4277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}